{"id":105668,"date":"2013-02-07T16:23:49","date_gmt":"2013-02-07T18:23:49","guid":{"rendered":"http:\/\/revistapesquisa.fapesp.br\/?p=105668"},"modified":"2015-11-24T13:23:52","modified_gmt":"2015-11-24T15:23:52","slug":"econom%c3%ada-de-alcohol","status":"publish","type":"post","link":"https:\/\/revistapesquisa.fapesp.br\/es\/econom%c3%ada-de-alcohol\/","title":{"rendered":"Econom\u00eda de alcohol"},"content":{"rendered":"<div id=\"attachment_105670\" style=\"max-width: 300px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-105670\" title=\"\" src=\"http:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2013\/02\/064-065_Etanol_196-1.jpg\" alt=\"\" width=\"290\" height=\"224\" \/><p class=\"wp-caption-text\"><span class=\"media-credits-inline\">EDUARDO CESAR<\/span>En el CTBE, un equipo de prueba para buj\u00edas de encendido y estudio de la combusti\u00f3n del etanol en motores<span class=\"media-credits\">EDUARDO CESAR<\/span><\/p><\/div>\n<p>Quien conduc\u00eda veh\u00edculos impulsados por alcohol en la d\u00e9cada de 1980, seguramente se acuerda del cebador, un bot\u00f3n o palanca del que deb\u00eda tirarse para inyectar m\u00e1s combustible en el motor al momento del arranque, para que \u00e9ste se calentara y funcionase de manera adecuada. La evoluci\u00f3n tecnol\u00f3gica condujo a la automatizaci\u00f3n del cebador e impuls\u00f3 el sistema <em>flex<\/em>, al comienzo de los a\u00f1os 2000, y desde entonces, la gasolina y el etanol conviven en el mismo motor con cualquier porcentaje de uno u otro. Esta configuraci\u00f3n se transform\u00f3 en un \u00e9xito de ventas, pero todav\u00eda requiere avances, principalmente con respecto al consumo de alcohol, mayor en un 30% al de gasolina, una desventaja que est\u00e1 empezando a ser mejor estudiada en varios trabajos conjuntos entre instituciones de investigaci\u00f3n y las industrias automovil\u00edsticas y de autopartes.<\/p>\n<p>\u201cEl conocimiento sobre la combusti\u00f3n del etanol dentro del motor a\u00fan es escaso\u201d, dice el ingeniero Jayr de Amorim Filho, investigador del Laboratorio Nacional de Ciencia y Tecnolog\u00eda del Bioetanol (CTBE), instalado en la ciudad de Campinas, en S\u00e3o Paulo. \u201cDesde 2009 venimos realizando estudios fundamentales en el plasma que se forma entre la chispa emitida por la buj\u00eda y la combusti\u00f3n del etanol dentro del motor\u201d, comenta. \u201cHemos logrado proponer algunas nuevas t\u00e9cnicas para comprender mejor lo que sucede en el instante de la descarga, cuando la combusti\u00f3n del etanol se propaga en el espacio, provoca reacciones qu\u00edmicas y libera energ\u00eda para impulsar al veh\u00edculo\u201d.<\/p>\n<p>Los investigadores descubrieron y lograron visualizar lo que sucede en el interior del motor por medio de una fibra \u00f3ptica acoplada a la buj\u00eda y que ingresa en las entra\u00f1as del motor. \u201cEs similar a un endoscopio\u201d, comenta Amorim. La fibra capta la luz emitida por la chispa. Despu\u00e9s se la analiza para detectar los gases que se formaron antes, durante y despu\u00e9s de la combusti\u00f3n. \u201cEn nuestro estudio, la buj\u00eda emite chispas cada 10 milisegundos \u2013100 pulsos por segundo\u2013 y la luz nos suministra informaci\u00f3n sobre los gases que se forman con la explosi\u00f3n dentro de esos lapsos. As\u00ed es como pretendemos, am\u00e9n de contribuir a la reducci\u00f3n del consumo de etanol, tambi\u00e9n disminuir la emisi\u00f3n de gases nocivos para el ambiente, que ya es menor en relaci\u00f3n con los motores de gasolina\u201d.<\/p>\n<p>El trabajo del equipo de Amorim se financi\u00f3 mediante un convenio entre la FAPESP y la Fundaci\u00f3n de Apoyo a la Investigaci\u00f3n Cient\u00edfica del Estado de Minas Gerais (Fapemig) en un proyecto vinculado con el Programa FAPESP de Investigaciones en Bioenerg\u00eda (Bioen) y cuenta con investigadores de la Universidad Federal de Juiz de Fora (UFJF) y del Departamento de F\u00edsica del Instituto Tecnol\u00f3gico de Aeron\u00e1utica (ITA), donde el investigador del CTBE comenz\u00f3 los estudios con motores impulsados con alcohol. Desde el comienzo de la investigaci\u00f3n, Bosch, una empresa fabricante de buj\u00edas y sistemas de combusti\u00f3n automovil\u00edstica \u2013pionera en el desarrollo del sistema <em>flex<\/em>\u2013, contribuy\u00f3 con la provisi\u00f3n del material y ahora est\u00e1 estudiando un convenio para el montaje de un laboratorio en el CTBE con el objetivo de estudiar la combusti\u00f3n del etanol. El grupo tambi\u00e9n cuenta con un convenio en el \u00e1rea de combusti\u00f3n con la empresa Mahle, fabricante de piezas de motores con sede en la localidad de Jundia\u00ed (S\u00e3o Paulo).<\/p>\n<p>Una mejor comprensi\u00f3n de los motores que funcionan con etanol tambi\u00e9n requiere un mejor entendimiento del desgaste y el rozamiento de las piezas que lo componen. \u201cAunque han evolucionado, los motores <em>flex<\/em> que utilizan etanol presentan mayor desgaste en sus partes porque el alcohol tiene una menor capacidad de lubricaci\u00f3n que la gasolina\u201d, dice el profesor Amilton Sinatora, docente de la Escuela Polit\u00e9cnica (Poli) de la Universidad de S\u00e3o Paulo (USP). \u201cHace algunos a\u00f1os empezamos a estudiar el problema en trabajos acad\u00e9micos. Lo que nos motiv\u00f3 fueron los informes, en revistas como <em>4 Rodas<\/em>, de problemas de desgaste en v\u00e1lvulas y aros de pist\u00f3n de los motores, por ejemplo\u201d, comenta Sinatora. A partir de ah\u00ed, \u00e9l comenz\u00f3 a diagramar un proyecto conjunto con el centro tecnol\u00f3gico de Mahle.<\/p>\n<p><strong>El <em>spray<\/em> de la explosi\u00f3n<\/strong><br \/>\nEl proyecto, en gestaci\u00f3n desde 2009, fue aprobado por la FAPESP en 2011 con otros socios: Fiat, Volkswagen, Renault y Petrobras, que contribuir\u00e1 en los estudios tendientes a obtener nuevos aceites lubricantes para combatir en forma m\u00e1s espec\u00edfica el efecto del uso simult\u00e1neo de lubricantes distintos en los motores <em>flex<\/em>. \u201cLa tendencia de los \u00faltimos a\u00f1os es la fabricaci\u00f3n de motores m\u00e1s livianos, comprimidos, potentes y que emiten menos contaminantes. Ahora proyectamos motores que tengan menor desgaste a lo largo del tiempo con el etanol\u201d. La importancia de estos estudios reside tambi\u00e9n en el hecho de que no existen todav\u00eda estudios muy extensos de motores <em>flex<\/em> con etanol fuera de Brasil. \u201cLos estudios en el exterior comenzaron hace tres a\u00f1os\u201d, informa. \u00c9l coordina el proyecto con la colaboraci\u00f3n de equipos en las empresas y en otras dos universidades, la Universidad Federal del ABC, junto con el profesor Humberto Yoshimura, y en la Unicamp, con el profesor Francisco Marques.<\/p>\n<p>La medici\u00f3n del tama\u00f1o de las gotas del <em>spray<\/em> en la combusti\u00f3n de etanol mediante t\u00e9cnicas que utilizan l\u00e1ser forma parte del inicio de otro proyecto relacionado con los motores de alcohol cuyo objetivo es analizar nuevas posibilidades de combusti\u00f3n del biocombustible. \u201cSe trata de una investigaci\u00f3n b\u00e1sica para el estudio de la combusti\u00f3n del etanol\u201d, dice el profesor Guenther Carlos Krieger Filho, de la Poli-USP. El proyecto que \u00e9l coordina forma parte del Bioen y se apoya en un convenio de cooperaci\u00f3n para el desarrollo tecnol\u00f3gico entre la FAPESP, la empresa Vale S.A., la Fundaci\u00f3n de Apoyo a la Investigaci\u00f3n Cient\u00edfica del Estado de Par\u00e1 (Fapespa) y la Fapemig. El proyecto concluir\u00e1 en 2015.<\/p>\n<p>\u201cEstos estudios resultan muy importantes porque el motor <em>flex<\/em> se encuentra a medio camino entre el motor de gasolina y el impulsado con alcohol en t\u00e9rminos de regulaci\u00f3n\u201d, apunta el ingeniero Waldemar Christofoletti, del comit\u00e9 de veh\u00edculos livianos de SAE Brasil, una entidad que agrupa a los ingenieros automovil\u00edsticos y aeroespaciales. En su opini\u00f3n, el sistema <em>flex<\/em> es muy bueno, aunque est\u00e1 lejos de ser un motor de alcohol eficiente. \u201cCreo que la relaci\u00f3n puede mejorar del 30% de diferencia en el consumo hasta un 15% a lo sumo; pero, para ello, se necesita incluir tambi\u00e9n <em>software <\/em>y <em>hardware<\/em>, o los componentes f\u00edsicos y electr\u00f3nicos que conforman el sistema de inyecci\u00f3n de combustible\u201d, dice Christofoletti.<\/p>\n<p>Otro factor que aliment\u00f3 el inter\u00e9s de las empresas en los avances para los motores de alcohol es el programa del gobierno federal presentado en abril de este a\u00f1o, denominado Programa de Incentivo a la Innovaci\u00f3n Tecnol\u00f3gica y Consolidaci\u00f3n de la Cadena Productiva de Veh\u00edculos Automotores (Inovar-Auto). El mismo conceder\u00e1 descuentos en el Impuesto sobre Productos Industrializados (IPI), a partir de enero de 2013, a los fabricantes de veh\u00edculos y autopartes que demuestren inversiones en desarrollo tecnol\u00f3gico y eficiencia energ\u00e9tica.<\/p>\n<p><strong>Los Proyectos<br \/>\n1. <\/strong>Etanol \u2013 Utilizaci\u00f3n del etanol como combustible: ignici\u00f3n por plasma en motores vehiculares\u00a0(<a href=\"http:\/\/www.bv.fapesp.br\/pt\/auxilios\/29273\/etanol-utilizacao-do-etanol-como-combustivel-ignicao-a-plasma-de-motores-veiculares\/\" target=\"_blank\">n\u00ba 2008\/58195-3<\/a>);\u00a0<strong>Modalidad<\/strong>\u00a0Programa FAPESP de Investigaci\u00f3n en Bioenerg\u00eda (Bioen);\u00a0<strong>Coordinador<\/strong>\u00a0Jayr de Amorim Filho \u2013 CTBE;\u00a0<strong>Inversi\u00f3n\u00a0<\/strong>R$ 174.962,34 y US$ 149.501,85 (FAPESP)<br \/>\n<strong>2.<\/strong> Desaf\u00edos tribol\u00f3gicos en los motores <em>flex-fuel<\/em>\u00a0(<a href=\"http:\/\/www.bv.fapesp.br\/pt\/auxilios\/35174\/desafios-tribologicos-em-motores-flex-fuel\/\" target=\"_blank\">n\u00ba 2009\/54891-8<\/a>); <strong>Modalidad\u00a0<\/strong>Programa de Apoyo a la Investigaci\u00f3n Cooperativa para Innovaci\u00f3n Tecnol\u00f3gica (Pite);\u00a0<strong>Coordinador\u00a0<\/strong>Amilton Sinatora \u2013 USP;\u00a0<strong>Inversi\u00f3n<\/strong>\u00a0R$ 975.435,65 y US$ 690.091,30 (FAPESP)<br \/>\n<strong>3. <\/strong>Estudio experimental y computarizado de <em>spray<\/em> turbulentos de etanol para aplicaciones en motores de combusti\u00f3n interna\u00a0(<a href=\"http:\/\/www.bv.fapesp.br\/pt\/auxilios\/29765\/estudo-experimental-e-computacional-de-sprays-turbulentos-de-etanol-para-aplicacoes-em-motores-de-co\/\" target=\"_blank\">n\u00ba 2010\/51310-1<\/a>); <strong>Modalidad<\/strong>\u00a0Programa FAPESP de Investigaci\u00f3n en Bioenerg\u00eda (Bioen); <strong>Coordinador<\/strong>\u00a0Guenther Carlos Krieger Filho \u2013 USP;\u00a0<strong>Inversi\u00f3n\u00a0<\/strong>R$ 123.551,15 y US$ 293.241,32 (FAPESP); R$ 285.274,15 y US$ 293.241,32 (Vale)<\/p>\n","protected":false},"excerpt":{"rendered":"Los motores flex reducir\u00e1n el gasto de etanol","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[1587,192],"tags":[297],"coauthors":[97],"class_list":["post-105668","post","type-post","status-publish","format-standard","hentry","category-investigacion-en-colaboracion-para-la-innovacion-tecnologica-en","category-tecnologia-es","tag-ingenieria"],"acf":[],"_links":{"self":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/posts\/105668","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/comments?post=105668"}],"version-history":[{"count":0,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/posts\/105668\/revisions"}],"wp:attachment":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/media?parent=105668"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/categories?post=105668"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/tags?post=105668"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/coauthors?post=105668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}