{"id":11806,"date":"2012-05-25T18:24:54","date_gmt":"2012-05-25T21:24:54","guid":{"rendered":"http:\/\/revistapesquisa.fapesp.br\/?p=11806"},"modified":"2013-01-24T16:25:28","modified_gmt":"2013-01-24T18:25:28","slug":"lo-que-los-j%c3%b3venes-deben-a-velho","status":"publish","type":"post","link":"https:\/\/revistapesquisa.fapesp.br\/es\/lo-que-los-j%c3%b3venes-deben-a-velho\/","title":{"rendered":"Lo que los j\u00f3venes deben a Velho"},"content":{"rendered":"<div id=\"attachment_11808\" style=\"max-width: 211px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-11808 \" title=\"059_Obituario_195-2\" src=\"http:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2012\/06\/059_Obituario_195-21-201x300.jpg\" alt=\"\" width=\"201\" height=\"300\" \/><span class=\"media-credits-inline\">CARLOS IVAN \/ AG\u00caNCIA O GLOBO<\/span><p class=\"wp-caption-text\">Gilberto Velho<span class=\"media-credits\">CARLOS IVAN \/ AG\u00caNCIA O GLOBO<\/span><\/p><\/div>\n<p>Actualmente, tem\u00e1ticas tales como la droga y el sexo son usuales en tesis e investigaciones acad\u00e9micas. Pero fue el trabajo pionero del antrop\u00f3logo Gilberto Velho (1945-2012) lo que permiti\u00f3 a los j\u00f3venes estudiar la sociedad sin restricciones. Se necesitaron 113 art\u00edculos en peri\u00f3dicos y 28 libros, entre los cuales podemos citar <em>Desvio e diverg\u00eancia<\/em> (1985), <em>Individualismo e cultura<\/em> (1987), <em>A utopia urbana<\/em> (1989), <em>Nobres e anjos<\/em> (1998), <em>Juventude contempor\u00e2nea: culturas, gostos e carreiras<\/em> (2010). No fue un camino sencillo. Siendo un joven profesor, le escucho decir a un intelectual: \u201c\u00bfPara qu\u00e9 estudiar prostitutas y homosexuales? Un antrop\u00f3logo debe estudiar a los abor\u00edgenes\u201d. Gilberto Velho falleci\u00f3 el 16 de abril en R\u00edo de Janeiro, a los 66 a\u00f1os.<\/p>\n<p>\u201cYo ten\u00eda el deseo de ensanchar horizontes, oxigenar. Mi innovaci\u00f3n consisti\u00f3 en estudiar nuestra propia sociedad\u201d, dec\u00eda Velho. Hijo de un militar intelectual, se enamor\u00f3 de la antropolog\u00eda en el colegio Aplica\u00e7\u00e3o y se interes\u00f3 por las clases medias brasile\u00f1as, ignorada en las investigaciones. Se gradu\u00f3 en ciencias sociales en la Universidad Federal de R\u00edo de Janeiro (UFRJ) en 1968, y se instal\u00f3 en Copacabana, en un apartamento de dos ambientes. \u201cFue algo al azar, pero era lo que yo necesitaba: logr\u00e9 llevar adelante un estudio de caso en mi edificio, con 500 personas. La utop\u00eda urbana, mi maestr\u00eda, realizada en 1970, se bas\u00f3 en esa situaci\u00f3n.<\/p>\n<p>La maestr\u00eda se hizo efectiva en la Universidad de Texas, en Estados Unidos. All\u00e1 conoci\u00f3 al antrop\u00f3logo estadounidense Anthony Leeds, un estudioso de la antropolog\u00eda urbana, entonces desconocido en Brasil. Gilberto fue por ello pionero al traer ese campo de la antropolog\u00eda al pa\u00eds, mediante el an\u00e1lisis de la sociedad urbana en r\u00e1pida modernizaci\u00f3n. \u201cLo que me interesaba, por ese entonces, era la difusi\u00f3n de las drogas en los estratos medios superiores, la \u2018aristocracia con estatus medio\u2019 y la investigaci\u00f3n result\u00f3, en 1975, en el doctorado <em>Nobles y \u00e1ngeles<\/em>, dirigido por Ruth Cardoso en la Universidad de S\u00e3o Paulo, y que m\u00e1s tarde se edit\u00f3 como libro\u201d.<\/p>\n<p>Gilberto Velho enfoc\u00f3 su inter\u00e9s en el \u201ctr\u00e1nsito\u201d social entre los brasile\u00f1os. \u201cEstudi\u00e9 las relaciones entre los niveles culturales, entre la elite y los sectores populares, entre los estratos medios y las elites, en definitiva, la cuesti\u00f3n de la mediaci\u00f3n, la transici\u00f3n entre diversos grupos y dominios. Se trata de un fen\u00f3meno que existe en toda sociedad, aunque en la gran metr\u00f3polis es una cuesti\u00f3n trascendental, que es importante estudiar, especialmente en Brasil\u201d, afirm\u00f3 en una de sus entrevistas. Viviendo en R\u00edo, tambi\u00e9n estudi\u00f3 los efectos de la inseguridad retrat\u00e1ndolos en el libro <em>Mudan\u00e7a, crise e viol\u00eancia<\/em>.<\/p>\n<p>El investigador incentiv\u00f3 a toda una generaci\u00f3n de antrop\u00f3logos a pensar en el Brasil alternativo de los marginales, del sexo, de las religiones populares y de la transgresi\u00f3n. Su di\u00e1logo con Georg Simmel innov\u00f3 el pensamiento al respecto del individualismo. Promovi\u00f3 la institucionalizaci\u00f3n de las ciencias sociales en Brasil y la consolidaci\u00f3n del programa de posgrado del Museo Nacional. Era un pensador muy activo, que cultivaba la reflexi\u00f3n cr\u00edtica, a la que ve\u00eda amenazada por el conformismo. \u201cEl pensamiento cr\u00edtico y amplio, \u00faltimamente es visto como algo pernicioso que debe ser detenido. Pero la reflexi\u00f3n cr\u00edtica no termina nunca\u201d, asegur\u00f3 en una de sus \u00faltimas entrevistas. Su trabajo constituye la prueba de esa lucha.<\/p>\n","protected":false},"excerpt":{"rendered":"El investigador carioca fue pionero de la antropolog\u00eda urbana en el pa\u00eds","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[181],"tags":[270],"coauthors":[93],"class_list":["post-11806","post","type-post","status-publish","format-standard","hentry","category-ciencia-es","tag-antropologia-es"],"acf":[],"_links":{"self":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/posts\/11806","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/comments?post=11806"}],"version-history":[{"count":0,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/posts\/11806\/revisions"}],"wp:attachment":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/media?parent=11806"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/categories?post=11806"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/tags?post=11806"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/coauthors?post=11806"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}