{"id":189037,"date":"2015-02-18T18:12:17","date_gmt":"2015-02-18T20:12:17","guid":{"rendered":"http:\/\/revistapesquisa.fapesp.br\/?p=189037"},"modified":"2015-06-30T18:16:27","modified_gmt":"2015-06-30T21:16:27","slug":"un-camino-innovador","status":"publish","type":"post","link":"https:\/\/revistapesquisa.fapesp.br\/es\/un-camino-innovador\/","title":{"rendered":"Un camino innovador"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-189038\" src=\"http:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2015\/06\/carreiras_salem_com_livros_1.jpg\" alt=\"carreiras_salem_com_livros_1\" width=\"290\" height=\"218\" srcset=\"https:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2015\/06\/carreiras_salem_com_livros_1.jpg 290w, https:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2015\/06\/carreiras_salem_com_livros_1-120x90.jpg 120w, https:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2015\/06\/carreiras_salem_com_livros_1-250x188.jpg 250w\" sizes=\"auto, (max-width: 290px) 100vw, 290px\" \/><span class=\"media-credits-inline\">Archivo personal<\/span>Alumnos, ex alumnos y docentes del Instituto de Matem\u00e1tica y Estad\u00edstica de la Universidad de S\u00e3o Paulo (IME-USP) cuentan desde diciembre del a\u00f1o pasado con un instrumento de apoyo para transformar ideas y proyectos innovadores en un emprendimiento comercial. El IMEmpreende se cre\u00f3 como un grupo de inter\u00e9s en emprendedorismo, para conectar a personas que comparten la misma cultura acad\u00e9mica y ayudarlas en sus proyectos. \u201cExiste en la universidad mucha investigaci\u00f3n aplicable, de gran calidad, que no encuentra un camino para transformarse en producto\u201d, dice Paulo Salem, ex alumno de la carrera de ciencia de la computaci\u00f3n del IME y director ejecutivo del IMEmpreende. \u201cBuena parte del conocimiento que podr\u00eda generar valor econ\u00f3mico, como los <em>software<\/em> creados con el uso de sofisticadas teor\u00edas de inteligencia artificial, se pierde pues no existe el incentivo suficiente como para que se convierta en producto\u201d. Salem dio rienda suelta a su costado emprendedor a los 17 a\u00f1os, cuando cre\u00f3 SmartNote, en respuesta a un desaf\u00edo lanzado entonces por la revista <em>Inform\u00e1tica Exame<\/em>, actualmente <em>Info Exame<\/em>, de crear la mejor aplicaci\u00f3n para <em>post-its<\/em> (los peque\u00f1os adhesivos usados para recordar tareas y compromisos).<\/p>\n<p>El objetivo del IMEmpreende es fomentar la transformaci\u00f3n del conocimiento en tecnolog\u00eda y productos mediante la promoci\u00f3n de encuentros e intercambios entre sus miembros, como as\u00ed tambi\u00e9n de \u00e9stos con inversionistas, por ejemplo. Por ahora la comunicaci\u00f3n entre los miembros transcurre fundamentalmente en una <a href=\"https:\/\/groups.google.com\/forum\/#!forum\/imempreende\" target=\"_blank\">lista de correos electr\u00f3nicos<\/a>, en la cual se han inscrito 51 personas. De ellas, 35 participaron en la primera reuni\u00f3n del grupo, a finales del a\u00f1o pasado. \u201cEn el IME existe la Junior Empresa, pero tradicionalmente no se enfoca en esa idea de emprendedorismo, de fomentar <em>startup<\/em>\u201d, dice Salem, quien luego de graduarse, en 2005, ingres\u00f3 en el programa de doctorado directo de la USP en ciencia de la computaci\u00f3n, con doble titulaci\u00f3n tambi\u00e9n por la Universit\u00e9 Paris-Sud (Francia). \u201cCuando termin\u00e9 mi doctorado, en 2012, resolv\u00ed dedicarme al emprendedorismo\u201d, comenta Salem. Fue cuando tuvo la idea de crear el <a href=\"http:\/\/liberalis.biz\/\" target=\"_blank\">portal Liberalis<\/a>, destinado a profesionales liberales y aut\u00f3nomos: m\u00e9dicos, psic\u00f3logos, abogados, ebanistas y arquitectos, por ejemplo, que pretenden divulgar sus curr\u00edculos o carteras de trabajos. \u201cEl <em>software <\/em>es totalmente automatizado. Si el profesional pone poca informaci\u00f3n, por ejemplo, se generar\u00e1 una p\u00e1gina adecuada a los datos disponibles.\u201d<\/p>\n<p>El sitio web sali\u00f3 al aire en 2012 con opciones b\u00e1sicas, y con el tiempo se fueron haciendo algunas modificaciones. \u201cAl principio s\u00f3lo pod\u00edan subir el curr\u00edculo los que pagasen, pero a mitad de camino cambi\u00e9 el modelo de negocios\u201d, comenta Salem. El sistema tiene registrados actualmente a alrededor de 2.500 profesionales, pero los que pagan a\u00fan son muy pocos.<\/p>\n","protected":false},"excerpt":{"rendered":"El IMEmpreende, del IME-USP, aspira a transformar ideas en productos","protected":false},"author":475,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[1217],"tags":[312],"coauthors":[785],"class_list":["post-189037","post","type-post","status-publish","format-standard","hentry","category-carreiras-es","tag-innovacion"],"acf":[],"_links":{"self":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/posts\/189037","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/users\/475"}],"replies":[{"embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/comments?post=189037"}],"version-history":[{"count":0,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/posts\/189037\/revisions"}],"wp:attachment":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/media?parent=189037"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/categories?post=189037"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/tags?post=189037"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/coauthors?post=189037"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}