{"id":192711,"date":"2015-05-15T13:27:03","date_gmt":"2015-05-15T16:27:03","guid":{"rendered":"http:\/\/revistapesquisa.fapesp.br\/?p=192711"},"modified":"2015-08-04T13:32:52","modified_gmt":"2015-08-04T16:32:52","slug":"biodiesel-de-moringa","status":"publish","type":"post","link":"https:\/\/revistapesquisa.fapesp.br\/es\/biodiesel-de-moringa\/","title":{"rendered":"Biodi\u00e9sel de moringa"},"content":{"rendered":"<div id=\"attachment_192713\" style=\"max-width: 300px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-192713\" src=\"http:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2015\/08\/Tecno_Sonjna_Moringa_oleifera_flowers_at_Kolkata_W_IMG_2124.jpg\" alt=\"El extracto de las hojas de la Moringa oleifera sirve como aditivo antioxidante\" width=\"290\" height=\"190\" srcset=\"https:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2015\/08\/Tecno_Sonjna_Moringa_oleifera_flowers_at_Kolkata_W_IMG_2124.jpg 290w, https:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2015\/08\/Tecno_Sonjna_Moringa_oleifera_flowers_at_Kolkata_W_IMG_2124-120x79.jpg 120w, https:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2015\/08\/Tecno_Sonjna_Moringa_oleifera_flowers_at_Kolkata_W_IMG_2124-250x164.jpg 250w\" sizes=\"auto, (max-width: 290px) 100vw, 290px\" \/><p class=\"wp-caption-text\"><span class=\"media-credits-inline\">J. M. GARG \/ WIKICOMMONS<\/span>El extracto de las hojas de la <em>Moringa oleifera<\/em> sirve como aditivo antioxidante<span class=\"media-credits\">J. M. GARG \/ WIKICOMMONS<\/span><\/p><\/div>\n<p>El aceite de las semillas de la <em>Moringa oleifera<\/em>, un \u00e1rbol originario de la India y com\u00fan en el nordeste de Brasil, podr\u00eda utilizarse para la producci\u00f3n de biodi\u00e9sel, y el extracto de sus hojas, para la producci\u00f3n de aditivos antioxidantes que retardan la degradaci\u00f3n qu\u00edmica del combustible. Tal es la conclusi\u00f3n a la que arribaron investigadores de la Universidad Federal de Uberl\u00e2ndia (UFU), en Minas Gerais. En un estudio publicado en la edici\u00f3n del 15 de abril de la revista <em>Fuel<\/em>, los cient\u00edficos elaboraron biodi\u00e9sel de moringa con propiedades fisicoqu\u00edmicas dentro de las especificaciones de los organismos regulatorios. El biodi\u00e9sel de moringa present\u00f3 una estabilidad oxidativa superior a la de la mayor\u00eda de los combustibles que se producen en el pa\u00eds. La estabilidad oxidativa alude al per\u00edodo en que el combustible logra mantener ciertas propiedades antes de degradarse. Esa reacci\u00f3n qu\u00edmica, denominada oxidaci\u00f3n, conduce a la producci\u00f3n de compuestos que pueden corroer las piezas del motor y obstruir el sistema de inyecci\u00f3n. As\u00ed, cuanto m\u00e1s demora un combustible en oxidarse, mejores son su calidad y su eficiencia. En el estudio, los investigadores agregaron un extracto de la hoja del \u00e1rbol a las muestras de biodi\u00e9sel elaborado con soja, ma\u00edz, colza y girasol. Con ello se elev\u00f3 la estabilidad oxidativa de esos combustibles. \u201cNuestros resultados evidencian el potencial antioxidante del extracto de las hojas de la <em>M. oleifera<\/em> como aditivo para el biodi\u00e9sel\u201d, dice el qu\u00edmico Rodrigo Mu\u00f1oz, principal autor del estudio.<\/p>\n","protected":false},"excerpt":{"rendered":"El aceite de las semillas puede utilizarse para producir biodi\u00e9sel","protected":false},"author":475,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[191],"tags":[276,282],"coauthors":[785],"class_list":["post-192711","post","type-post","status-publish","format-standard","hentry","category-tecnociencia-es-es","tag-bioenergia-es","tag-botanica-es"],"acf":[],"_links":{"self":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/posts\/192711","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/users\/475"}],"replies":[{"embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/comments?post=192711"}],"version-history":[{"count":0,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/posts\/192711\/revisions"}],"wp:attachment":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/media?parent=192711"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/categories?post=192711"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/tags?post=192711"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/coauthors?post=192711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}