{"id":203778,"date":"2015-12-02T15:00:39","date_gmt":"2015-12-02T17:00:39","guid":{"rendered":"http:\/\/revistapesquisa.fapesp.br\/?p=203778"},"modified":"2015-11-26T14:48:44","modified_gmt":"2015-11-26T16:48:44","slug":"la-danza-de-la-lluvia-2","status":"publish","type":"post","link":"https:\/\/revistapesquisa.fapesp.br\/es\/la-danza-de-la-lluvia-2\/","title":{"rendered":"La danza de la lluvia"},"content":{"rendered":"<div id=\"attachment_203784\" style=\"max-width: 300px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-203784\" src=\"http:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2015\/11\/006-013_Capa_int_20152-300x172.jpg\" alt=\"Alteraciones en el volumen y en la periodicidad de las precipitaciones y un mal uso de los acu\u00edferos se encuentran entre los factores que secan las ca\u00f1er\u00edas en regiones de Brasil\" width=\"290\" height=\"166\" \/><p class=\"wp-caption-text\"><span class=\"media-credits-inline\">L\u00c9O RAMOS<\/span>Alteraciones en el volumen y en la periodicidad de las precipitaciones y un mal uso de los acu\u00edferos se encuentran entre los factores que secan las ca\u00f1er\u00edas en regiones de Brasil<span class=\"media-credits\">L\u00c9O RAMOS<\/span><\/p><\/div>\n<p><em>Publicado en diciembre de 2014<\/em><\/p>\n<p>La Amazonia no es solamente la mayor selva tropical que queda en el mundo. Esa vasta extensi\u00f3n de verde entrecortado por r\u00edos serpenteantes de diversos tama\u00f1os y colores tampoco se ci\u00f1e a ser el h\u00e1bitat de una incre\u00edble diversidad de flora y fauna. La selva amaz\u00f3nica tambi\u00e9n es un motor capaz de alterar el sentido de los vientos y una bomba que extrae agua del aire sobre el oc\u00e9ano Atl\u00e1ntico y del suelo, haci\u00e9ndola circular por Am\u00e9rica del Sur, provocando en lejanas regiones las lluvias que hoy anhelan los paulistas. Pero el funcionamiento de esa bomba depende de la conservaci\u00f3n de la selva, cuya porci\u00f3n brasile\u00f1a, hasta 2013, perdi\u00f3 763 mil kil\u00f3metros cuadrados (km<sup>2<\/sup>) de su superficie original, el equivalente a tres estados de S\u00e3o Paulo. El investigador Antonio Donato Nobre, del Instituto Nacional de Investigaciones Espaciales (Inpe, por sus siglas en portugu\u00e9s) no apunta hacia ning\u00fan culpable. Lo que importa, en su opini\u00f3n, es revertir ese proceso, para lo cual no s\u00f3lo hay que acabar con el desmonte, sino tambi\u00e9n recuperar la selva. En el informe <a href=\"http:\/\/www.ccst.inpe.br\/wp-content\/uploads\/2014\/10\/Futuro-Climatico-da-Amazonia.pdf\" target=\"_blank\"><em>O futuro clim\u00e1tico da Amaz\u00f4nia<\/em><\/a>, divulgado a finales del mes de octubre, Nobre deja en claro que el \u00fanico motivo por el cual no se tomaron medidas inmediatas para reducir el desmonte es el desconocimiento de lo que sabe la ciencia. Para \u00e9l, el camino consiste en la concientizaci\u00f3n de la poblaci\u00f3n. \u201cAhora es un buen momento porque los grifos se est\u00e1n secando\u201d, afirma.<\/p>\n<p>En el informe, elaborado a partir del an\u00e1lisis de alrededor de 200 trabajos cient\u00edficos, el investigador revela que cada d\u00eda, la selva de la cuenca amaz\u00f3nica transpira 20 mil millones de toneladas de agua (20 billones de litros). Es una cifra mayor que las 17 mil millones de toneladas que vierte diariamente el r\u00edo Amazonas en el Atl\u00e1ntico. Ese r\u00edo vertical es el que alimenta a las nubes y ayuda a alterar la ruta de los vientos. Nobre explica que los mapas de los vientos sobre el Atl\u00e1ntico muestran que, en el hemisferio sur y a bajas alturas, el aire se desplaza hacia el noroeste en direcci\u00f3n hacia el ecuador. \u201cEn la Amazonia, la selva desv\u00eda ese orden\u201d, dice. \u201cEn determinada parte del a\u00f1o, los vientos alisios cargados de humedad llegan desde el hemisferio norte y convergen hacia el oeste\/ sudoeste, intern\u00e1ndose en Am\u00e9rica del Sur\u201d.<\/p>\n<p>Esa circulaci\u00f3n viola un paradigma meteorol\u00f3gico que sostiene que los vientos deber\u00edan soplar desde las regiones con superficies m\u00e1s fr\u00edas hacia aqu\u00e9llas con superficies m\u00e1s c\u00e1lidas. \u201cEn la Amazonia, durante todo el a\u00f1o circulan desde zonas c\u00e1lidas \u2013el Atl\u00e1ntico ecuatorial\u2013 hacia zonas fr\u00edas, en este caso, la selva\u201d, explica. Un trabajo conjunto con los rusos Anastasia Makarieva y V\u00edctor Gorshkov, del Instituto de F\u00edsica Nuclear de Petersburgo, ha ayudado a explicar, desde el punto de vista f\u00edsico, los fen\u00f3menos meteorol\u00f3gicos en la Amazonia. En un art\u00edculo publicado en febrero de 2014 en <em>Journal of Hydrometeorology<\/em>, los cient\u00edficos afirman, basados en an\u00e1lisis te\u00f3ricos confirmados por observaciones emp\u00edricas, que el desmonte altera los est\u00e1ndares de presi\u00f3n y puede ocasionar una disminuci\u00f3n de los vientos cargados de humedad provenientes del oc\u00e9ano hacia el continente. El grupo analiz\u00f3 los datos registrados en 28 estaciones meteorol\u00f3gicas de dos \u00e1reas de Brasil y observ\u00f3 que los vientos que provenientes de la selva amaz\u00f3nica cargan m\u00e1s humedad y se asocian con mayores \u00edndices de lluvias que los vientos originados en \u00e1reas sin selva que llegan a una misma estaci\u00f3n.<\/p>\n<p>Eso ocurre, a juicio de los investigadores, a causa de la bomba bi\u00f3tica de humedad, una teor\u00eda propuesta por el d\u00fao ruso en 2007 para explicar la din\u00e1mica de los vientos impulsados por las selvas. Dicha concepci\u00f3n completa la descripci\u00f3n realizada por el climat\u00f3logo Jos\u00e9 Antonio Marengo, por ese entonces investigador del Inpe, sobre c\u00f3mo exporta lluvias la Amazonia hacia regiones m\u00e1s meridionales de Sudam\u00e9rica. La teor\u00eda de la bomba bi\u00f3tica aplica una f\u00edsica heterodoxa a la meteorolog\u00eda y postula que la condensaci\u00f3n del agua, favorecida por la transpiraci\u00f3n de la selva, reduce la presi\u00f3n atmosf\u00e9rica que atrae a las corrientes de aire cargadas de agua desde el mar hacia la tierra.<\/p>\n<p><a href=\"http:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2015\/11\/006-013_Capa_La-danza-de-la-lluvia_Esp_2015.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-203787\" src=\"http:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2015\/11\/006-013_Capa_La-danza-de-la-lluvia_Esp_2015-789x1024.jpg\" alt=\"006-013_Capa_La danza de la lluvia_Esp_2015\" width=\"290\" height=\"376\" \/><\/a>Los principios de la influencia de la condensaci\u00f3n sobre los vientos fueron presentados en un art\u00edculo publicado en 2013 por Makarieva y Gorshkov, en un trabajo conjunto con Nobre y otros colaboradores, en la revista <em>Atmospheric Chemistry and Physics<\/em>, una de las m\u00e1s importantes del sector. Vali\u00e9ndose de una serie de ecuaciones, los cient\u00edficos revelan que el vapor de agua arrojado a la atm\u00f3sfera por la transpiraci\u00f3n de la selva genera, al condensarse, un flujo capaz de impulsar a los vientos a grandes distancias. De acuerdo con Nobre, la nueva f\u00edsica de la condensaci\u00f3n que postularon gener\u00f3, incluso durante la revisi\u00f3n del art\u00edculo, una controversia con los meteor\u00f3logos, que debatieron furiosamente el tema en los <em>blogs<\/em> cient\u00edficos con la intenci\u00f3n de refutar la principal ecuaci\u00f3n del trabajo. No lo consiguieron y el trabajo fue publicado. El investigador del Inpe explica esa pol\u00e9mica. \u201cSe trata de una f\u00edsica que le adjudica a la condensaci\u00f3n, un fen\u00f3meno b\u00e1sico y central en el funcionamiento atmosf\u00e9rico, un efecto opuesto al que ostentaba\u201d, dice. \u201cHabr\u00e1 que reescribir los manuales del \u00e1rea\u201d.<\/p>\n<p>Para brindar una dimensi\u00f3n de la dificultad del di\u00e1logo entre f\u00edsicos te\u00f3ricos y meteor\u00f3logos, Nobre recuerda que la f\u00edsica desarrolla una comprensi\u00f3n de los fen\u00f3menos atmosf\u00e9ricos a partir de las leyes fundamentales de la naturaleza, mientras que la meteorolog\u00eda lo hace, en gran medida, bas\u00e1ndose en la observaci\u00f3n de patrones clim\u00e1ticos del pasado, cuya estad\u00edstica alimenta modelos matem\u00e1ticos. Tales modelos representan adecuadamente las fluctuaciones clim\u00e1ticas observadas, pero presentan fallas cuando surgen alteraciones significativas en el modelo.<\/p>\n<p>Eso es lo que sucede ahora, cuando un nuevo contexto \u2013causado por el desmonte, alteraciones globales del clima u otros factores\u2013 genera fen\u00f3menos clim\u00e1ticos inesperados para ciertas regiones, tales como lluvias m\u00e1s torrenciales y sequ\u00edas m\u00e1s prolongadas. La teor\u00eda f\u00edsica acierta donde las extrapolaciones del pasado se equivocan, por eso es necesaria, a su juicio, la construcci\u00f3n de nuevos modelos climatol\u00f3gicos que reubiquen a la f\u00edsica en el centro de los desvelos de la meteorolog\u00eda.<\/p>\n<p>El momento actual es crucial, pues el clima amaz\u00f3nico est\u00e1 modific\u00e1ndose. Sequ\u00edas importantes en esa regi\u00f3n signaron los a\u00f1os 2005 y 2010. \u201cAntes la Amazonia ten\u00eda una estaci\u00f3n h\u00fameda y otra m\u00e1s h\u00fameda, ahora hay una estaci\u00f3n seca\u201d, dice Nobre. Los da\u00f1os causados por esas sequ\u00edas en la selva no la aniquilaron porque \u00e9sta logra regenerarse, pero la progresiva acumulaci\u00f3n de da\u00f1os erosiona dicha capacidad. Un efecto importante que ya se percibe, previsto hace 20 a\u00f1os por los modelos clim\u00e1ticos, es una prolongaci\u00f3n de la estaci\u00f3n seca, que ha perjudicado la producci\u00f3n agr\u00edcola en ciertos sectores del estado de Mato Grosso. Lo que preocupa enormemente es que se llegue a un punto sin retorno, en el cual la selva ya no logre producir lluvia suficiente ni siquiera para abastecerse a s\u00ed misma. Los pron\u00f3sticos que tienen en cuenta el clima y la vegetaci\u00f3n indican que ese punto se alcanzar\u00e1 cuando se pierda el 40% del \u00e1rea original de la selva, una cifra sobre la cual no existe un consenso. Seg\u00fan el informe de Nobre, el 20% de la selva ya ha sido talada y otro 20% fue alterado a punto tal de haber perdido parte de sus propiedades.<\/p>\n<div id=\"attachment_203780\" style=\"max-width: 300px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-203780\" src=\"http:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2015\/11\/Aguas_image0021-300x225.jpg\" alt=\"R\u00edos voladores: las corrientes de vapor de agua que se forman sobre la selva amaz\u00f3nica exportan lluvias hacia la regi\u00f3n sur de Brasil\" width=\"290\" height=\"218\" \/><p class=\"wp-caption-text\"><span class=\"media-credits-inline\">Gerard moss \/ PROYECTO R\u00cdOS VOLADORES<\/span>R\u00edos voladores: las corrientes de vapor de agua que se forman sobre la selva amaz\u00f3nica exportan lluvias hacia la regi\u00f3n sur de Brasil<span class=\"media-credits\">Gerard moss \/ PROYECTO R\u00cdOS VOLADORES<\/span><\/p><\/div>\n<p>Si la teor\u00eda de la bomba bi\u00f3tica estuviera en lo cierto, los efectos causados por ese punto sin retorno ser\u00edan m\u00e1s graves que la sabanizaci\u00f3n propuesta por el climat\u00f3logo Carlos Nobre, hermano mayor de Antonio. \u201cSi la selva perdiera la capacidad de atraer la humedad del oc\u00e9ano, las lluvias en la regi\u00f3n pueden cesar por completo\u201d, dice el menor de los Nobre. Sin agua como para sostener una sabana, el resultado podr\u00eda derivar en una desertificaci\u00f3n de la Amazonia. Si eso llegara a ocurrir, el escenario que \u00e9l avizora para el sur y sudeste del pa\u00eds podr\u00eda ser similar al de otras regiones ubicadas en la misma latitud: transformarse en un desierto.<\/p>\n<p>Antonio Nobre no se anima a hablar demasiado con respecto a S\u00e3o Paulo. \u201cMi informe se refiere a la Amazonia\u201d. Pero considera que la sequ\u00eda registrada aqu\u00ed no es independiente de lo que ocurre en el norte. Y opina que fue posible devastar buena parte del bosque atl\u00e1ntico sin que se note una reducci\u00f3n en las lluvias porque la Amazonia era capaz de suplir la falta de agua en la atm\u00f3sfera local. Pero eso parece que ya no sucede, y aprovecha la ocasi\u00f3n para sugerir que no s\u00f3lo la selva amaz\u00f3nica, sino tambi\u00e9n la que cubr\u00eda el litoral de casi todo Brasil necesita recuperarse inmediatamente. Si no fuera por otro motivo, al menos el agotamiento al que llegaron las represas que surten a buena parte de la poblaci\u00f3n paulista deber\u00eda bastar como argumento.<\/p>\n<p>La exportaci\u00f3n de agua desde la Amazonia hacia otras regiones de Brasil, sobre todo hacia el sudeste y el sur, constituye una realidad basada en el fen\u00f3meno denominado r\u00edos voladores. Un indicio de esa conexi\u00f3n directa fueron las intensas lluvias en el sudoeste de la Amazonia al comienzo de 2014, pr\u00e1cticamente el doble del volumen habitual, mientras S\u00e3o Paulo atravesaba el peor momento de una sequ\u00eda hist\u00f3rica. \u201cLa lluvia qued\u00f3 restringida a los estados de Rond\u00f4nia, Acre y la vecina Bolivia, a causa de un bloqueo atmosf\u00e9rico, algo similar a una burbuja de aire que imped\u00eda el paso de la humedad. Eso gener\u00f3 una estabilidad atmosf\u00e9rica, inhibiendo la formaci\u00f3n de lluvias y elevando las temperaturas\u201d, comenta Marengo, actualmente investigador del Centro Nacional de Monitoreo y Alerta de Desastres Naturales (Cemaden). \u00c9l es coautor de un art\u00edculo liderado por Jhan Carlo Espinoza, del Instituto Geof\u00edsico de Per\u00fa, que est\u00e1 en proceso de publicaci\u00f3n en <em>Environmental Research Letters<\/em> y forma parte de los resultados del programa Green Ocean (GO) Amazon, que cuenta con apoyo de la FAPESP.<\/p>\n<p>Sin embargo, no es posible afirmar cu\u00e1nto de esa relaci\u00f3n determina la sequ\u00eda paulista. \u201cTodav\u00eda no se ha logrado calcular que porcentaje de las lluvias del sudeste provienen de la Amazonia ni cu\u00e1nto llega aqu\u00ed proveniente de los frentes fr\u00edos del sur, a trav\u00e9s de la humedad transportada por la brisa marina o por la evaporaci\u00f3n local\u201d, dice. En su opini\u00f3n, la deforestaci\u00f3n podr\u00eda tener un impacto a largo plazo, pero a\u00fan es imposible determinar si est\u00e1 relacionada con la sequ\u00eda actual. \u201cPuede que el sudeste no se convierta en un desierto\u201d, pondera, \u201cpero los extremos clim\u00e1ticos podr\u00edan tornarse m\u00e1s intensos\u201d. Los estudios que utilizan los modelos clim\u00e1ticos elaborados por el grupo de Marengo ya preve\u00edan una redistribuci\u00f3n del total de lluvias, con un volumen muy grande en pocos d\u00edas y sequ\u00edas m\u00e1s prolongadas, algo que ya se ha observado en el sudeste y en el sur del pa\u00eds en los \u00faltimos 50 a\u00f1os.<\/p>\n<p>M\u00e1s all\u00e1 de ese efecto a distancia, a escala nacional, la relaci\u00f3n entre la vegetaci\u00f3n y los recursos h\u00eddricos tambi\u00e9n ocurre en el plano local, seg\u00fan el ingeniero agr\u00f3nomo Walter de Paula Lima, docente de la Escuela Superior de Agricultura Luiz de Queiroz (Esalq) de la Universidad de S\u00e3o Paulo (USP) y coordinador cient\u00edfico del Programa Cooperativo de Monitoreo Ambiental en Microcuencas (Promab) del Instituto de Investigaciones y Estudios Forestales. En sus estudios sobre el efecto de las selvas (o su remoci\u00f3n) en microcuencas hidrogr\u00e1ficas, De Paula Lima revel\u00f3 que la selva ribere\u00f1a o bosque en galer\u00eda que acompa\u00f1a los cursos de agua ayuda a mantener saludables los peque\u00f1os r\u00edos. \u201cEl sistema Cantareira, que abastece a S\u00e3o Paulo, est\u00e1 integrado por miles de microcuencas\u201d, relata. \u201cAqu\u00e9llas que se encuentran m\u00e1s degradadas no aportan al manantial\u201d. No obstante, tal an\u00e1lisis carece de datos experimentales concretos. Seg\u00fan De Paula Lima, para conocer exactamente el efecto de los bosques en galer\u00eda sobre los manantiales ser\u00eda necesario estudiar una microcuenca experimental donde se pueda medir las propiedades de los cursos de agua con y sin la protecci\u00f3n de la selva, sin que haya otros factores implicados. Un escenario pr\u00e1cticamente inalcanzable.<\/p>\n<p>El bi\u00f3logo Ricardo Ribeiro Rodrigues, de la Esalq, experto en recuperaci\u00f3n de bosques nativos, relata un experimento pr\u00e1ctico que refuerza la importancia de preservar las selvas ribere\u00f1as para el mantenimiento de los recursos h\u00eddricos. Cuenta que hace 24 a\u00f1os, el agua desapareci\u00f3 de la microcuenca de Iracem\u00e1polis, una localidad del interior paulista. La gobernaci\u00f3n busc\u00f3 ayuda en la Esalq, y el grupo de Ribeiro Rodrigues implement\u00f3 un proyecto de conservaci\u00f3n del suelo de la microcuenca y de recuperaci\u00f3n del bosque en galer\u00eda que deber\u00eda hallarse ah\u00ed. \u201cHace poco fui y me llev\u00e9 una sorpresa\u201d, comenta el investigador. El nivel de la represa se encuentra algo m\u00e1s bajo, pero cuenta con agua suficiente como para continuar abasteciendo a Iracem\u00e1polis, cuya poblaci\u00f3n se triplic\u00f3 durante el per\u00edodo. \u201cToda la regi\u00f3n padece problemas por falta de agua, pero Iracem\u00e1polis no\u201d.<\/p>\n<p>Las selvas afectan la salud de los recursos h\u00eddricos debido a su influencia sobre las lluvias, pero tambi\u00e9n reviste importancia su relaci\u00f3n con las aguas subterr\u00e1neas. El ingeniero Edson Wendland, docente del Departamento de Hidr\u00e1ulica y Saneamiento de la USP de S\u00e3o Carlos, estudia precisamente lo que ocurre con la recarga del acu\u00edfero Guaran\u00ed cuando se sustituye al cerrado por pasturas o cultivos tales como ca\u00f1a de az\u00facar, c\u00edtricos o eucalipto. El trabajo se llev\u00f3 a cabo en la cuenca del Ribeir\u00e3o da On\u00e7a, en el municipio de Brotas, del interior paulista, que se encuentra en estudio desde los a\u00f1os 1980.<\/p>\n<div id=\"attachment_203790\" style=\"max-width: 300px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-203790\" src=\"http:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2015\/11\/Aguas_40_2JG0883.jpg\" alt=\"Al final de noviembre, el sistema Cantareira ten\u00eda agua en la represa Paiva Castro...\" width=\"290\" height=\"193\" srcset=\"https:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2015\/11\/Aguas_40_2JG0883.jpg 290w, https:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2015\/11\/Aguas_40_2JG0883-120x80.jpg 120w, https:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2015\/11\/Aguas_40_2JG0883-250x166.jpg 250w\" sizes=\"auto, (max-width: 290px) 100vw, 290px\" \/><p class=\"wp-caption-text\"><span class=\"media-credits-inline\">L\u00c9O RAMOS<\/span>Al final de noviembre, el sistema Cantareira ten\u00eda agua en la represa Paiva Castro&#8230;<span class=\"media-credits\">L\u00c9O RAMOS<\/span><\/p><\/div>\n<p>Vali\u00e9ndose de pozos de monitoreo y estaciones clim\u00e1ticas, la idea consiste en describir, antes que ah\u00ed no quede vegetaci\u00f3n aut\u00f3ctona del cerrado, c\u00f3mo se produce la recarga del acu\u00edfero Guaran\u00ed bajo diferentes reg\u00edmenes de utilizaci\u00f3n del suelo. \u201cNo se puede administrar lo que no se conoce\u201d, dice Wendland al respecto de una de las fuentes de agua subterr\u00e1nea m\u00e1s importantes de Brasil. El acu\u00edfero es un estrato poroso de rocas en el cual se infiltra el agua de las lluvias, que luego se libera lentamente hacia los r\u00edos. Esa diferencia de tiempo entre el abastecimiento y la descarga, como consecuencia del lento desplazamiento del agua en el medio subterr\u00e1neo, es lo que le garantiza la permanencia a los r\u00edos, que dependen de esa econom\u00eda h\u00eddrica.<\/p>\n<p>El grupo de Wendland ha demostrado, por ejemplo, que la disponibilidad de agua disminuye cuando se sustituyen los peque\u00f1os \u00e1rboles retorcidos del cerrado o sabana, adaptados a la vida bajo estr\u00e9s h\u00eddrico, por eucaliptos, que consumen bastante agua y en pocos a\u00f1os alcanzan el tama\u00f1o de corte. Mediciones efectuadas entre 2004 y 2007 revelan que los \u00edndices de recarga exhiben una relaci\u00f3n \u00edntima con la intensidad de las precipitaciones y el tama\u00f1o de los cultivos agr\u00edcolas en esa regi\u00f3n donde el cerrado se encuentra pr\u00e1cticamente extinto, seg\u00fan se informa en un art\u00edculo aceptado para su publicaci\u00f3n en <em>Anais da Academia Brasileira de Ci\u00eancias<\/em>.<\/p>\n<p>Con todo, esto no significa que los eucaliptos sean absolutos villanos. El impacto de los \u00e1rboles de gran porte depende, en parte, de la profundidad del acu\u00edfero en el punto en que est\u00e1n plantados. A juicio de De Paula Lima, los m\u00e1s de 20 a\u00f1os de monitoreo continuo realizado por el Promab demostraron que la relaci\u00f3n entre especies forestales y el agua no es constante. \u201cAll\u00ed donde la disponibilidad es cr\u00edtica, un nuevo elemento podr\u00eda secar las microcuencas\u201d, explica. \u201cPero donde el balance h\u00eddrico y clim\u00e1tico es bueno, la merma del agua no se siente\u201d. Tales conclusiones dejan en claro que se necesita determinar las zonas donde se puede plantar y donde esa pr\u00e1ctica resultar\u00eda nociva, una planificaci\u00f3n que no existe en Brasil.<\/p>\n<p>Para Wendland, la importancia de comprender la relaci\u00f3n entre el cerrado y los acu\u00edferos resulta crucial, pues las cabeceras de la mayor\u00eda de las grandes cuencas hidrogr\u00e1ficas del pa\u00eds se encuentran en los dominios de ese bioma. M\u00e1s all\u00e1 de su relevancia como recurso h\u00eddrico, algunas de esas cuencas \u2013del Paran\u00e1, del Tocantins, del Parna\u00edba y del S\u00e3o Francisco\u2013 son las principales proveedoras de agua para la generaci\u00f3n de energ\u00eda el\u00e9ctrica en Brasil.<\/p>\n<p>En poco m\u00e1s de medio siglo, la mitad del \u00e1rea del cerrado fue talada, cedi\u00e9ndole su lugar a las actividades agr\u00edcolas. Para evaluar el efecto de dicha alteraci\u00f3n en el uso del suelo sobre la disponibilidad h\u00eddrica, el doctorando Paulo Tarso de Oliveira, del grupo de S\u00e3o Carlos, efectu\u00f3 un estudio utilizando los datos del monitoreo remoto en toda el \u00e1rea que ocupa el bioma. Por medio de los sensores, se puede evaluar no s\u00f3lo la alteraci\u00f3n de la vegetaci\u00f3n, sino tambi\u00e9n calcular las precipitaciones, los \u00edndices de evapotranspiraci\u00f3n por las plantas y estimar la variaci\u00f3n en el almacenamiento del agua. Seg\u00fan un art\u00edculo publicado en septiembre de 2014 en la revista <em>Water Resources Research<\/em>, los datos indican una reducci\u00f3n del escurrimiento a causa de actividades agr\u00edcolas intensivas.<\/p>\n<p>El desmonte y el uso agr\u00edcola del suelo son importantes, pero Wendland sostiene que el mayor problema actual para la recarga del acu\u00edfero es la disminuci\u00f3n de las lluvias. \u201cEl acu\u00edfero suple la falta de precipitaciones durante dos o tres a\u00f1os, luego ya no logra mantener el escurrimiento b\u00e1sico en los r\u00edos\u201d, dice. En los \u00faltimos a\u00f1os, las precipitaciones de la estaci\u00f3n lluviosa se ubicaron por debajo del promedio, lo cual confirma los resultados observados. Tambi\u00e9n explica, seg\u00fan \u00e9l, fen\u00f3menos alarmantes tales como el agotamiento de la cabecera principal del r\u00edo S\u00e3o Francisco, que se sec\u00f3 durante un lapso de alrededor de tres meses y reci\u00e9n volvi\u00f3 a manar al final de noviembre.<\/p>\n<p>El desaf\u00edo de administrar las aguas subterr\u00e1neas, que representan un 98% del agua dulce del planeta, presenta otras particularidades en las zonas urbanas, donde puede llegar a ser un recurso crucial. Seg\u00fan el ge\u00f3logo Ricardo Hirata, del Instituto de Geociencias (IGc) de la USP, un 75% de los municipios paulistas se abastece en parte o completamente con esas aguas. Eso incluye a importantes ciudades del estado, entre las que se destaca Ribeir\u00e3o Preto, donde surten al 100% de los m\u00e1s de 600 mil habitantes. A escala nacional, otras ciudades que se abastecen completamente mediante aguas subterr\u00e1neas son Juazeiro do Norte, en el estado de Cear\u00e1, Santar\u00e9m, en Par\u00e1, y Uberaba, en Minas Gerais, seg\u00fan informa el libro <em>\u00c1guas subterr\u00e2neas urbanas no Brasil<\/em>, en proceso de publicaci\u00f3n a cargo del IGc y del Centro de Investigaciones en Aguas Subterr\u00e1neas (Cepas).<\/p>\n<p>Lo sorprendente es que las p\u00e9rdidas de agua en el abastecimiento p\u00fablico de las ciudades vayan a parar al acu\u00edfero. \u201cLa impermeabilizaci\u00f3n del suelo reduce la penetraci\u00f3n del agua de lluvia, pero las p\u00e9rdidas compensan y superan esa merma y el saldo es una recarga mayor donde hay ciudades, en comparaci\u00f3n con otras \u00e1reas\u201d, explica Hirata. \u201cSi analizamos el agua de cualquier pozo en S\u00e3o Paulo, una mitad provendr\u00e1 del acu\u00edfero y la otra, de la compa\u00f1\u00eda de abastecimiento, la Sabesp\u201d. Hirata estima que la capital paulista cuenta con casi 13 mil perforaciones, todas particulares, y muchas ilegales. \u201cHay leyes para la administraci\u00f3n de ese recurso, pero no se cumplen\u201d, comenta.<\/p>\n<div id=\"attachment_203789\" style=\"max-width: 300px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-203789\" src=\"http:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2015\/11\/Aguas_21_2JG0893.jpg\" alt=\"... mientras la sequ\u00eda era evidente en el Jacare\u00ed\/ Jaguari\" width=\"290\" height=\"436\" srcset=\"https:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2015\/11\/Aguas_21_2JG0893.jpg 290w, https:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2015\/11\/Aguas_21_2JG0893-120x180.jpg 120w, https:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2015\/11\/Aguas_21_2JG0893-250x376.jpg 250w\" sizes=\"auto, (max-width: 290px) 100vw, 290px\" \/><p class=\"wp-caption-text\"><span class=\"media-credits-inline\">L\u00c9O RAMOS<\/span>&#8230; mientras la sequ\u00eda era evidente en el Jacare\u00ed\/ Jaguari<span class=\"media-credits\">L\u00c9O RAMOS<\/span><\/p><\/div>\n<p>Un problema que se genera en las ciudades es la contaminaci\u00f3n de los acu\u00edferos con nitrato, debido a las p\u00e9rdidas en el sistema de cloacas. Como el saneamiento es caro, los pozos afectados terminan abandonados. En las ciudades donde se los utiliza para el abastecimiento p\u00fablico, la soluci\u00f3n consiste en mezclar agua contaminada con la de pozos limpios, para que la calidad final sea aceptable. \u201cEn Natal ya no hay agua suficiente para mezclar\u201d, advierte Hirata. Las napas constituyen la fuente del 70% del agua en la capital del estado de Rio Grande do Norte.<\/p>\n<p>Otro tipo de contaminaci\u00f3n importante es la proveniente de la industria, tal como la que causan los solventes organoclorados. El ge\u00f3logo Reginaldo Bertolo, tambi\u00e9n del IGc y director del Cepas, estudia c\u00f3mo se comporta ese contaminante en el acu\u00edfero que se encuentra en el subsuelo de Jurubatuba, en la zona sur paulistana, una regi\u00f3n industrial desde los a\u00f1os 1950. \u201cSe trata de un contaminante con comportamiento complejo en el acu\u00edfero\u201d, comenta. En esa roca dura, donde el agua se desplaza a trav\u00e9s de fracturas, ese compuesto m\u00e1s denso que el agua se hunde y s\u00f3lo se detiene cuando llega a un estrato impermeable. \u201cSon productos t\u00f3xicos y carcin\u00f3genos\u201d. La contaminaci\u00f3n impide el uso del agua subterr\u00e1nea en una regi\u00f3n donde existe una fuerte demanda.<\/p>\n<p>En forma conjunta con cient\u00edficos de la Universidad de Guelph, en Canad\u00e1, el grupo de Bertolo est\u00e1 mapeando esos contaminantes para comprender c\u00f3mo se comportan y plantear estrategias para eliminarlo del acu\u00edfero. Para ello, el pr\u00f3ximo paso consiste en la utilizaci\u00f3n de un sistema desarrollado por los canadienses para la extracci\u00f3n de muestras de la roca e instalaci\u00f3n de perforaciones de monitoreo especiales. \u201cEsos dispositivos permiten recoger agua en m\u00e1s de 20 fracturas diferentes en una misma perforaci\u00f3n\u201d, afirma. \u201cDesarrollaremos un modelo matem\u00e1tico para reproducir lo que sucede y elaborar pron\u00f3sticos\u201d.<\/p>\n<p>El ge\u00f3logo advierte que es importante mapear mejor las napas subterr\u00e1neas y analizar su calidad, porque es un recurso que podr\u00eda resultar complementario en las ciudades. \u201cEl agua subterr\u00e1nea es un recurso poco conocido\u201d. La ingeniera Monica Porto, de la Escuela Polit\u00e9cnica de la USP, no cree que se pueda expandir demasiado el uso de esas napas en la Regi\u00f3n Metropolitana de S\u00e3o Paulo. Y opina que, para rebasar los alrededor de 10 metros c\u00fabicos por segundo (m<sup>3<\/sup>\/s) que se extraen de los miles de pozos existentes, se necesitar\u00edan miles de nuevas perforaciones. \u201cPero esos 10 m<sup>3<\/sup>\/s no pueden faltar, debemos cuidarlos\u201d.<\/p>\n<p>La ingeniera, quien ya ocup\u00f3 la presidencia y todav\u00eda integra el consejo consultivo de la Asociaci\u00f3n Brasile\u00f1a de Recursos H\u00eddricos, medita maneras de garantizarle la seguridad h\u00eddrica a la poblaci\u00f3n. La falta de agua es efectivamente una de las cosas m\u00e1s graves que pueden ocurrir en una ciudad. \u201cEstamos obligados a trabajar con una probabilidad de fallo muy baja\u201d. Seg\u00fan ella, en 2009 el gobierno paulista le encarg\u00f3 a una empresa consultora un estudio sobre lo que deber\u00eda hacerse para garantizar el abastecimiento de agua. El estudio estuvo listo en octubre de 2013, cuando ya se padec\u00eda la m\u00e1s importante crisis h\u00eddrica de la historia del estado. Porto explica que resulta imposible contemplar al Gran S\u00e3o Paulo en forma aislada, porque ya no hay de d\u00f3nde sacar agua sin disputarla con los vecinos. Por eso, el estudio abarca a la megametr\u00f3polis, que engloba m\u00e1s de 130 municipios y una poblaci\u00f3n de 30 millones de personas.<\/p>\n<p>Las obras necesarias para la mejora de la seguridad h\u00eddrica ya han comenzado, con la implementaci\u00f3n de un sistema destinado extraer agua del r\u00edo Juqui\u00e1, en Vale do Ribeira, que estar\u00e1 listo en 2018. La construcci\u00f3n de las represas de Pedreira y Duas Pontes, que abastecer\u00e1n a la regi\u00f3n de Campinas, atraviesa la etapa de obtenci\u00f3n de permiso ambiental. \u201cManaos y Campinas son las \u00fanicas ciudades de Brasil con m\u00e1s de un mill\u00f3n de habitantes que no cuentan con reservorio de agua\u201d, comenta Porto. No le hace falta a Manaos, a orillas del r\u00edo Amazonas, pero s\u00ed a Campinas, que depende del sistema Cantareira. Ella, que en su hogar \u201chace de tripas coraz\u00f3n\u201d para ahorrar agua, sostiene que la crisis actual es importante para concientizar a la poblaci\u00f3n acerca de la necesidad de disminuir el consumo. Tambi\u00e9n subraya la importancia del conjunto de disposiciones que deber\u00e1 revisarse con car\u00e1cter de emergencia. \u201cTendremos que aprender mediante el padecimiento\u201d, dice Porto, quien habitualmente bromea que es mejor que no llueva demasiado para que la instructiva crisis no quede en el olvido. \u201cNo obstante, si no llueve mucho, y pronto, voy a dejar de bromear: tiene que llover\u201d<\/p>\n<p><strong>Proyectos<\/strong><br \/>\n<strong>1.<\/strong> Comprensi\u00f3n de las causas de las tendencias que determinan el inicio de la estaci\u00f3n lluviosa en la Amazonia sobre los modelos clim\u00e1ticos utilizando observaciones del GoAmazon y de las lluvias (<a href=\"http:\/\/www.bv.fapesp.br\/pt\/auxilios\/83532\/entendimento-das-causas-dos-vieses-que-determinam-o-inicio-da-estacao-chuvosa-na-amazonia-nos-modelo\/\" target=\"_blank\">n\u00ba 13\/50538-7<\/a>); <strong>Investigador responsable<\/strong> Jos\u00e9 Antonio Marengo Orsini (Cemaden); <strong>Modalidad<\/strong> Ayuda Regular al Proyecto de Investigaci\u00f3n \u2013 GoAmazon; <strong>Inversi\u00f3n<\/strong> R$ 57.960,00 (FAPESP).<br \/>\n<strong>2.<\/strong> Establecimiento de un modelo conceptual hidrogeol\u00f3gico y de transporte y destino de compuestos organoclorados en el acu\u00edfero fracturado de la regi\u00f3n de Jurubatuba, S\u00e3o Paulo (<a href=\"http:\/\/www.bv.fapesp.br\/pt\/auxilios\/84496\/estabelecimento-do-modelo-conceitual-hidrogeologico-e-de-transporte-e-destino-de-compostos-organoclo\/\" target=\"_blank\">n\u00ba 13\/10311-3<\/a>); <strong>Investigador responsable<\/strong> Reginaldo Antonio Bertolo (IGc-USP); <strong>Modalidad<\/strong> Ayuda Regular al Proyecto de Investigaci\u00f3n; <strong>Inversi\u00f3n<\/strong> R$ 502.715,27 (FAPESP).<\/p>\n<p><em>Art\u00edculos cient\u00edficos<br \/>\n<\/em>MAKARIEVA, A. M. <em>et al<\/em>. <a href=\"http:\/\/journals.ametsoc.org\/doi\/abs\/10.1175\/JHM-D-12-0190.1\" target=\"_blank\">Why does air passage over forest yield more rain? Examining the coupling between rainfall, pressure and atmospheric moisture content<\/a>. <strong>Journal of Hydrometeorology<\/strong>. v. 15, n. 1, p. 411-26. feb. 2014.<br \/>\nMAKARIEVA, A. M. <em>et al<\/em>. <a href=\"http:\/\/www.atmos-chem-phys.net\/13\/1039\/2013\/acp-13-1039-2013.pdf\" target=\"_blank\">Where do winds come from? A new theory on how water vapor condensation influences atmospheric pressure and dynamics<\/a>. <strong>Atmospheric Chemistry and Physics<\/strong>. v. 13, p. 1039-56. 25 ene. 2013.<br \/>\nESPINOZA, J. <em>et al<\/em>. <a href=\"http:\/\/iopscience.iop.org\/1748-9326\/9\/12\/124007\/article\" target=\"_blank\">The extreme 2014 flood in South-western Amazon basin: The role of tropical-subtropical South Atlantic SST gradient<\/a>. <strong>Environmental Research Letters<\/strong>. En prensa.<br \/>\nWENDLAND, E. <em>et al<\/em>. <a href=\"http:\/\/www.scielo.br\/scielo.php?script=sci_serial&amp;pid=0001-3765&amp;lng=en&amp;nrm=iso\" target=\"_blank\">Recharge contribution to the Guarani Aquifer System estimated from the water balance method in a representative watershed<\/a>. <strong>Anais da Academia Brasileira de Ci\u00eancias<\/strong>. En prensa.<br \/>\nOLIVEIRA, P. T. S. <em>et al<\/em>. <a href=\"http:\/\/onlinelibrary.wiley.com\/doi\/10.1002\/2013WR015202\/abstract\" target=\"_blank\">Trends in water balance components across the Brazilian Cerrado<\/a>. <strong>Water Resources Research<\/strong>. v. 50, n. 9, p. 7100-14. sept. 2014<\/p>\n","protected":false},"excerpt":{"rendered":"La escasez de agua que alarma a Brasil tiene relaci\u00f3n \u00edntima con las selvas","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[179],"tags":[286,309,269],"coauthors":[95],"class_list":["post-203778","post","type-post","status-publish","format-standard","hentry","category-tapa","tag-clima-es","tag-geologia-es","tag-ambiente-es"],"acf":[],"_links":{"self":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/posts\/203778","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/comments?post=203778"}],"version-history":[{"count":0,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/posts\/203778\/revisions"}],"wp:attachment":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/media?parent=203778"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/categories?post=203778"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/tags?post=203778"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/coauthors?post=203778"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}