{"id":283614,"date":"2019-04-24T14:52:01","date_gmt":"2019-04-24T17:52:01","guid":{"rendered":"http:\/\/revistapesquisa.fapesp.br\/?p=283614"},"modified":"2019-04-24T14:52:01","modified_gmt":"2019-04-24T17:52:01","slug":"las-puertas-de-entrada-a-la-universidad","status":"publish","type":"post","link":"https:\/\/revistapesquisa.fapesp.br\/es\/las-puertas-de-entrada-a-la-universidad\/","title":{"rendered":"Las puertas de entrada a la universidad"},"content":{"rendered":"<p>La difusi\u00f3n de acciones afirmativas en la selecci\u00f3n de los estudiantes de las universidades brasile\u00f1as comienza a producir efectos que no se limitan a la meta de ampliar el acceso de los alumnos provenientes de las escuelas p\u00fablicas o a la garant\u00eda de representatividad para negros, mulatos e ind\u00edgenas en las carreras de grado. En el caso de las universidades estaduales paulistas, la admisi\u00f3n en la educaci\u00f3n superior, que anta\u00f1o s\u00f3lo depend\u00eda del examen de ingreso, pas\u00f3 a regirse por todo un men\u00fa de alternativas tendientes a asegurar la calidad de los postulantes y que incluyen la asignaci\u00f3n de bonus en los resultados del examen de ingreso, la utilizaci\u00f3n de notas del Examen Nacional de la Ense\u00f1anza Media (Enem) y, eventualmente, incluso simplificaciones, en las cuales la admisi\u00f3n no depende de un examen.<\/p>\n<p>El nuevo modelo de ingreso anunciado en el mes de noviembre por la Universidad de Campinas (Unicamp) constituye el ejemplo m\u00e1s radical de esta tendencia. A partir de 2019, entra en vigencia un sistema de cupos \u00e9tnico-raciales que reservar\u00e1 un 25% de las vacantes disponibles en la instituci\u00f3n a aquellos postulantes que se autodeclaren negros o mulatos o pardos. Su mecanismo es bastante m\u00e1s complejo que el sistema de cupos vigente en las 63 universidades federales, creado por ley en 2012. Las vacantes de la Unicamp se ofrecer\u00e1n mediante dos sistemas paralelos, donde el 80% se adjudicar\u00e1 por examen de ingreso (con un cuarto de ellas reservado para los autodeclarados negros y mulatos) y el resto por las notas obtenidas en el Enem por los candidatos (un 15% de las vacantes para los egresados de establecimientos p\u00fablicos y un 5% para negros y pardos). Adem\u00e1s, se mantuvo otra pol\u00edtica afirmativa creada hace m\u00e1s de una d\u00e9cada que otorga bonus en el puntaje en las dos etapas del examen de ingreso a los postulantes provenientes de las escuelas p\u00fablicas. \u201cCon tales disposiciones, se busca asegurar que al menos la mitad de los ingresantes provenga del sistema p\u00fablico y que el porcentaje de negros y pardos entre los alumnos crezca del actual 20% al 37%, que representa a la proporci\u00f3n de esos grupos en la poblaci\u00f3n paulista\u201d, dice Jos\u00e9 Alves de Freitas Neto, coordinador del examen de ingreso de la Unicamp.<\/p>\n<p>El Consejo Universitario aprob\u00f3 otras innovaciones que se implementar\u00e1n a partir de 2019, tales como la creaci\u00f3n de un examen espec\u00edfico para el ingreso de abor\u00edgenes y la posibilidad, in\u00e9dita en el pa\u00eds, de acceder sin rendir examen para los medallistas de olimp\u00edadas cient\u00edficas. En ambas situaciones, la cantidad de vacantes disponibles estar\u00e1 definida por cada departamento de la universidad. \u201cIdeamos posibilidades que ampl\u00edan las posibilidades de acceso y muestran el empe\u00f1o de la universidad p\u00fablica para proponer nuevas ideas para el ingreso de los estudiantes\u201d, dice el f\u00edsico Marcelo Knobel, rector de la Unicamp. \u201cNo s\u00f3lo estamos lidiando con pol\u00edticas de inclusi\u00f3n, sino tambi\u00e9n con un perfeccionamiento de la admisi\u00f3n, en busca de los mejores alumnos\u201d, dice.<\/p>\n<p>La Unicamp tambi\u00e9n eval\u00faa la posibilidad de expandir un programa de acciones afirmativas creado por la universidad en 2012: el ProFIS (Programa de Formaci\u00f3n Interdisciplinaria Superior). La iniciativa selecciona a los mejores alumnos del 3\u00ba y \u00faltimo a\u00f1o de la ense\u00f1anza media p\u00fablica de Campinas, con base en las notas del Enem, y les ofrece un curso de dos a\u00f1os de duraci\u00f3n con contenidos multidisciplinarios. Al finalizar el mismo, aquellos alumnos con buenas calificaciones tienen la posibilidad de ingresar en las carreras de grado de la Unicamp sin rendir examen de ingreso. Se encuentra en estudio la ampliaci\u00f3n de la cantidad de ciudades beneficiadas por el programa para llegar a un p\u00fablico mayor que el actual.<\/p>\n<div id=\"attachment_283623\" style=\"max-width: 1310px\" class=\"wp-caption alignright\"><a href=\"http:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2019\/04\/030_Cotas_263_03-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-283623 size-full\" src=\"http:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2019\/04\/030_Cotas_263_03-1.jpg\" alt=\"\" width=\"1300\" height=\"1954\" srcset=\"https:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2019\/04\/030_Cotas_263_03-1.jpg 1300w, https:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2019\/04\/030_Cotas_263_03-1-250x376.jpg 250w, https:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2019\/04\/030_Cotas_263_03-1-700x1052.jpg 700w, https:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2019\/04\/030_Cotas_263_03-1-120x180.jpg 120w\" sizes=\"auto, (max-width: 1300px) 100vw, 1300px\" \/><p class=\"wp-caption-text\"><span class=\"media-credits-inline\">L\u00e9o Ramos Chaves<\/span><\/a> Estudiantes de la Universidad Federal del ABC<span class=\"media-credits\">L\u00e9o Ramos Chaves<\/span><\/p><\/div>\n<p>Las universidades de S\u00e3o Paulo (USP) y Estadual Paulista (Unesp) tambi\u00e9n modificaron su forma de ingreso en los a\u00f1os recientes. La USP, que desde hace m\u00e1s de una d\u00e9cada conced\u00eda bonus en la calificaci\u00f3n del examen de ingreso a los alumnos de las escuelas p\u00fablicas y a negros, mulatos e ind\u00edgenas, en 2015 comenz\u00f3 a ofrecer parte de sus vacantes mediante el Sistema de Selecci\u00f3n Unificado (Sisu), que selecciona a los ingresantes de las universidades federales a partir de sus notas en el Enem. De las 11.147 vacantes que ofrece la USP en 2018, 2.745 ser\u00e1n disputadas v\u00eda Sisu, pero en tres listas por separado, siendo 423 por amplia competencia, 1.312 para estudiantes que cursaron la ense\u00f1anza media en escuelas p\u00fablicas y 1.010 para aquellos alumnos de escuelas p\u00fablicas autodeclarados negros, pardos e ind\u00edgenas. Con ese esquema, la USP elev\u00f3 el porcentaje de egresados de la ense\u00f1anza p\u00fablica de un 32,3% en 2014 a un 36,9% en 2017.<\/p>\n<p>En un estudio efectuado por la Prorrector\u00eda de Grado de la USP en 2016, se compar\u00f3 el desempe\u00f1o de los alumnos que ingresaron mediante el examen de ingreso y por el Sisu en 22 \u00e1reas. Al finalizar el segundo semestre lectivo, los estudiantes que hab\u00edan ingresado rindiendo un examen de ingreso tuvieron promedios mayores que los del Sisu en carreras tales como medicina, derecho y ciencias sociales; mientras que los del Sisu tomaron ventaja en carreras tales como ingenier\u00eda de materiales, econom\u00eda, f\u00edsica y qu\u00edmica, entre otras. De cualquier modo, la diferencia de promedios entre los dos grupos fue exigua.<\/p>\n<p>En el mes de julio, la USP decidi\u00f3 cambiar nuevamente las reglas para instituir un sistema que destinar\u00e1 la mitad de las vacantes ofrecidas a los alumnos de las escuelas p\u00fablicas, con una subreserva para los que se reconozcan como negros, mulatos y abor\u00edgenes nativos. La iniciativa se implementar\u00e1 en forma escalonada: para el ingreso de 2018, un 37% de las vacantes de cada carrera y turno ser\u00e1 para los alumnos provenientes de escuelas p\u00fablicas. En 2019, esa proporci\u00f3n ser\u00e1 de un 40% y, en 2025, de un 45%, para llegar a un 50% en 2031. \u201cEs la primera vez que la USP adopta una pol\u00edtica institucional de cupos sociales y raciales\u201d, dice el prorrector de Grado, Ant\u00f4nio Carlos Hernandes.<\/p>\n<p>Esto no es una novedad en el caso de la Unesp. En 2013, la universidad cre\u00f3 en forma pionera entre todas las universidades estaduales paulistas un sistema de cupos similar al de las federales. Increment\u00f3 progresivamente la reserva de vacantes hasta llegar, en el examen de ingreso de 2018, a un 50% para los alumnos de las escuelas p\u00fablicas, con una parte de las mismas destinadas a negros y pardos, de manera tal que ese grupo llegase al 35% de los admitidos. \u201cLa Unesp siempre ha logrado atraer a un grueso contingente de alumnos de las escuelas p\u00fablicas, pero para cumplir con la meta del 50% fue necesario recurrir a los cupos\u201d, dice Gladis Massini-Cagliari, prorrectora de Grado de la universidad.<\/p>\n<p>La meta a la que alude Massini-Cagliari, de una reserva del 50% para alumnos provenientes de escuelas p\u00fablicas y de un 35% para negros, mulatos e ind\u00edgenas, qued\u00f3 definida por el Programa de Inclusi\u00f3n por M\u00e9rito en la Educaci\u00f3n P\u00fablica de Nivel Superior de S\u00e3o Paulo (Pimesp), instituido al final de 2012 por la gobernaci\u00f3n paulista, y fue implementada con formatos espec\u00edficos por las tres universidades del estado. \u201cEl Pimesp incorpor\u00f3 un reclamo de la sociedad consistente en ampliar la presencia de alumnos de las escuelas p\u00fablicas que representan la diversidad de la poblaci\u00f3n. A partir de ello, las universidades estaduales tuvieron que modificar sus sistemas de ingreso\u201d, explica Fernanda Estevan, docente de la Facultad de Econom\u00eda, Administraci\u00f3n y Contabilidad (FEA) de la USP, una estudiosa de las acciones afirmativas.<\/p>\n<p>En su tesis de libre docencia, que defendiera en 2017, la investigadora analiz\u00f3 los efectos del sistema de bonus en el examen de ingreso creado por la Unicamp en 2005, un impulso innovador para la \u00e9poca tendiente a ampliar la inclusi\u00f3n social y racial en la universidad sin recurrir a cupos. \u201cEl programa era interesante y tuvo resultados positivos\u201d, concluy\u00f3. El sistema part\u00eda de un supuesto, seg\u00fan Estevan poco explorado en el debate p\u00fablico. \u201cFue elaborado a partir de evidencias estad\u00edsticas, seg\u00fan las cuales los postulantes de escuelas p\u00fablicas cuyas calificaciones en el examen de ingreso no guardaban gran diferencia con respecto a las de los candidatos provenientes de establecimientos educativos privados pod\u00edan alcanzar un desempe\u00f1o muy satisfactorio en la universidad, a veces incluso superior al de los egresados de colegios privados. La concesi\u00f3n de un bonus de 40 puntos ayudar\u00eda a atraer talentos de la escuela p\u00fablica a la universidad\u201d.<\/p>\n<blockquote><p>La meta del 50% para alumnos provenientes de escuelas p\u00fablicas indujo a las universidades estaduales paulistas a modificar las reglas de ingreso<\/p><\/blockquote>\n<p>La investigadora constat\u00f3 que el sistema increment\u00f3 en un 30% la probabilidad de que un alumno de la escuela p\u00fablica ingresara en la Unicamp, m\u00e1s all\u00e1 de elevar el porcentaje de estudiantes de bajos ingresos. En cuanto a las pol\u00edticas de bonus, no se observaron efectos colaterales, tales como un eventual desinter\u00e9s de los beneficiarios por esforzarse para aprobar el examen de admisi\u00f3n. Seg\u00fan Estevan, existen indicios de que el bonus tuvo una influencia positiva en la elecci\u00f3n de carreras, promoviendo que los egresados de las escuelas p\u00fablicas intentaran ser admitidos en las carreras donde se registraba mayor competencia.<\/p>\n<p>Para Estevan, el programa tuvo efectos limitados \u2013el porcentaje de postulantes para rendir el examen de ingreso provenientes de escuelas p\u00fablicas alcanz\u00f3 un techo lindante al 35% del total\u2013 debido a razones ajenas a su concepci\u00f3n. \u201cEn el examen de ingreso de 2005, cuando se lo implement\u00f3, aument\u00f3 la cantidad de postulantes de escuelas p\u00fablicas, pero al a\u00f1o siguiente esa cifra se estanc\u00f3. Hay algunos factores que pueden ayudar a entender este fen\u00f3meno, tales como el aumento de vacantes en las universidades federales y la oferta de becas en el sistema privado del programa Universidad para Todos, el Prouni, aunque har\u00eda falta estudiar estas hip\u00f3tesis con mayor profundidad\u201d, explica. El profesor Renato Pedrosa, docente del Instituto de Geociencias de la Unicamp que coordin\u00f3 el examen de ingreso a la universidad entre 2003 y 2011, se\u00f1ala que desde hace una d\u00e9cada, el porcentaje de graduados de la ense\u00f1anza media en S\u00e3o Paulo se estanc\u00f3 en un 66%. En Brasil, el promedio es del 55%. \u201cEstim\u00e1bamos que esa cuota aumentar\u00eda, incrementando el n\u00famero de postulantes de las escuelas p\u00fablicas que rendir\u00edan ex\u00e1menes de ingreso, as\u00ed como la cantidad de aprobados. Pero eso no sucedi\u00f3\u201d.<\/p>\n<p>Hace dos a\u00f1os, la Unicamp realiz\u00f3 una primera modificaci\u00f3n para aumentar la inclusi\u00f3n, sin recurrir, no obstante, a la reserva de vacantes. El bonus en la nota del examen de ingreso subi\u00f3 hasta los 120 puntos, y con ello, el porcentaje de ingresantes provenientes de las escuelas p\u00fablicas lleg\u00f3 a un promedio del 50% del total de la universidad, tanto en 2016 como en 2017, conforme a lo previsto en el Pimesp. Pero esta estrategia tuvo efectos inesperados: en las carreras muy elegidas, tales como medicina y arquitectura, donde la diferencia entre las notas de muchos de los postulantes es exigua, el bonus se transform\u00f3 en una ventaja considerable para los alumnos de las escuelas p\u00fablicas, muy superior a aqu\u00e9lla que se espera que proporcione un programa de acci\u00f3n afirmativa. En tanto, en las carreras con poca demanda, el sistema admiti\u00f3 en la universidad a alumnos con un desempe\u00f1o muy pobre en el examen de ingreso, que luego afrontaron dificultades para sostenerse en la instituci\u00f3n. \u201cEl bonus exagerado distorsion\u00f3 los resultados del examen de admisi\u00f3n\u201d, analiza Knobel. Seg\u00fan el rector, el nuevo sistema h\u00edbrido de bonus, cupos y examen de ingreso apunta a ser eficiente en cuanto a la inclusi\u00f3n social y racial, y simult\u00e1neamente atrae a estudiantes con amplio potencial.<\/p>\n<div id=\"attachment_283627\" style=\"max-width: 1010px\" class=\"wp-caption alignright\"><a href=\"http:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2019\/04\/030_Cotas_263_04-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-283627 size-full\" src=\"http:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2019\/04\/030_Cotas_263_04-1.jpg\" alt=\"\" width=\"1000\" height=\"605\" srcset=\"https:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2019\/04\/030_Cotas_263_04-1.jpg 1000w, https:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2019\/04\/030_Cotas_263_04-1-250x151.jpg 250w, https:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2019\/04\/030_Cotas_263_04-1-700x424.jpg 700w, https:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2019\/04\/030_Cotas_263_04-1-120x73.jpg 120w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><p class=\"wp-caption-text\"><span class=\"media-credits-inline\">L\u00e9o Ramos Chaves<\/span><\/a> Una divisi\u00f3n de ingresantes de medicina de la Unicamp en 2016, que gracias al bonus en la nota del examen de ingreso, congregaba casi un 70% de alumnos provenientes de la red p\u00fablica<span class=\"media-credits\">L\u00e9o Ramos Chaves<\/span><\/p><\/div>\n<p>La experiencia acumulada con los cupos y otras acciones afirmativas en el pa\u00eds disip\u00f3 los temores de que habr\u00eda un descenso dr\u00e1stico en el nivel de los estudiantes y en la calidad de la educaci\u00f3n. \u201cCuando en una carrera hay gran competencia en el examen de ingreso, con m\u00e1s de 50 postulantes por vacante, pr\u00e1cticamente no existe riesgo de que los alumnos que ingresan por cupo no est\u00e9n a la altura. Como la cantidad de candidatos de alto desempe\u00f1o siempre es muy elevada, tambi\u00e9n hay en ese grupo muchos beneficiarios de acciones afirmativas que logran mantenerse en la carrera y llegan a ser buenos profesionales\u201d, dice Renato Pedrosa. El riesgo de los cupos, seg\u00fan el investigador, queda restringido a las carreras de baja demanda, que pueden llegar a recibir alumnos sin condiciones para lograr su permanencia. Para Pedrosa, la idea que sostiene que el examen de ingreso es el \u00fanico m\u00e9todo adecuado para la selecci\u00f3n es incorrecta. \u201cAquel alumno con la mayor nota en dicho examen raramente es el que logra el mejor desempe\u00f1o a lo largo de la carrera. Podr\u00eda pensarse en formas de selecci\u00f3n que atraigan a la universidad a estudiantes con potencial, incluso aunque presenten alguna deficiencia o no se hayan preparado muy bien para rendir el examen de ingreso\u201d.<\/p>\n<p>La soci\u00f3loga Rosana Heringer estudia los efectos de la adopci\u00f3n de cupos en la Universidad Federal de R\u00edo de Janeiro (UFRJ), donde se desempe\u00f1a como docente en la Facultad de Educaci\u00f3n, y refuta la idea de que el sistema tuvo un impacto negativo en la calidad educativa. \u201cLas dificultades para sostenerse en la carrera y reprobar en materias de ciencias exactas pueden ser algo m\u00e1s sintom\u00e1ticas entre los beneficiarios de cupos, pero tambi\u00e9n son frecuentes en los casos de todos los estudiantes\u201d, sostiene. \u201cEn aquellas carreras donde hay poca competencia al momento de rendir el examen de ingreso siempre habr\u00e1 problemas. En pedagog\u00eda, muchos alumnos muestran dificultades para seguir el ritmo de las lecturas y no han desarrollado habilidades lo suficientemente adecuadas en cuanto a la escritura. En el profesorado en f\u00edsica, resultan comunes los problemas con las materias de c\u00e1lculo. Estos problemas tambi\u00e9n aparecen ahora y puntualmente en otras carreras, pero disponemos de las herramientas para afrontarlos\u201d.<\/p>\n<p>Tales herramientas se ajustan a dos vertientes: las que buscan brindar condiciones econ\u00f3micas para la permanencia de los estudiantes, principalmente por medio de becas, y aqu\u00e9llas que apuntan a las dificultades acad\u00e9micas, bajo la forma de apoyo pedag\u00f3gico y psicol\u00f3gico. En Brasil se ha hecho hincapi\u00e9 en la primera de estas vertientes. Rosana Heringer coordina un proyecto tendiente a comparar la situaci\u00f3n de Brasil y de Estados Unidos en relaci\u00f3n con el ingreso y la permanencia de alumnos negros y mulatos en la educaci\u00f3n superior. \u201cEn cuanto al acceso a la educaci\u00f3n superior, los sistemas de ambos pa\u00edses son muy distintos. El porcentaje de j\u00f3venes de 18 a 24 a\u00f1os en las universidades estadounidenses es tres veces mayor que el de ac\u00e1. All\u00e1 el sistema educativo es mayoritariamente pagado, aunque existen esquemas de pagos escalonados seg\u00fan la renta de la familia, financiaci\u00f3n estudiantil y becas otorgadas por entidades filantr\u00f3picas. Con todo, el endeudamiento de los alumnos con la financiaci\u00f3n estudiantil se transform\u00f3 en ese pa\u00eds en un problema cr\u00f3nico y grav\u00edsimo\u201d, dice.<\/p>\n<div id=\"attachment_283631\" style=\"max-width: 1510px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2019\/04\/030_Cotas_263_05-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-283631 size-full\" src=\"http:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2019\/04\/030_Cotas_263_05-1.jpg\" alt=\"\" width=\"1500\" height=\"1000\" srcset=\"https:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2019\/04\/030_Cotas_263_05-1.jpg 1500w, https:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2019\/04\/030_Cotas_263_05-1-250x167.jpg 250w, https:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2019\/04\/030_Cotas_263_05-1-700x467.jpg 700w, https:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2019\/04\/030_Cotas_263_05-1-120x80.jpg 120w\" sizes=\"auto, (max-width: 1500px) 100vw, 1500px\" \/><p class=\"wp-caption-text\"><span class=\"media-credits-inline\">Eduardo Anizelli\/Folhapress<\/span><\/a> La prueba de ingreso unificado a las universidades del estado de S\u00e3o Paulo \u2013 Fuvest, en 2016: parte de las vacantes de la USP se disput\u00f3 mediante examen de ingreso y otra parte mediante el sistema del Sisu<span class=\"media-credits\">Eduardo Anizelli\/Folhapress<\/span><\/p><\/div>\n<p>En cuanto a las pol\u00edticas de permanencia, las diferencias tambi\u00e9n son acentuadas. \u201cEn Estados Unidos, las universidades se ocupan mucho de promover el \u00e9xito acad\u00e9mico de los alumnos y se hacen cargo de la oferta de varios tipos de ayuda. En eso, nosotros reci\u00e9n estamos dando los primeros pasos\u201d, afirma. Entre los mecanismos disponibles en las universidades estadounidenses, hay ayudant\u00edas, presencia de tutores, y guardias de atenci\u00f3n para los estudiantes, entre otros ejemplos.<\/p>\n<p>Una cr\u00edtica com\u00fan a las pol\u00edticas afirmativas es que \u00e9stas no generan gran impacto en las causas del acceso restringido de pobres y negros a la universidad p\u00fablica, que son la mala calidad de la educaci\u00f3n b\u00e1sica y la desigualdad social del pa\u00eds. \u201cEstoy a favor de las pol\u00edticas inclusivas, pero no creo que los cupos sean una soluci\u00f3n adecuada\u201d, sostuvo la antrop\u00f3loga Eunice Ribeiro Durhan, profesora em\u00e9rita de la USP, en un debate sobre los cupos promovido por la Radio USP en el mes de julio. \u201cSe intenta resolver el problema de la enorme desigualdad social de Brasil por medio de una disposici\u00f3n paliativa. No es por prejuicios que los negros no ingresan a las universidades, sino porque son pobres. El salario constituye el factor m\u00e1s importante en la caracterizaci\u00f3n del desempe\u00f1o educativo de la gente. Cuando se crean los cupos, en el fondo, lo que se hace es evitar afrontar ese problema\u201d. La antrop\u00f3loga fue una de las responsables de un documento sobre acciones afirmativas lanzado en 2013 por la Academia de Ciencias del Estado de S\u00e3o Paulo (Aciesp) y coordinado por el f\u00edsico Jos\u00e9 Goldemberg, actual presidente de la FAPESP. En dicho documento se sostiene que es necesaria una reestructuraci\u00f3n de la educaci\u00f3n b\u00e1sica e inicial para asegurarles una preparaci\u00f3n adecuada a los estudiantes, y propone medidas para implementarse a corto plazo, tales como la creaci\u00f3n de cursillos preparatorios para el ingreso en las universidades dedicados a alumnos de escasos recursos, acompa\u00f1ados por un sistema de concesi\u00f3n de becas de estudio.<\/p>\n<p>El profesor Jos\u00e9 Eduardo Krieger, docente de la Facultad de Medicina de la USP y que presid\u00eda la Aciesp al momento de la publicaci\u00f3n de dicho estudio, sostiene que existe una incompatibilidad entre el concepto de los cupos y la naturaleza de las universidades que act\u00faan en las fronteras del conocimiento. \u201cEn varios pa\u00edses se encuentra en debate la sostenibilidad de las universidades de investigaci\u00f3n. \u00c9stas cumplen un rol vital en la formaci\u00f3n de l\u00edderes y en la generaci\u00f3n del conocimiento, pero cuestan muy caras. Fundamentalmente en Europa, se discute al respecto de la necesidad de concentrar recursos en una cantidad acotada de instituciones para que \u00e9stas puedan cumplir su funci\u00f3n\u201d, dice Krieger. Una universidad de excelencia, puntualiza, depende de su capacidad para lograr atraer a los mejores alumnos independientemente del color de su piel. \u201cLos cupos, aparte de no resolver el problema dram\u00e1tico de la calidad de la educaci\u00f3n b\u00e1sica y media, pueden debilitar a las universidades de investigaci\u00f3n. En Brasil contamos con pocas: est\u00e1n las tres universidades estaduales paulistas y alrededor de una decena de federales. Es necesario luchar contra la desigualdad sin desarticular el esfuerzo de d\u00e9cadas de labor realizada para garantizar la calidad de esas instituciones\u201d, dice Krieger, quien tambi\u00e9n critica el escaso compromiso de las universidades para detectar a los mejores alumnos. \u201cNo se puede depender solamente del examen de ingreso. Hace mucho tiempo que vengo abogando para que la USP atraiga a los medallistas de olimp\u00edadas cient\u00edficas sin examen de ingreso, tal como hacen las universidades estadounidenses y europeas\u201d.<\/p>\n<p>Para el soci\u00f3logo Jos\u00e9 de Souza Martins, los sistemas adoptados por la USP y la Unicamp difieren de los criterios reguladores de las escuelas superiores de alto nivel. \u201cLas universidades que se precien deben empe\u00f1arse en reclutar a las mejores vocaciones, a los cerebros m\u00e1s destacados, sin importar la raza, el color, el origen, el g\u00e9nero o la convicci\u00f3n religiosa. Estas universidades no est\u00e1n para hacer caridad, para hacerle justicia a los supuestos damnificados. Existen para reclutar y capacitar a los mejores profesionales\u201d, dice De Souza Martins, profesor em\u00e9rito de la USP. \u201cSi la sociedad en su conjunto fuese seria, tendr\u00eda pol\u00edticas educativas tendientes a capacitar adecuadamente a las n\u00f3veles generaciones para las nuevas funciones profesionales de la sociedad moderna antes de que lleguen a la universidad. Brasil no est\u00e1 haciendo eso. Les endosa sus deudas sociales a las universidades de excelencia, y \u00e9stas no est\u00e1n preparadas para resolver este problema\u201d.<br \/>\n<a href=\"http:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2019\/04\/eng-e-esp-infos12.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1140\" height=\"620\" class=\"alignnone size-full wp-image-283641\" src=\"http:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2019\/04\/eng-e-esp-infos12.jpg\" alt=\"\" srcset=\"https:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2019\/04\/eng-e-esp-infos12.jpg 1140w, https:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2019\/04\/eng-e-esp-infos12-250x136.jpg 250w, https:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2019\/04\/eng-e-esp-infos12-700x381.jpg 700w, https:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2019\/04\/eng-e-esp-infos12-120x65.jpg 120w\" sizes=\"auto, (max-width: 1140px) 100vw, 1140px\" \/><\/a><br \/>\nUn estudio llevado a cabo por el peri\u00f3dico <em>Folha de S.Paulo<\/em> con base en el desempe\u00f1o de 252 mil alumnos universitarios en el Examen Nacional de Desempe\u00f1o de Estudiantes (Enade) entre 2014 y 2016, revel\u00f3 que en 33 de las 64 carreras de grado, el rendimiento de los beneficiarios de cupos fue similar o superior al de los no beneficiarios. En tanto, en otras 31 carreras, el promedio fue al menos un 5% inferior. Dentro de ese \u00faltimo grupo hay una concentraci\u00f3n de carreras ligadas a las ciencias exactas. Este punto vulnerable de las acciones afirmativas, que consiste en la precaria capacitaci\u00f3n en matem\u00e1tica entre los egresados de las escuelas p\u00fablicas, inspir\u00f3 la investigaci\u00f3n de doctorado en educaci\u00f3n matem\u00e1tica de Guilherme Henrique Gomes da Silva, concluida en 2016 en la Unesp de Rio Claro. El investigador, actualmente docente de la Universidad Federal de Alfenas (Unifal), en Minas Gerais, se dedic\u00f3 a estudiar el rol de la educaci\u00f3n matem\u00e1tica en las pol\u00edticas de acciones afirmativas al notar que exist\u00eda una carencia en la literatura sobre el tema. \u201cCuando ingres\u00e9 en la Unifal, en 2012, not\u00e9 que hab\u00eda un discurso en la comunidad universitaria, muchas veces prejuicioso, en cuanto a que el \u00edndice de reprobaci\u00f3n, que de por s\u00ed era muy alto en las c\u00e1tedras de matem\u00e1tica de las carreras de ciencias exactas, aumentar\u00eda con el ingreso de beneficiarios de cupos en la red federal\u201d.<\/p>\n<p>Gomes da Silva entrevist\u00f3 a docentes y estudiantes acogidos a ese beneficio en las universidades federales de S\u00e3o Carlos (UFSCar) y del ABC (UFABC) e identific\u00f3 las estrategias de mayor ayuda en el campo de la educaci\u00f3n matem\u00e1tica para la permanencia de los alumnos en la carrera. \u201cVarios alumnos refirieron que el establecimiento de un v\u00ednculo con un docente result\u00f3 fundamental para poder superar las dificultades del primer a\u00f1o y proseguir la carrera\u201d, dice el investigador. Uno de los entrevistados le confi\u00f3 su malestar al preguntarle a un profesor de c\u00e1lculo el significado de un gr\u00e1fico y escuchar como respuesta que dicho contenido se aprend\u00eda en la educaci\u00f3n b\u00e1sica. \u201cEse alumno nunca volvi\u00f3 a hacer una pregunta en el aula\u201d, dice. \u201cLos beneficiarios de cupos son objeto frecuente de microagresiones, que desde\u00f1an su capacidad para mantenerse en carrera en la universidad\u201d. No es casual, seg\u00fan Gomes da Silva, que los alumnos hayan apuntado la importancia de alg\u00fan esquema de apoyo psicol\u00f3gico. Tambi\u00e9n surtieron efecto positivo la concesi\u00f3n de becas de iniciaci\u00f3n a la investigaci\u00f3n cient\u00edfica, que ayudan econ\u00f3micamente a los alumnos y otorgan un sentido m\u00e1s pr\u00e1ctico al aprendizaje, y la conformaci\u00f3n de grupos de estudio de alumnos beneficiarios de cupos, que se ayudan mutuamente.<\/p>\n<p>Uno de los desaf\u00edos principales de las pol\u00edticas de acci\u00f3n afirmativa consiste en asegurar que los alumnos puedan mantenerse econ\u00f3micamente durante su carrera. En la UFABC, que adopt\u00f3 un sistema de cupos a partir de 2006, la mitad de los novatos proviene de escuelas p\u00fablicas y un tercio de ellos est\u00e1 compuesto por autodeclarados negros, mulatos o ind\u00edgenas. Dentro del contingente de los egresados de la educaci\u00f3n p\u00fablica, existe una subreserva del 50% de vacantes para postulantes cuyos ingresos per c\u00e1pita familiares sean de hasta 1,5 salarios m\u00ednimos. \u201cTenemos un universo de alrededor de 2.500 alumnos de bajos ingresos y tan s\u00f3lo 500 becas para asignarles\u201d, dice Fernando Mattos, prorrector de Extensi\u00f3n y Acciones Afirmativas de la UFABC. La Unesp le disputa al gobierno paulista un resarcimiento por una suma de 16,6 millones de reales que lleva gastados este a\u00f1o en programas de permanencia estudiantil con m\u00e1s de mil becas de ayuda para alquileres y 2.791 de ayuda econ\u00f3mica. \u201cEstamos ampliando el acceso de alumnos provenientes de escuelas p\u00fablicas, pero no contamos con los recursos suficientes como para financiar los nuevos costos\u201d, explica M\u00e1rio S\u00e9rgio Vasconcelos, coordinador de permanencia estudiantil de la Unesp.<\/p>\n<blockquote><p>Uno de los principales desaf\u00edos consiste en asegurar que los alumnos puedan sostenerse econ\u00f3micamente durante la carrera<\/p><\/blockquote>\n<p>Las acciones afirmativas se implementaron en un momento de expansi\u00f3n de las vacantes en las universidades del pa\u00eds. El informe intitulado \u201cLas caras de la desi-gualdad en Brasil\u201d, de la Facultad Latinoamericana de Ciencias Sociales (Flacso), identific\u00f3 que el acceso a la educaci\u00f3n superior (que incluye a las carreras de grado, maestr\u00edas y doctorados) aument\u00f3 en toda la sociedad brasile\u00f1a. Este estudio, elaborado con base en datos recabados por la Investigaci\u00f3n Nacional por Muestra de Domicilios (Pnad, por sus siglas en portugu\u00e9s), entre 2002 y 2015, revel\u00f3 que el contingente de j\u00f3venes negros en las universidades p\u00fablicas o privadas creci\u00f3 de 400 mil en 2002 a 1,6 millones en 2015.<\/p>\n<p>Una de las cr\u00edticas recurrentes a las pol\u00edticas afirmativas indica que, si bien se las propone como soluciones temporales, acaban convirti\u00e9ndose en permanentes dado que subsiste la desigualdad que las torna necesarias. Renato Pedrosa, de la Unicamp, recuerda la prohibici\u00f3n de cupos raciales en Estados Unidos por un fallo de la Corte Suprema en 1978: \u201cLas universidades que adoptaban ese tipo de pol\u00edtica retornaron a una situaci\u00f3n de exclusi\u00f3n similar a la que se viv\u00eda antes de dicha experiencia\u201d. No obstante, las instituciones estadounidenses son libres para seleccionar a sus alumnos siguiendo diferentes criterios, tales como el de la diversidad del cuerpo discente o una cierta participaci\u00f3n de alumnos de las escuelas p\u00fablicas de su entorno, principalmente cuando la universidad es p\u00fablica.<\/p>\n<p>La soci\u00f3loga Arabela Campos Oliven, docente de la Universidad Federal de Rio Grande do Sul (UFRGS), actualmente lleva a cabo una investigaci\u00f3n en la cual compara las pol\u00edticas de inclusi\u00f3n de afrodescendientes implementadas en la UFRGS y en la Universidad de Illinois en Urbana-Champaign. En 1968, durante el auge de la lucha por los derechos civiles en Estados Unidos, esa instituci\u00f3n estadounidense lanz\u00f3 un proyecto para atraer a 500 estudiantes negros, el equivalente a un 5% del total de sus alumnos, que en la \u00e9poca tuvo \u00e9xito. Esa iniciativa subsiste hasta hoy, pero ya no logra reclutar a tantos alumnos. \u201cMedio siglo despu\u00e9s, hay una presencia calificada de l\u00edderes negros en la administraci\u00f3n de la universidad, incluso el rector, y hubo un aumento de la cantidad de docentes negros, pero el total de alumnos afroamericanos disminuy\u00f3. Mientras que en 1968 ingresaron 565, en 2014 fueron solamente 356\u201d, dice Campos Oliven.<\/p>\n","protected":false},"excerpt":{"rendered":"El avance de las acciones afirmativas diversifica las formas de ingreso a la educaci\u00f3n superior en Brasil","protected":false},"author":11,"featured_media":283615,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[189],"tags":[295],"coauthors":[98,1600],"class_list":["post-283614","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica-ct","tag-educacion"],"acf":[],"_links":{"self":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/posts\/283614","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/comments?post=283614"}],"version-history":[{"count":1,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/posts\/283614\/revisions"}],"predecessor-version":[{"id":283649,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/posts\/283614\/revisions\/283649"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/media\/283615"}],"wp:attachment":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/media?parent=283614"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/categories?post=283614"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/tags?post=283614"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/coauthors?post=283614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}