{"id":293169,"date":"2019-06-26T15:27:08","date_gmt":"2019-06-26T18:27:08","guid":{"rendered":"https:\/\/revistapesquisa.fapesp.br\/?p=293169"},"modified":"2019-06-26T17:36:46","modified_gmt":"2019-06-26T20:36:46","slug":"ideas-de-muchos-lugares","status":"publish","type":"post","link":"https:\/\/revistapesquisa.fapesp.br\/es\/ideas-de-muchos-lugares\/","title":{"rendered":"Ideas de muchos lugares"},"content":{"rendered":"<div id=\"attachment_293176\" style=\"max-width: 793px\" class=\"wp-caption alignright\"><a href=\"https:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2019\/06\/083_Ao-vencedor-A_261.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-293176 size-full\" src=\"https:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2019\/06\/083_Ao-vencedor-A_261.jpg\" alt=\"\" width=\"783\" height=\"1176\" srcset=\"https:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2019\/06\/083_Ao-vencedor-A_261.jpg 783w, https:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2019\/06\/083_Ao-vencedor-A_261-250x375.jpg 250w, https:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2019\/06\/083_Ao-vencedor-A_261-700x1051.jpg 700w, https:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2019\/06\/083_Ao-vencedor-A_261-120x180.jpg 120w\" sizes=\"auto, (max-width: 783px) 100vw, 783px\" \/><p class=\"wp-caption-text\"><span class=\"media-credits-inline\">Editora 34<\/span><\/a> Cient\u00edficos de diversas \u00e1reas convocados para debatir sobre la obra en el mes de septiembre<span class=\"media-credits\">Editora 34<\/span><\/p><\/div>\n<p>Hace 40 a\u00f1os, el cr\u00edtico literario Roberto Schwarz public\u00f3 el libro intitulado <em>Ao vencedor as batatas: Forma liter\u00e1ria e processo social nos in\u00edcios do romance brasileiro<\/em> (Duas Cidades\/ Editora 34), en el cual polemiza sobre el surgimiento de la novela brasile\u00f1a a partir del an\u00e1lisis de las obras de Jos\u00e9 de Alencar (1829-1877) y Machado de Assis (1839-1908). En el libro, Schwarz ejerce una cr\u00edtica literaria en constante di\u00e1logo con tem\u00e1ticas de las ciencias sociales, haciendo hincapi\u00e9 en la disparidad presente entre la sociedad esclavista brasile\u00f1a y las ideas del liberalismo europeo, el contexto en el que ocurri\u00f3 la g\u00e9nesis de la novela como forma literaria en el siglo XIX. El cr\u00edtico plantea c\u00f3mo difieren las ideas europeas adoptadas en Brasil que se hacen evidentes en las obras de Alencar y de Machado, al sostener que la novela era un lenguaje ajeno a trav\u00e9s del cual quedaba de manifiesto el af\u00e1n de autenticidad de los escritores. \u201cEn el devenir de su reproducci\u00f3n social, Brasil adopta y reproduce incansablemente conceptos europeos, siempre en sentido impropio. En calidad de ello es que las mismas ser\u00e1n objeto y problema a un mismo tiempo para la literatura\u201d, escribe Schwarz en uno de los ensayos incluidos en el libro.<\/p>\n<p>El aniversario de la publicaci\u00f3n de la obra, a la cual se la considera una de las m\u00e1s significativas para la cr\u00edtica literaria y el pensamiento social brasile\u00f1o, fue el tema de un seminario organizado por la Facultad de Filosof\u00eda, Letras y Ciencias Humanas de la Universidad de S\u00e3o Paulo (FFLCH-USP), en el mes de septiembre. Docentes y j\u00f3venes investigadores de las \u00e1reas de letras, filosof\u00eda, sociolog\u00eda y ciencias pol\u00edticas convergieron para debatir la obra.<\/p>\n<p>El c\u00e9lebre texto \u201cLas ideas for\u00e1neas\u201d al comienzo del libro, apunta a dar cuenta de ese desplazamiento, al consignar que, en el Brasil de finales del siglo XIX, las ideas provenientes del universo burgu\u00e9s europeo, entre ellas el trabajo libre y el progreso, se hallaban desacopladas en relaci\u00f3n con su empleo en Europa. El cr\u00edtico escribi\u00f3 ese ensayo durante su exilio en Par\u00eds, adonde se traslad\u00f3 en 1968, cuando la represi\u00f3n impuesta por el gobierno militar brasile\u00f1o se torn\u00f3 m\u00e1s violenta, y regres\u00f3 reci\u00e9n en 1978.<\/p>\n<p>El ensayo, publicado originalmente en la revista <em>Novos Estudos<\/em>, del Centro Brasile\u00f1o de An\u00e1lisis y Planificaci\u00f3n (Cebrap), en 1973, busca explicar lo que signific\u00f3 la adopci\u00f3n de la ideolog\u00eda liberal por la clase dirigente brasile\u00f1a en el siglo XIX. Schwarz adopta el concepto marxista de ideolog\u00eda y afirma que, si el discurso liberal ya entra\u00f1aba un encubrimiento de la realidad europea, aqu\u00ed su sentido era algo m\u00e1s complicado, al fin y al cabo, \u00bfc\u00f3mo podr\u00edan pensarse la \u201clibertad\u201d y las relaciones de trabajo libres en una sociedad orquestada en torno a la esclavitud? \u00bfC\u00f3mo operaban las ideas gestadas en Europa en condiciones materiales y simb\u00f3licas tan diferentes como las brasile\u00f1as? \u201cEn ese contexto, las ideolog\u00edas no describen ni siquiera falsamente la realidad, y no gravitan al comp\u00e1s de una ley que les sea propia, raz\u00f3n por la cual las llamamos de segundo grado\u201d, escribe Schwarz. Cuando menciona el t\u00e9rmino \u201csegundo grado\u201d, el autor parte del precepto de que en Europa, la ideolog\u00eda liberal ya enmascara, en el siglo XIX, la realidad material y las relaciones de clase. Una ideolog\u00eda de segundo grado, en lugar de encubrir y, por lo tanto, enmascarar la opresi\u00f3n, contrariamente servir\u00eda como justificativo directo para la opresi\u00f3n.<\/p>\n<blockquote><p>El cr\u00edtico escribi\u00f3 el c\u00e9lebre ensayo \u201cAs ideias fora do lugar\u201d durante su exilio en Par\u00eds, hacia donde se fue en 1968<\/p><\/blockquote>\n<p>El autor hace hincapi\u00e9 en resaltar un tramo en el ensayo \u201cLas ideas fuera de contexto\u201d, realzando el car\u00e1cter central de su argumentaci\u00f3n, al afirmar: \u201c(&#8230;) una vez adoptadas las ideas y las razones europeas, las mismas pod\u00edan servir y muchas veces sirvieron como justificativo, nominalmente \u2018objetivo\u2019, para el momento de arbitrio que subyace en la naturaleza del favor. Ese segmento se\u00f1ala uno de los temas principales que se tratan en el libro: el \u201cfavor\u201d, un concepto que permite la entrada en escena de Machado de Assis y uno de los momentos en que se combinan la teor\u00eda literaria y la sociolog\u00eda. En <em>Quincas Borba <\/em>(1892), el protagonista principal \u2013Rubi\u00e3o\u2013 recibe una cuantiosa herencia y se aprovecha de ella para vivir repartiendo y negociando agrados reales e imaginarios. Toda la herencia que recibi\u00f3 la dilapida y con ella, tambi\u00e9n desaparece su cordura. Sin embargo, \u00e9l no deja nunca de repetir la m\u00e1xima \u201cal vencedor, las papas\u201d, una frase que va adquiriendo ribetes cada vez m\u00e1s ir\u00f3nicos a lo largo de la narrativa.<\/p>\n<p>Para Schwarz, el protagonista ser\u00eda una expresi\u00f3n de las huellas que deja el trabajo esclavo, no s\u00f3lo en la relaci\u00f3n entre amos y esclavos, sino tambi\u00e9n en el \u00e1mbito del trabajo libre. As\u00ed como en Europa la relaci\u00f3n entre trabajadores libres y burgues\u00eda simula proporcionarles a ambos un grado similar de libertad, ese favor, puesto en pr\u00e1ctica en la periferia del capitalismo (o sea, en Brasil, y Schwarz sugiere sin ahondar, en toda Am\u00e9rica Latina) explica una relaci\u00f3n de trabajo que comporta una dependencia del obrero ante los poderosos, que raramente son burgueses en el sentido europeo del t\u00e9rmino, sino, generalmente, propietarios.<\/p>\n<p>Los ensayos que le siguen al texto inicial del libro de Schwarz se sostienen, cada uno, en los libros de la primera etapa de Machado de Assis: <em>Ressurrei\u00e7\u00e3o<\/em> (1872), <em>A m\u00e3o e a luva <\/em>(1874), <em>Helena <\/em>(1876) y <em>Iai\u00e1 Garcia<\/em> (1878). En estas novelas, el favor interviene directamente en la construcci\u00f3n de la trama, que narra historias o proyectos de progreso social frente a una sociedad que les impone obst\u00e1culos a los m\u00e1s pobres. En tanto, el t\u00edtulo <em>Ao vencedor as batatas<\/em> fue extra\u00eddo de una novela de la etapa posterior de Machado de Assis, cuando los narradores y protagonistas de <em>Mem\u00f3rias p\u00f3stumas de Br\u00e1s Cubas <\/em>(1881), <em>Quincas Borba <\/em>y <em>Dom Casmurro<\/em> (1899), <em>Esa\u00fa e Jac\u00f3<\/em> (1904) y <em>Memorial de Aires <\/em>(1908), pasan a ejercer, con virajes y digresiones, un doble discurso, capaz de defender simult\u00e1neamente el libre mercado y la esclavitud. \u00c9ste es el momento en que el formato social se traduce al formato literario, no como un espejo, sino como una nueva construcci\u00f3n. Las lecturas de aquello que el cr\u00edtico literario denomin\u00f3 como \u201cviraje machadiano\u201d se describen en otros ensayos de su autor\u00eda, especialmente en el libro <em>Um mestre na periferia do capitalismo<\/em> (1990) y en art\u00edculos compilados en <em>Que horas s\u00e3o?<\/em> (1987), <em>Sequ\u00eancias brasileiras <\/em>(1999), <em>Duas meninas <\/em>(1997) y <em>Martinha versus Lucr\u00e9cia <\/em>(2012).<\/p>\n<p>El cr\u00edtico literario Roberto Schwarz naci\u00f3 en Austria y estudi\u00f3 ciencias sociales, entre 1957 y 1960, en la Universidad de S\u00e3o Paulo (USP). \u00c9l fue uno de los participantes m\u00e1s j\u00f3venes de un seminario de debates sobre <em>El capital<\/em>, de Marx, que en 1958 convoc\u00f3 a distintas personalidades del ambiente universitario paulista de varias \u00e1reas, entre los que figuraron Fernando Henrique Cardoso, Fernando Novais, Jos\u00e9 Arthur Giannotti y Paul Singer. M\u00e1s tarde, Schwarz realiz\u00f3 un m\u00e1ster en teor\u00eda literaria y literatura comparada en la Universidad Yale, en Estados Unidos. A su regreso a Brasil, se convirti\u00f3 en asistente de Antonio Candido en el Departamento de Teor\u00eda Literaria de la USP. El doctorado lo hizo en la Universidad Par\u00eds III, en Francia. Uno de los puntos de partida de <em>Ao vencedor as batatas<\/em> justamente fue el rescate cr\u00edtico del proceso hist\u00f3rico elaborado por Candido en el libro <em>Forma\u00e7\u00e3o da literatura brasileira: O estudo das rela\u00e7\u00f5es entre forma liter\u00e1ria e processo social nos in\u00edcios do romance brasileiro<\/em>, que fue publicado en 1959. \u201cQue la literatura forma parte de la sociedad o que se conozca la literatura a trav\u00e9s de la sociedad y la sociedad por intermedio de la literatura, son tesis capitales del siglo XIX, sin las cuales, por cierto, la importancia espec\u00edficamente moderna de la literatura ser\u00eda incomprensible\u201d, <a href=\"https:\/\/revistapesquisa.fapesp.br\/es\/2004\/04\/01\/un-critico-en-la-periferia-del-capitalismo-2\/\" target=\"_blank\" rel=\"noopener noreferrer\">explic\u00f3 Schwarz en una entrevista que le concediera a <em>Pesquisa FAPESP<\/em> en 2004<\/a>.<\/p>\n<blockquote><p>El m\u00e9todo de Schwarz suscit\u00f3 diversas pol\u00e9micas. Una de ellas le atribuye que se inclina m\u00e1s hacia la sociolog\u00eda que a la cr\u00edtica literaria<\/p><\/blockquote>\n<p>\u201cAl abrir el debate para la inclusi\u00f3n de otros libros de Schwarz, el seminario organizado en la FFLCH puso sobre el tapete que, para el autor, la forma art\u00edstica constituye una manera de conocer contradicciones poco obvias de las formas de la experiencia social, y que la producci\u00f3n cultural brasile\u00f1a se encuentra relacionada tanto con los temas locales como globales\u201d, analiza Salete de Almeida Cara, docente de teor\u00eda literaria en la FFLCH-USP.<\/p>\n<p>Las elecciones de Schwarz suscitaron diversas pol\u00e9micas, entre ellas, aqu\u00e9lla que apunta que el autor hace m\u00e1s sociolog\u00eda que cr\u00edtica literaria. Para Jo\u00e3o Cezar de Castro Rocha, docente de literatura comparada de la Universidad del Estado de R\u00edo de Janeiro (Uerj), esta cr\u00edtica se explica por la trayectoria de la disciplina de la cr\u00edtica literaria como posgrado en el pa\u00eds, donde est\u00e1 anclada una visi\u00f3n \u201cfuertemente binaria\u201d con dos corrientes opuestas. Una de ellas prioriz\u00f3 los debates formales y se organiz\u00f3 en torno a la revista <em>Noigandres<\/em> y a los poetas y cr\u00edticos Haroldo y Augusto de Campos. La otra puso de relieve el debate acerca de c\u00f3mo se expresa aquello externo a la obra en la forma literaria. \u201cEl subt\u00edtulo de <em>Ao vencedor as batatas<\/em> es \u2018Forma literaria y proceso social\u2019. Hago hincapi\u00e9 en la \u2018y\u2019 y en el orden de los t\u00e9rminos, no es \u2018proceso social y forma literaria\u2019\u201d, acota De Castro Rocha.<\/p>\n<p>Seg\u00fan el investigador de la Uerj, el \u00e9xito del libro se basa en la superaci\u00f3n, lograda por Schwarz, al pasar de un lugar com\u00fan que era usual en la d\u00e9cada de 1960, cuando comenz\u00f3 a gestarse el libro: la idea de un Machado de Assis ausente, es decir, la percepci\u00f3n de que \u00e9ste no abordaba los asuntos pol\u00edticos y raciales de su \u00e9poca. A partir de Schwarz, Machado de Assis dej\u00f3 entonces de ser \u201cun Luciano de Sam\u00f3sata nacido en el Morro do Livramento\u201d, tal el apelativo que le dio el cr\u00edtico Alfredo Pujol (1865-1930) refiri\u00e9ndose al escritor y humorista nacido en Siria alrededor del a\u00f1o 120 d. C.<\/p>\n<p>Los argumentos de Schwarz no s\u00f3lo generaron pol\u00e9mica en el campo estricto de la teor\u00eda literaria. El profesor de ciencia pol\u00edtica de la USP Bernardo Ricupero, uno de los participantes del seminario que celebr\u00f3 los 40 a\u00f1os de la obra, registr\u00f3 en el art\u00edculo \u201cDe la formaci\u00f3n a la forma. Incluyendo las \u2018ideas for\u00e1neas\u2019\u201d, publicado en la revista <em>Lua Nova<\/em>, que \u201cuno de los planteos m\u00e1s controvertidos, y mal comprendidos, de la cr\u00edtica de la cultura brasile\u00f1a es la de las \u2018ideas fuera de lugar\u2019\u201d. En sinton\u00eda con Ricupero, la fil\u00f3sofa Maria Sylvia Carvalho Franco, docente jubilada de la USP, autora de <em>Homens livres na sociedade escravocrata <\/em>(1977), sostiene \u201cque centro y periferia formar\u00edan parte de un mismo modelo de producci\u00f3n, cooperando en diferentes momentos del proceso de constituci\u00f3n y reproducci\u00f3n del capital\u201d, algo que reducir\u00eda el sentido de pensar al liberalismo como una idea fuera de lugar en Brasil en el tono en que lo hizo el cr\u00edtico.<\/p>\n<p><a href=\"https:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2019\/06\/084-085_Ao-vencedor_261.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"837\" class=\"alignright size-full wp-image-293184\" src=\"https:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2019\/06\/084-085_Ao-vencedor_261.jpg\" alt=\"\" srcset=\"https:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2019\/06\/084-085_Ao-vencedor_261.jpg 1200w, https:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2019\/06\/084-085_Ao-vencedor_261-250x174.jpg 250w, https:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2019\/06\/084-085_Ao-vencedor_261-700x488.jpg 700w, https:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2019\/06\/084-085_Ao-vencedor_261-120x84.jpg 120w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><span class=\"media-credits-inline\">Alexandre Camanho<\/span><\/a><\/p>\n<p>Otra pol\u00e9mica importante surgi\u00f3 entre Schwarz y el tambi\u00e9n cr\u00edtico e historiador de la literatura Alfredo Bosi, autor de <em>Br\u00e1s Cubas em tr\u00eas vers\u00f5es: Estudos machadianos <\/em>(2006). \u201cBosi avala la existencia de diferentes formas de liberalismo a lo largo del siglo XIX brasile\u00f1o que invalidar\u00edan la posibilidad de trazar una ideolog\u00eda uniforme para los estratos dominantes de ese per\u00edodo en Brasil. Hab\u00eda distintas nociones de liberalismo en conflicto, y \u00e9se es el detalle que, seg\u00fan Bosi, se le habr\u00eda pasado por alto a Schwarz\u201d, escribi\u00f3 el soci\u00f3logo Fl\u00e1vio de Rosa Moura en el art\u00edculo \u201cUn cr\u00edtico en el pandemonio\u201d, en la revista <em>Tempo Social<\/em>, en 2011.<\/p>\n<p>En diversas ocasiones, Schwarz intent\u00f3 dar respuesta a las pol\u00e9micas suscitadas. En una de ellas, durante un encuentro en Buenos Aires, en 2009, escribi\u00f3: \u201cBien, est\u00e1 claro que nunca se me ocurri\u00f3 que las ideas en Brasil estuvieran en un sitio equivocado, ni tampoco, por cierto, que se hallaran en el lugar correcto, y mucho menos que yo fuera capaz de corregir su localizaci\u00f3n, como el t\u00edtulo les ha sugerido a muchos lectores\u201d, escribi\u00f3 en el texto \u201cPor qu\u00e9 \u2018ideas fuera de lugar\u2019\u201d, publicado en el libro <em>Martinha versus Lucr\u00e9cia<\/em>. \u201cEl problema del ensayo \u2013al cual el t\u00edtulo alud\u00eda en forma ir\u00f3nica, con distanciamiento brechtiano\u2013 era otro: se trataba de dilucidar las razones hist\u00f3ricas por las cuales las ideas y las formas nuevas, indispensables para la modernizaci\u00f3n del pa\u00eds, causaban no obstante una irrefutable<\/p>\n<div class=\"box\"><strong>El origen de la frase \u201cal vencedor, las papas\u201d<br \/>\n<\/strong><em>En el sexto cap\u00edtulo de <\/em>Quincas Borba<em>, Machado de Assis le da voz al personaje del mismo nombre para que le transmita a su amigo Rubi\u00e3o sus conceptos filos\u00f3ficos<\/em><\/p>\n<p>\u201cPiensa en un campo sembrado de papas y dos tribus hambrientas. Las papas tan s\u00f3lo alcanzan para alimentar a una de las tribus, que as\u00ed cobra fuerzas para cruzar la monta\u00f1a y dirigirse al valle siguiente, donde hay papas en abundancia; pero si las dos tribus se repartieran en paz las papas del campo, no podr\u00edan alimentarse lo suficiente y morir\u00edan de inanici\u00f3n. La paz, en este caso, es sin\u00f3nimo de destrucci\u00f3n; la guerra es la supervivencia. Una de las tribus extermina a la otra y recoge los despojos. De all\u00ed la alegr\u00eda por la victoria, los himnos, las aclamaciones, el reconocimiento p\u00fablico y el resto de las consecuencias de las acciones b\u00e9licas. Si la guerra no fuese eso, no se producir\u00edan tales demostraciones, dado el motivo real de que el hombre s\u00f3lo festeja y ama aquello que le es apacible o provechoso, y por el motivo racional de que nadie santifica una acci\u00f3n que virtualmente la destruye. Al vencido, odio o compasi\u00f3n; al vencedor, las papas\u201d.<\/div>\n","protected":false},"excerpt":{"rendered":"El libro de ensayos <em>Ao vencedor as batatas<\/em>, de Roberto Schwarz, cumple 40 a\u00f1os de debates en varias \u00e1reas del conocimiento","protected":false},"author":633,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[187],"tags":[],"coauthors":[1654],"class_list":["post-293169","post","type-post","status-publish","format-standard","hentry","category-humanidades-es"],"acf":[],"_links":{"self":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/posts\/293169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/users\/633"}],"replies":[{"embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/comments?post=293169"}],"version-history":[{"count":2,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/posts\/293169\/revisions"}],"predecessor-version":[{"id":293569,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/posts\/293169\/revisions\/293569"}],"wp:attachment":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/media?parent=293169"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/categories?post=293169"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/tags?post=293169"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/coauthors?post=293169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}