{"id":324773,"date":"2020-01-22T19:04:39","date_gmt":"2020-01-22T22:04:39","guid":{"rendered":"https:\/\/revistapesquisa.fapesp.br\/?p=324773"},"modified":"2020-01-23T12:39:28","modified_gmt":"2020-01-23T15:39:28","slug":"bajo-la-sombra-de-los-britanicos-2","status":"publish","type":"post","link":"https:\/\/revistapesquisa.fapesp.br\/es\/bajo-la-sombra-de-los-britanicos-2\/","title":{"rendered":"Bajo la sombra de los brit\u00e1nicos"},"content":{"rendered":"<p>Dos expediciones menos conocidas acompa\u00f1aron al equipo brit\u00e1nico en sus observaciones del eclipse de Sol en Sobral, el 29 de mayo de 1919. Una de ellas estaba conformada por brasile\u00f1os, entre los cuales se encontraban L\u00e9lio Gama, Domingos Fernandes da Costa, Allyrio Hugueney de Mattos y Te\u00f3filo Lee. El equipo, encabezado por el astr\u00f3nomo Henrique Charles Morize, director del Observatorio Nacional (ON) de R\u00edo de Janeiro, desembarc\u00f3 en Sobral el 9 de mayo de ese a\u00f1o. El objetivo era realizar observaciones espectrosc\u00f3picas de la corona solar mediante la producci\u00f3n placas fotogr\u00e1ficas similares a las producidas por el equipo de Greenwich. \u201cM\u00e1s que eso\u201d, explica Carlos Veiga, de la Coordinaci\u00f3n de Astronom\u00eda y Astrof\u00edsica del ON, \u201cMorize pretend\u00eda demostrarles a los investigadores extranjeros la calidad cient\u00edfica de los brasile\u00f1os, as\u00ed como de la instituci\u00f3n de la cual era director\u201d.<\/p>\n<p>Los astr\u00f3nomos brasile\u00f1os instalaron sus equipos en una plaza frente a la iglesia de Patroc\u00ednio, distante del lugar reservado a los brit\u00e1nicos. En la actualidad, esa plaza alberga al Museo del Eclipse, inaugurado el 29 de mayo de 1999 con motivo de las celebraciones de los 80 a\u00f1os de la observaci\u00f3n del fen\u00f3meno en dicha ciudad de Cear\u00e1. Desde el a\u00f1o 2014, debido a problemas en sus instalaciones, el museo est\u00e1 cerrado. Su reapertura est\u00e1 prevista para principios de mayo, en v\u00edsperas de las conmemoraciones del centenario del eclipse. La instituci\u00f3n re\u00fane r\u00e9plicas de los planetas y sat\u00e9lites naturales del Sistema Solar, como as\u00ed tambi\u00e9n fotos del evento de 1919 y videos con contenido cient\u00edfico y astron\u00f3mico.<\/p>\n<div class=\"box-lateral\"><strong>Lea m\u00e1s:<\/strong><br \/>\n&#8211; <a href=\"https:\/\/revistapesquisa.fapesp.br\/es\/2020\/01\/22\/cuando-la-luz-se-curvo-2\/\" rel=\"noopener noreferrer\" target=\"_blank\">Cuando la luz se curv\u00f3<\/a><br \/>\n&#8211; <a href=\"https:\/\/revistapesquisa.fapesp.br\/es\/2020\/01\/22\/daniel-kennefick-la-importancia-de-sobral-2\/\" rel=\"noopener noreferrer\" target=\"_blank\">Daniel Kennefick: La importancia de Sobral<\/a><\/div>\n<p>Los brasile\u00f1os tomaron varias placas sucesivamente desde c\u00e1maras acopladas a los telescopios, registrando el Sol y la posici\u00f3n de las estrellas que lo circundaban. Investigadores del ON rescataron y restauraron algunas de dichas placas en 2015. Las mismas, que miden 24 cent\u00edmetros (cm) por 18, y 9 cm por 12, est\u00e1n cubiertas por una emulsi\u00f3n con sales de plata sensibles a la luz. Se las hall\u00f3 en cajas de la biblioteca del ON. Despu\u00e9s de la restauraci\u00f3n, se las digitaliz\u00f3 y se las public\u00f3 en internet (bit.ly\/2D2hxlW).<\/p>\n<p>\u201cDesafortunadamente, no se ha llegado a ninguna conclusi\u00f3n a partir de las im\u00e1genes producidas por los brasile\u00f1os\u201d, dice Veiga. La astronom\u00eda era un campo incipiente en Brasil en aquella \u00e9poca. \u201cNo se lograron las condiciones como para extraer ninguna informaci\u00f3n relevante de las placas producidas, de modo tal que la participaci\u00f3n brasile\u00f1a termin\u00f3 restringi\u00e9ndose al apoyo log\u00edstico del equipo ingl\u00e9s y a algunos mapeos clim\u00e1ticos\u201d, comenta el investigador.<\/p>\n<p>El otro equipo que acompa\u00f1\u00f3 el eclipse en Sobral estaba conformado por los cient\u00edficos Daniel Maynard Wise y Andrew Thomson, del Departamento de Magnetismo Terrestre del Instituto Carnegie en Washington, Estados Unidos. Estudiaron los efectos del eclipse en el campo magn\u00e9tico de la Tierra y la electricidad atmosf\u00e9rica.<\/p>\n","protected":false},"excerpt":{"rendered":"El eclipse visto en Cear\u00e1 tambi\u00e9n se observ\u00f3 en el marco de expediciones cient\u00edficas de Brasil y de Estados Unidos","protected":false},"author":346,"featured_media":322092,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[179],"tags":[274,304],"coauthors":[662],"class_list":["post-324773","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tapa","tag-astronomia-es","tag-fisica-es"],"acf":[],"_links":{"self":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/posts\/324773","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/users\/346"}],"replies":[{"embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/comments?post=324773"}],"version-history":[{"count":3,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/posts\/324773\/revisions"}],"predecessor-version":[{"id":326349,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/posts\/324773\/revisions\/326349"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/media\/322092"}],"wp:attachment":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/media?parent=324773"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/categories?post=324773"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/tags?post=324773"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/coauthors?post=324773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}