{"id":376546,"date":"2021-01-27T14:12:42","date_gmt":"2021-01-27T17:12:42","guid":{"rendered":"https:\/\/revistapesquisa.fapesp.br\/?p=376546"},"modified":"2021-01-27T14:12:42","modified_gmt":"2021-01-27T17:12:42","slug":"el-coronavirus-y-el-cerebro","status":"publish","type":"post","link":"https:\/\/revistapesquisa.fapesp.br\/es\/el-coronavirus-y-el-cerebro\/","title":{"rendered":"El coronavirus y el cerebro"},"content":{"rendered":"<p>Un estudio llevado a cabo por cient\u00edficos de cinco instituciones brasile\u00f1as confirma que el nuevo coronavirus puede infectar a diferentes tipos de c\u00e9lulas cerebrales y, posiblemente, causar da\u00f1os directamente en el cerebro. Los investigadores analizaron im\u00e1genes cerebrales de 81 pacientes con la versi\u00f3n leve de covid-19 y observaron alteraciones significativas en diferentes \u00e1reas de la corteza cerebral, la parte externa del cerebro, responsable de facultades tales como la memoria, la atenci\u00f3n, la conciencia y el lenguaje. En pruebas efectuadas dos meses despu\u00e9s de la infecci\u00f3n, la tercera parte de esos pacientes presentaba s\u00edntomas de problemas neurol\u00f3gicos (dolor de cabeza, alteraciones de la memoria, p\u00e9rdida del olfato) o neuropsiqui\u00e1tricos (ansiedad y depresi\u00f3n). Las autopsias revelaron infecci\u00f3n por Sars-CoV-2 en el cerebro de 5 de los 26 individuos fallecidos a causa del covid-19. En las pruebas de laboratorio, los cient\u00edficos constataron que el virus infecta a las c\u00e9lulas cerebrales, especialmente a los astrocitos, que sostienen y nutren a las neuronas (<em>medRxiv<\/em>, 13 de octubre). Ahora resta confirmar si las alteraciones en la corteza cerebral y en el desempe\u00f1o neurol\u00f3gico son causadas por la presencia del virus en las c\u00e9lulas cerebrales. El estudio estuvo a cargo de equipos de las universidades de Campinas (Unicamp), de S\u00e3o Paulo (USP) en Ribeir\u00e3o Preto y Federal de R\u00edo de Janeiro (UFRJ), y del Instituto D\u2019Or de Pesquisa e Ensino (Idor).<\/p>\n","protected":false},"excerpt":{"rendered":"Un estudio llevado a cabo por cient\u00edficos de cinco instituciones brasile\u00f1as confirma que el nuevo coronavirus puede infectar a diferentes tipos de c\u00e9lulas cerebrales","protected":false},"author":476,"featured_media":376653,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[1670],"tags":[316,319],"coauthors":[786],"class_list":["post-376546","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notas-es","tag-medicina-es","tag-neurociencia-es","keywords-coronavirus-es","keywords-covid-19-es","keywords-sars-cov-2-es"],"acf":[],"_links":{"self":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/posts\/376546","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/users\/476"}],"replies":[{"embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/comments?post=376546"}],"version-history":[{"count":2,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/posts\/376546\/revisions"}],"predecessor-version":[{"id":377147,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/posts\/376546\/revisions\/377147"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/media\/376653"}],"wp:attachment":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/media?parent=376546"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/categories?post=376546"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/tags?post=376546"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/coauthors?post=376546"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}