{"id":444973,"date":"2022-08-01T13:45:34","date_gmt":"2022-08-01T16:45:34","guid":{"rendered":"https:\/\/revistapesquisa.fapesp.br\/?p=444973"},"modified":"2022-08-01T13:45:34","modified_gmt":"2022-08-01T16:45:34","slug":"cientificos-debaten-diversos-medios-de-recompensar-mejor-a-quienes-comparten-datos","status":"publish","type":"post","link":"https:\/\/revistapesquisa.fapesp.br\/es\/cientificos-debaten-diversos-medios-de-recompensar-mejor-a-quienes-comparten-datos\/","title":{"rendered":"Cient\u00edficos debaten diversos medios de recompensar mejor a quienes comparten datos"},"content":{"rendered":"<p>Un texto editorial publicado en abril en la revista <em>Nature<\/em> se\u00f1al\u00f3 una contradicci\u00f3n en las pol\u00edticas de los gobiernos y las agencias de financiaci\u00f3n referentes a la evaluaci\u00f3n acad\u00e9mica y al est\u00edmulo a la compartici\u00f3n de los datos de investigaci\u00f3n. Un cient\u00edfico que pone libremente a disposici\u00f3n la informaci\u00f3n de sus estudios, como es lo que m\u00e1s se promueve en la actualidad, puede ser menos reconocido o recompensado que otro que opta por vedar el acceso a los registros primarios de sus experimentos.<\/p>\n<p>La revista menciona un caso concreto que ella misma difundi\u00f3. Se trata de un estudio publicado el 6 de abril donde se describen los gr\u00e1ficos de los patrones de desarrollo del cerebro, similares a aquellos que registran el peso y la altura de las personas a lo largo de su vida. En el art\u00edculo en cuesti\u00f3n, suscrito por neurocient\u00edficos de las universidades de Cambridge, en el Reino Unido, y de Filadelfia, en Estados Unidos, se utilizaron los registros de alrededor de 120.000 ex\u00e1menes por resonancia magn\u00e9tica vinculados a m\u00e1s de un centenar de estudios de diferentes grupos. Esos datos eran en parte de acceso restringido bajo el argumento de que era necesario proteger la privacidad de los pacientes. Hubo que llegar a acuerdos para poder obtenerlos y analizarlos.<\/p>\n<p>La contradicci\u00f3n queda en evidencia en los cr\u00e9ditos del art\u00edculo. Algunos de los cient\u00edficos que manten\u00edan sus datos reservados y aceptaron cederlos figuran entre los m\u00e1s de 200 coautores del <em>paper<\/em>, mientras que aquellos que pon\u00edan a disposici\u00f3n sus datos sin limitaciones solamente aparecen en los agradecimientos. Es verdad que solo deben firmar los art\u00edculos cient\u00edficos los investigadores que hayan contribuido de manera sustancial a la concepci\u00f3n o a la realizaci\u00f3n de la investigaci\u00f3n; cualquier otro tipo de colaboraci\u00f3n debe figurar en la lista de agradecimientos.<\/p>\n<p>En opini\u00f3n de los editores de la revista <em>Nature<\/em>, la publicaci\u00f3n de art\u00edculos y la disponibilidad de los registros deber\u00edan tener una incidencia similar en los procesos de evaluaci\u00f3n, contrataci\u00f3n y ascenso de los investigadores, con el prop\u00f3sito de estimular esta pr\u00e1ctica. \u201cLas universidades, los grupos de investigaci\u00f3n, las agencias de financiaci\u00f3n y los editores de las revistas deber\u00edan empezar a considerar en conjunto c\u00f3mo otorgar un mayor reconocimiento a los datos abiertos en sus sistemas de evaluaci\u00f3n\u201d, propone el editorial.<\/p>\n<p>Un art\u00edculo publicado en enero en la revista <em>Journal of Medical Internet Research<\/em> por investigadores de las universidades de Lovaina y de Gante, en B\u00e9lgica, tambi\u00e9n puso de manifiesto este descontento de los cient\u00edficos que ponen a disposici\u00f3n sus datos. Para ello entrevistaron a 17 epidemi\u00f3logos que utilizan repositorios financiados por la Uni\u00f3n Europea, quienes refirieron la falta de un est\u00e1ndar en la adjudicaci\u00f3n de autor\u00eda de los art\u00edculos. En algunos casos, firmaron un art\u00edculo solamente por haber facilitado sus datos. En otros, se los incluy\u00f3 en los agradecimientos, con la excusa de que la lista de autores ya era demasiado extensa.<\/p>\n<p>En los \u00faltimos 10 a\u00f1os, las agencias de fomento de la investigaci\u00f3n cient\u00edfica de varios pa\u00edses, entre ellos Estados Unidos, Australia y tambi\u00e9n los europeos, empezaron a exigir que los proyectos que financian contemplen planes de gesti\u00f3n de los datos, para garantizar que se ajusten a los est\u00e1ndares conocidos por el acr\u00f3nimo en ingl\u00e9s Fair (localizables, accesibles, interoperables y reutilizables por colegas). En octubre de 2017, la FAPESP comenz\u00f3 a exigirles a los investigadores que adjunten a sus pedidos de financiaci\u00f3n un plan de gesti\u00f3n de los datos cient\u00edficos, desde su recabado hasta la plataforma en la que quedar\u00e1n disponibles (<a href=\"https:\/\/revistapesquisa.fapesp.br\/es\/los-planes-de-gestion-de-datos-deberan-incorporarse-a-los-proyectos-de-investigacion-en-brasil\/\" target=\"_blank\" rel=\"noopener\"><em>l\u00e9ase en <\/em>Pesquisa FAPESP<em>, edici\u00f3n n\u00ba 260<\/em><\/a>). Estos planes permiten la informaci\u00f3n pueda reutilizarse y confirm\u00e1rsela con mayor facilidad.<\/p>\n<p>La compartici\u00f3n de datos est\u00e1 creciendo, pero en forma desigual. En la \u00faltima d\u00e9cada, la cient\u00edfica de datos estadounidense Carol Tenopir, de la Universidad de Tennessee, en Knoxville (EE. UU.), ha realizado tres investigaciones sobre el tema en las que participaron m\u00e1s de 2.000 cient\u00edficos de diversos pa\u00edses, en las que pudo comprobar que el 96 % de los expertos en medio ambiente y ecolog\u00eda entrevistados estaban dispuestos a proporcionar informaci\u00f3n sobre sus investigaciones, mientras que los psic\u00f3logos y pedagogos mostraron un inter\u00e9s mucho menor. Sin embargo, esa predisposici\u00f3n no siempre se tradujo en acciones. Menos de la mitad de los investigadores depositaron sus datos en repositorios. Entre los recelos que argumentaron sobresalieron el de que los colegas hicieran uso de los registros antes de que los propietarios pudieran analizarlos en profundidad o que su divulgaci\u00f3n infrinja las leyes. Hay una serie de situaciones en que resulta necesario proteger los datos, como aquellas que tienen que ver con la privacidad de los sujetos de la investigaci\u00f3n, intereses comerciales leg\u00edtimos o los riesgos para la seguridad o la salud p\u00fablica. No obstante, incluso en algunas de estas eventualidades, se los puede divulgar parcialmente. En muchos casos, la privacidad de los sujetos de estudio puede preservarse, por ejemplo, excluyendo aquellas indicaciones que puedan llevar a su identificaci\u00f3n.<\/p>\n<p>La preocupaci\u00f3n por recompensar el esfuerzo puesto en la transparencia por los cient\u00edficos no es precisamente una novedad. Fue un \u00edtem destacado en la 6\u00aa Conferencia Mundial sobre Integridad Cient\u00edfica que se celebr\u00f3 en Hong Kong en 2019. En la declaraci\u00f3n divulgada al final del encuentro, una de las recomendaciones fue recompensar mejor a quienes adoptan las pr\u00e1cticas de lo que se denomina ciencia abierta, que promueven la transparencia en la investigaci\u00f3n y el trabajo colaborativo. Varias instituciones est\u00e1n avanzando en tal sentido. La Universidad de Glasgow, en Escocia, estableci\u00f3 criterios de evaluaci\u00f3n que no se limitan a indicadores tales como las citas de art\u00edculos y los premios obtenidos. Sus docentes deben dejar constancia sobre los esfuerzos que realizaron para garantizar la difusi\u00f3n de los datos siguiendo los principios de la ciencia abierta. La Universidad Tecnol\u00f3gica de Delft, en los Pa\u00edses Bajos, ha creado una galer\u00eda en su p\u00e1gina web, que contiene las fotograf\u00edas y perfiles de 70 \u201ccampeones de los datos\u201d, entre los cuales figuran docentes, becarios de posdoctorado, estudiantes y t\u00e9cnicos que gestionan la informaci\u00f3n de sus investigaciones en forma abierta y difunden recomendaciones sobre esa pr\u00e1ctica entre sus colegas.<\/p>\n<p>El bi\u00f3logo molecular Barend Mons, del Centro M\u00e9dico de la Universidad de Leiden, en los Pa\u00edses Bajos, asesor de programas cient\u00edficos de la Uni\u00f3n Europea, advierte que las responsabilidades del uso compartido de datos est\u00e1n demasiado centradas en los individuos y deben ser asumidas por las instituciones en las que estos trabajan. Mons recomienda que las universidades contraten a un experto en preservaci\u00f3n de datos por cada grupo de 20 investigadores. \u201cEl mayor error en el que pueden incurrir las instituciones reside en tratar de entrenar a todos los j\u00f3venes cient\u00edficos para que sean administradores de datos improvisados\u201d, declar\u00f3 a la revista <em>Nature<\/em>.<\/p>\n","protected":false},"excerpt":{"rendered":"De acuerdo con un editorial de la revista <em>Nature<\/em>, la publicaci\u00f3n de art\u00edculos y la oferta de registros de investigaciones deber\u00edan tener un peso similar en los procesos de an\u00e1lisis","protected":false},"author":11,"featured_media":444978,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[178],"tags":[299],"coauthors":[98],"class_list":["post-444973","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-buenas-practicas","tag-etica-es"],"acf":[],"_links":{"self":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/posts\/444973","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/comments?post=444973"}],"version-history":[{"count":2,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/posts\/444973\/revisions"}],"predecessor-version":[{"id":445689,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/posts\/444973\/revisions\/445689"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/media\/444978"}],"wp:attachment":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/media?parent=444973"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/categories?post=444973"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/tags?post=444973"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/coauthors?post=444973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}