{"id":466438,"date":"2023-01-30T23:47:35","date_gmt":"2023-01-31T02:47:35","guid":{"rendered":"https:\/\/revistapesquisa.fapesp.br\/?p=466438"},"modified":"2023-01-31T19:16:12","modified_gmt":"2023-01-31T22:16:12","slug":"universidad-columbia-cae-en-un-ranking-al-corregir-datos-sobrestimados","status":"publish","type":"post","link":"https:\/\/revistapesquisa.fapesp.br\/es\/universidad-columbia-cae-en-un-ranking-al-corregir-datos-sobrestimados\/","title":{"rendered":"Universidad Columbia cae en un <em>ranking<\/em> al corregir datos sobrestimados"},"content":{"rendered":"<p>La Universidad Columbia de Nueva York, admiti\u00f3 que proporcion\u00f3 datos incorrectos sobre el tama\u00f1o de sus cohortes y acreditaciones de su cuerpo docente para el <em>ranking<\/em> que elabora la revista <em>U.S. News &amp; World Report<\/em>, publicado anualmente desde 1983 y utilizado por miles de estudiantes como referencia a la hora de elegir en cu\u00e1les instituciones estadounidenses solicitar\u00e1n su admisi\u00f3n. Seg\u00fan la universidad, se sobrestim\u00f3 el n\u00famero de cursos de grado con menos de 20 alumnos y la cantidad de docentes de dedicaci\u00f3n exclusiva con nivel de doctorado. Al corregirse los datos, la instituci\u00f3n baj\u00f3 del 2\u00ba al 18\u00ba puesto en la clasificaci\u00f3n. \u201cLamentamos profundamente las deficiencias en nuestros informes anteriores y nos comprometemos mejorarlos\u201d, dijo la rectora de la Universidad Columbia, Mary Boyce, seg\u00fan publica el peri\u00f3dico <em>The Washington Post<\/em>. \u201cTodo aquello que no sea la total exactitud de los datos que informamos es incompatible con los est\u00e1ndares de excelencia de Columbia\u201d.<\/p>\n<p>Diversas informaciones sobre la instituci\u00f3n hab\u00edan sido cuestionadas en febrero por Michael Thaddeus, profesor de matem\u00e1tica de la propia universidad y experto en geometr\u00eda algebraica. En un informe publicado en su sitio web, dijo haber detectado otras discrepancias, adem\u00e1s de las que ya hab\u00edan sido reconocidas. Por ejemplo, Columbia indica que su proporci\u00f3n de alumnos por docente es de alrededor de 6 a 1, cuando, seg\u00fan Thaddeus, el n\u00famero oscilar\u00eda entre 8 y 11 a 1. La instituci\u00f3n tambi\u00e9n afirma que desembolsa 3.100 millones de d\u00f3lares por a\u00f1o en gastos de funcionamiento, m\u00e1s que Harvard, Yale y Princeton juntas. Para Thaddeus, esa cifra es inveros\u00edmil. En su momento, la direcci\u00f3n de la universidad neg\u00f3 que la informaci\u00f3n fuera err\u00f3nea. \u201cResulta dif\u00edcil creer que haya sido un error involuntario o una simple cuesti\u00f3n de metodolog\u00eda\u201d, dijo Thaddeus. \u201cEs probable que alguien de la universidad estuviera al tanto de que hab\u00eda una tergiversaci\u00f3n grave. Y si la hab\u00eda, \u00bfqui\u00e9n era?\u201d, indag\u00f3.<\/p>\n<p>El caso ha reavivado el debate al respecto de la exactitud de las clasificaciones universitarias, que tienen en cuenta muchos datos proporcionados por las propias instituciones y deben verificar su validez. El a\u00f1o pasado, Moshe Porat, exdirector de la Escuela de Negocios Fox de la Universidad Temple, en Filadelfia (Pensilvania &#8211; EE. UU.), fue demandado por adulterar la informaci\u00f3n enviada a la misma <em>U.S. News<\/em> referente a los programas de posgrado profesionales MBA (<em>Master in Business Administration<\/em>) de la instituci\u00f3n, tales como la experiencia profesional de los alumnos y la cantidad de estudiantes que cursaban en tiempo parcial (<em>lea en <\/em>Pesquisa FAPESP<em>, edici\u00f3n n\u00ba 304<\/em>). En 2012, el Claremont McKenna College, en Claremont (California \u2013 EE. UU.), reconoci\u00f3 que hab\u00eda proporcionado informaci\u00f3n err\u00f3nea sobre las estad\u00edsticas de admisiones.<\/p>\n","protected":false},"excerpt":{"rendered":"La instituci\u00f3n envi\u00f3 informaci\u00f3n incorrecta sobre el tama\u00f1o de cohortes y sobre las acreditaciones de su cuerpo docente","protected":false},"author":476,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[178],"tags":[299],"coauthors":[786],"class_list":["post-466438","post","type-post","status-publish","format-standard","hentry","category-buenas-practicas","tag-etica-es"],"acf":[],"_links":{"self":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/posts\/466438","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/users\/476"}],"replies":[{"embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/comments?post=466438"}],"version-history":[{"count":3,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/posts\/466438\/revisions"}],"predecessor-version":[{"id":467434,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/posts\/466438\/revisions\/467434"}],"wp:attachment":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/media?parent=466438"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/categories?post=466438"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/tags?post=466438"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/coauthors?post=466438"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}