{"id":517398,"date":"2024-07-12T16:28:27","date_gmt":"2024-07-12T19:28:27","guid":{"rendered":"https:\/\/revistapesquisa.fapesp.br\/?p=517398"},"modified":"2024-07-12T16:28:27","modified_gmt":"2024-07-12T19:28:27","slug":"una-fauna-unica-en-pico-da-neblina","status":"publish","type":"post","link":"https:\/\/revistapesquisa.fapesp.br\/es\/una-fauna-unica-en-pico-da-neblina\/","title":{"rendered":"Una fauna \u00fanica en Pico da Neblina"},"content":{"rendered":"<p>Cerca de la bandera que marca el punto m\u00e1s alto de Brasil, a casi 3.000 metros de altitud en Pico da Neblina, unos investigadores dieron vuelta una piedra y se toparon con un peque\u00f1o sapo de color pardo de unos 2 cent\u00edmetros (cm) de largo. No ten\u00edan ni idea de c\u00f3mo clasificarlo. Unos 1.000 metros m\u00e1s abajo hallaron otro anfibio enigm\u00e1tico entre la hierba. Solo con la secuenciaci\u00f3n gen\u00e9tica pudo explicarse la dificultad para identificar estos hallazgos: pertenecen a dos nuevas familias. De cada una de ellas, por ahora solo se conocen las especies que se encontraron, bautizadas como <em>Neblinaphryne mayeri<\/em> y <em>Caligophryne doylei<\/em>. El primero de estos nombres homenajea al general Sinclair James Mayer, responsable de los contactos entre los proyectos universitarios y el Ej\u00e9rcito de Brasil. \u201cSin \u00e9l no habr\u00eda sido posible nuestra expedici\u00f3n a Pico da Neblina en 2017 ni la siguiente, a Serra do Imeri, en 2022\u201d, relata el zo\u00f3logo Miguel Trefaut Rodrigues, de la Universidad de S\u00e3o Paulo [USP]. La segunda especie hace referencia al libro <em>El mundo perdido<\/em>, del escritor escoc\u00e9s Arthur Conan Doyle (1859-1930). Las familias descritas recientemente pueden ser remanentes de una fauna en gran parte extinta, lo que ha llevado a los cient\u00edficos a calificar a esta regi\u00f3n monta\u00f1osa de la Amazonia como cuna de nuevas especies y tambi\u00e9n museo, porque conserva vestigios del pasado (<em>Molecular Phylogenetics and Evolution<\/em>, 22 de noviembre).<\/p>\n<div id=\"attachment_517365\" style=\"max-width: 1150px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-517365 size-full\" src=\"https:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2024\/05\/RPF-notas-sapos-2024-01-site-1140-1.jpg\" alt=\"\" width=\"1140\" height=\"444\" srcset=\"https:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2024\/05\/RPF-notas-sapos-2024-01-site-1140-1.jpg 1140w, https:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2024\/05\/RPF-notas-sapos-2024-01-site-1140-1-250x97.jpg 250w, https:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2024\/05\/RPF-notas-sapos-2024-01-site-1140-1-700x273.jpg 700w, https:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2024\/05\/RPF-notas-sapos-2024-01-site-1140-1-120x47.jpg 120w\" sizes=\"auto, (max-width: 1140px) 100vw, 1140px\" \/><p class=\"wp-caption-text\"><span class=\"media-credits-inline\">Renato Recoder\u2009\/\u2009USP\u2002| Miguel Trefaut Rodrigues\u2009\/\u2009USP<\/span><em>Neblinaphryne mayeri<\/em> (<em>a la izquierda<\/em>) y <em>Caligophryne doylei<\/em> (<em>la derecha<\/em>): miembros \u00fanicos de las nuevas familias de anfibios<span class=\"media-credits\">Renato Recoder\u2009\/\u2009USP\u2002| Miguel Trefaut Rodrigues\u2009\/\u2009USP<\/span><\/p><\/div>\n","protected":false},"excerpt":{"rendered":"Cient\u00edficos descubren dos nuevas familias de sapos en Pico da Neblina, en el estado brasile\u00f1o de Amazonas","protected":false},"author":476,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[1670],"tags":[278,300,335],"coauthors":[786],"class_list":["post-517398","post","type-post","status-publish","format-standard","hentry","category-notas-es","tag-biologia-es","tag-evolucion","tag-zoologia-es"],"acf":[],"_links":{"self":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/posts\/517398","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/users\/476"}],"replies":[{"embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/comments?post=517398"}],"version-history":[{"count":1,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/posts\/517398\/revisions"}],"predecessor-version":[{"id":517399,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/posts\/517398\/revisions\/517399"}],"wp:attachment":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/media?parent=517398"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/categories?post=517398"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/tags?post=517398"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/coauthors?post=517398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}