{"id":73087,"date":"2001-05-01T10:10:00","date_gmt":"2001-05-01T13:10:00","guid":{"rendered":"http:\/\/revistapesquisa.fapesp.br\/2001\/05\/01\/un-paso-al-frente\/"},"modified":"2015-07-21T16:14:31","modified_gmt":"2015-07-21T19:14:31","slug":"un-paso-al-frente","status":"publish","type":"post","link":"https:\/\/revistapesquisa.fapesp.br\/es\/un-paso-al-frente\/","title":{"rendered":"Un paso al frente"},"content":{"rendered":"<p>Jaboticabal, una ciudad del nordeste paulista cercada de ca\u00f1averales, guarda valiosos secretos en una sala climatizada del campus de la Universidad Estadual Paulista (Unesp), en los estantes de grandes freezers, a 86 grados Celsius bajo cero. Invisibles a los ojos, esos secretos se alojan en cilindros amarillentos de menos de 2 mil\u00edmetros de di\u00e1metro, guardados en peque\u00f1as cajas de acr\u00edlico.<\/p>\n<p>Este material interesa a cient\u00edficos de todo el mundo y atrae la curiosidad de los productores de los ingenios de las cercan\u00edas. Son clones de los genes secuenciados de la ca\u00f1a de az\u00facar (<em>Saccharum officinarum<\/em>) y de cuatro bacterias causantes de plagas agr\u00edcolas (fitopatog\u00e9nicas): la\u00a0<em>Leifsonia xyli<\/em>, que provoca el raquitismo de la ca\u00f1a; la\u00a0<em>Xylella fastidiosa<\/em>, responsable por el amarelinho dos laranjais o veteado cloroso c\u00edtrico; la\u00a0<em>Xanthomonas citri<\/em>, causante del chancro c\u00edtrico; y la\u00a0<em>Xanthomonas campestris<\/em>, que ataca a algunas verduras. \u00c9se es el acervo del\u00a0<em>Brazilian Clone Collection Center<\/em> (BCCCenter), centro de almacenamiento all\u00ed inaugurado en abril \u00faltimo con una inversi\u00f3n de 600 mil d\u00f3lares.<\/p>\n<p><strong>Bacterias hospedadoras<br \/>\n<\/strong>Creado en los moldes del\u00a0<em>American Type Culture Collection<\/em> (ATCC) y del\u00a0<em>Image Consortium<\/em>, de Estados Unidos, el BCCCenter confirma la posici\u00f3n brasile\u00f1a en la elite de la biotecnolog\u00eda. &#8220;Corr\u00edamos el risco de perder todo el trabajo realizado en los \u00faltimos cuatro a\u00f1os de una hora para otra, porque antes de la instalaci\u00f3n del centro los datos estaban en la memoria de las computadoras, pero los clones que conten\u00edan los genes se encontraban estaban en varios laboratorios&#8221;, dice el profesor Jesus Aparecido Ferro, de la Facultad de Ciencias Agrarias y Veterinarias de la Unesp, uno de los coordinadores del centro.<\/p>\n<p>Con capacidad para 1.612.800 clones, el BCCCenter guarda en ocho freezers un total de 65 mil genes, de los cuales 40 mil corresponden a la ca\u00f1a de az\u00facar. Es el mayor banco de genes de la ca\u00f1a en el mundo.<\/p>\n<p>Para obtener todos esos genes \u00fanicos, fue necesario producir 300 mil clones de ca\u00f1a y otros 200 mil de las bacterias fitopatog\u00e9nicas. &#8220;Los genes secuenciados de la planta o de las bacterias&#8221;, relata Ferro, &#8220;son clonados en un segmento de ADN (\u00e1cido desoxirribonucleico, portador del c\u00f3digo gen\u00e9tico) circular llamado vector, que es entonces introducido en linajes de la bacteria\u00a0<em>Escherichia coli<\/em>.&#8221;<\/p>\n<p>&#8220;Estas bacterias&#8221;, prosigue el investigador, &#8220;conteniendo estos genes de otro organismo, se multiplican en gran cantidad; cada bacteria hija carga tambi\u00e9n el gen ex\u00f3geno. As\u00ed, no solo sirven de hospedadoras, sino tambi\u00e9n para aumentar el n\u00famero de copias de los genes, de modo tal que \u00e9stos puedan distribuirse sin p\u00e9rdida del clon original&#8221;.<\/p>\n<p>La clonaci\u00f3n y el almacenamiento se realizan en un \u00e1rea de 300 metros cuadrados, con tres salas. En la primera se encuentra el principal equipamiento: un robot que cost\u00f3 252 mil d\u00f3lares y realiza la manipulaci\u00f3n del material. \u00c9ste opera mediante un brazo mec\u00e1nico de poco m\u00e1s de un metro, instalado en una caja de vidrio de 2 metros cuadrados. Dotado de c\u00e1mara de video, el robot selecciona digitalmente las colonias que contienen los genes: colecta el material y consigue disponer 27 mil genes en duplicado en una membrana de nylon cuadrada &#8211; 22,5 por 22,5 cent\u00edmetros -, el llamado chip de ADN. La ventaja del robot es su capacidad de escoger y pinzar 30 colonias de bacterias por minuto con las agujas situadas en la punta del brazo. De esta manera elimina el riesgo de error humano y acelera el proceso m\u00e1s de 100 veces.<\/p>\n<p>A partir del trabajo del robot, las muestras se organizan en microplacas, cada una con 384 genes, y se guardan en los freezers para que las bacterias conserven su material gen\u00e9tico. &#8220;Solamente en un lugar como \u00e9ste podemos hacer el seguimiento de la evoluci\u00f3n de la multiplicaci\u00f3n de esas bacterias y de cada proceso de la fase de clonaci\u00f3n&#8221;, comenta el profesor Paulo Arruda, de la Universidad Estadual de Campinas (Unicamp), coordinador del proyecto de secuenciamiento de la ca\u00f1a.<\/p>\n<p>Adem\u00e1s de almacenarlos, el centro comercializar\u00e1 los genes con institutos de investigaci\u00f3n y empresas. &#8220;Para tener acceso a los clones&#8221;, explica Ferro, &#8220;debe ser suscrito un T\u00e9rmino de Transferencia de Material Biol\u00f3gico, con el compromiso de utilizar el gen o los genes solamente con fines de investigaci\u00f3n, y de no pas\u00e1rselos a otro investigador. Para el sector privado habr\u00e1 una negociaci\u00f3n aparte, con la participaci\u00f3n de un comit\u00e9 designado por la FAPESP&#8221;. La solicitud podr\u00e1 hacerse v\u00eda Internet, y el pago a trav\u00e9s de tarjetas de cr\u00e9dito.<\/p>\n<p>El precio var\u00eda. Las empresas privadas deben pagar entre 30 y 100 d\u00f3lares por clon. El banco norteamericano cobra entre 32 y 150 d\u00f3lares. Los 60 laboratorios de la red brasile\u00f1a Onsa (Organizaci\u00f3n para el Secuenciamiento y An\u00e1lisis de Nucle\u00f3tidos), creada por la FAPESP, contaban con acceso gratuito a los materiales solicitados. &#8220;Por lo menos 500 clones de la ca\u00f1a y otros 500 de bacterias ya han sido distribuidos entre los integrantes de la red Onsa que generaron esos clones&#8221;, informa Ferro. &#8220;A partir de ahora, esos grupos deber\u00e1n cubrir el costo de mantenimiento y distribuci\u00f3n de los clones solicitados, que ser\u00e1 de 5 d\u00f3lares por clon. Para otros grupos el costo ser\u00e1 mayor, pero menor que el establecido para el sector privado.&#8221;<\/p>\n<p><strong>Autosuficiente<br \/>\n<\/strong>Como la propiedad intelectual es de la FAPESP, los ingresos quedan en el propio centro, que debe y tornarse autosuficiente en tres a\u00f1os, con un presupuesto anual de alrededor de 200 mil reales. Adem\u00e1s de los clones, se vender\u00e1n los chips de ADN, membranas de alta densidad con todos o casi todos los genes de un organismo: en este caso, la ca\u00f1a de az\u00facar o la bacteria fitopatog\u00e9nica. Ferro revela que una multinacional ya ha manifestado inter\u00e9s en los genes de la ca\u00f1a y negocia la compra de los mismos con la FAPESP. Investigadores de Australia est\u00e1n interesados en adquirir membranas de alta densidad contenido los genes de la ca\u00f1a. En Estados Unidos, el chip de ADN cuesta cerca de 2 mil d\u00f3lares y la expectativa es que dicho precio tambi\u00e9n caiga en Brasil.<\/p>\n<p><strong>Inter\u00e9s industrial<br \/>\n<\/strong>El centro guarda tambi\u00e9n una copia de oper\u00f3n, un tramo del genoma que controla la expresi\u00f3n de un conjunto de genes en bacterias: es una copia de una bacteria Xylella que produce una goma similar a la xantana, espesante de alimentos y remedios y lubricante de brocas para la explotaci\u00f3n de petr\u00f3leo. A pedido del equipo del Genoma Xylella, el centro envi\u00f3 un clon de dicho oper\u00f3n a una empresa estadounidense que es una gran productora de goma xantana. La empresa prueba el oper\u00f3n con la bacteria Xanthomonas campestri, la m\u00e1s usada para producir esa goma, mientras que el equipo brasile\u00f1o recibi\u00f3 los linajes de las bacterias y debe efectuar los mismos experimentos, para evaluar si las propiedades del oper\u00f3n y de la goma resultante son de inter\u00e9s industrial.<\/p>\n<p>&#8220;Cuanto m\u00e1s industrias quieran hacer las pruebas, mejor para nosotros&#8221;, dice Arruda. La asociaci\u00f3n es viable porque el grupo paulista ya ha patentado el oper\u00f3n en Estados Unidos. &#8220;Si sale el negocio, estamos hechos&#8221;. Seg\u00fan Arruda, las pruebas culminar\u00edan al final de este a\u00f1o y, si son positivas, pueden hacer que la cooperaci\u00f3n redunde en un acuerdo comercial.<\/p>\n<p>Resta satisfacer la curiosidad de los azucareros vecinos. El BCCCenter es la segunda parte de un proyecto que empez\u00f3 con el secuenciamiento de la ca\u00f1a de az\u00facar y de la bacteria de la plaga amarilla, que causa le p\u00e9rdidas anuales de por 110 millones de reales a la citricultura de S\u00e3o Paulo. Desde 1997, los proyectos de secuenciamiento de la ca\u00f1a y de las bacterias de inter\u00e9s agr\u00edcola consumieron cerca de 40 millones de reales, que la FAPESP financi\u00f3 en asociaci\u00f3n con instituciones privadas, como el Centro de Tecnolog\u00eda de la Copersucar (CTC) y el Fondo de Defensa de la Citricultura (Fundecitrus).<\/p>\n<p><strong>Genomas y aviones<br \/>\n<\/strong>El inter\u00e9s de los socios por los genomas es el mismo: la b\u00fasqueda de mejoras para aumentar la productividad agr\u00edcola con nuevas variedades de plantas, as\u00ed como la reducci\u00f3n de costos en el combate a plagas y enfermedades. &#8220;A partir de la identificaci\u00f3n de la ADN de la planta, podemos saber exactamente cu\u00e1les genes est\u00e1n implicados en la s\u00edntesis de la sacarosa de la ca\u00f1a, cu\u00e1les son los responsables por su crecimiento y cu\u00e1les le otorgan resistencia a las plagas y las sequ\u00edas, entre otros tantos&#8221;, dice Ferro. &#8220;Por eso debemos tener cuidado y saber exactamente en las manos de qui\u00e9n est\u00e1n yendo a parar esos genes&#8221;. Con estos datos en manos, los institutos de investigaci\u00f3n o las empresas podr\u00e1n desarrollar variedades, para que al final lo productores vecinos puedan verse beneficiados.<\/p>\n<p>&#8220;As\u00ed como la instalaci\u00f3n del Instituto Tecnol\u00f3gico de la Aeron\u00e1utica (ITA) en S\u00e3o Jos\u00e9 dos Campos fue fundamental para la creaci\u00f3n de Embraer, en la actualidad una de las mayores fabricantes de aviones del mundo, el centro es testigo de la aptitud que crear\u00e1 las condiciones propicias para dar mayor vigor a la industria de la biotecnolog\u00eda agr\u00edcola&#8221;, dijo Jos\u00e9 Fernando Perez, director cient\u00edfico de la FAPESP, en la inauguraci\u00f3n del BCCCenter. Las inversiones prosiguen: en 2001 el proyecto Genoma recibir\u00e1 m\u00e1s 30 millones de reales. Entre las nuevas investigaciones se encuentra el secuenciamiento de la bacteria\u00a0<em>Schistossoma mansoni<\/em>, que causa la esquistosomosis, y se est\u00e1 estudiando el secuenciamiento del eucalipto.<\/p>\n","protected":false},"excerpt":{"rendered":"La Unesp crea el primer banco para almacenar y distribuir genes de bacterias y de ca\u00f1a de az\u00facar","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[189],"tags":[],"coauthors":[93],"class_list":["post-73087","post","type-post","status-publish","format-standard","hentry","category-politica-ct"],"acf":[],"_links":{"self":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/posts\/73087","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/comments?post=73087"}],"version-history":[{"count":0,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/posts\/73087\/revisions"}],"wp:attachment":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/media?parent=73087"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/categories?post=73087"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/tags?post=73087"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/coauthors?post=73087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}