{"id":73119,"date":"2001-04-01T00:00:00","date_gmt":"2001-04-01T00:00:00","guid":{"rendered":"http:\/\/revistapesquisa.fapesp.br\/2001\/04\/01\/un-rincon-y-un-laptop\/"},"modified":"2016-02-01T15:45:22","modified_gmt":"2016-02-01T17:45:22","slug":"un-rincon-y-un-laptop","status":"publish","type":"post","link":"https:\/\/revistapesquisa.fapesp.br\/es\/un-rincon-y-un-laptop\/","title":{"rendered":"Un rinc\u00f3n y un laptop"},"content":{"rendered":"<p>Una flauta de cuatro agujeros y un\u00a0<em>laptop<\/em>. Eso es lo que el compositor Silvio Ferraz lleva a sus conciertos. Su colega de escenario e investigaci\u00f3n, y tambi\u00e9n compositor, Fernando Iazzetta, llega munido de un d\u00fao no menos peculiar: un berimbau y su computadora port\u00e1til. Los conciertos en cuesti\u00f3n forman parte de la investigaci\u00f3n intitulada\u00a0<em>Ambiente de Composici\u00f3n y Performance Musical con Soporte Tecnol\u00f3gico<\/em>, que ambos investigadores de la Pontificia Universidad Cat\u00f3lica de S\u00e3o Paulo (PUC-SP) realizan con el apoyo de la beca recibida en el marco del Programa de Apoyo a J\u00f3venes Investigadores de la FAPESP.<\/p>\n<p>M\u00e1s all\u00e1 de simplemente estudiar la m\u00fasica hecha con la ayuda de la computadora, los dos investigadores procuraban entender c\u00f3mo la tecnolog\u00eda interfiere en el proceso de creaci\u00f3n. La idea inicial era mucho m\u00e1s ambiciosa: descubrir nuevas formas de componer y de tocar. Otro diferencial de la investigaci\u00f3n es que sale del campo estrictamente te\u00f3rico, realizando verdaderos laboratorios en el lugar en el que la m\u00fasica m\u00e1s interesa: el escenario. &#8220;Adem\u00e1s de estudiar c\u00f3mo el proceso de creaci\u00f3n es alterado por los equipos, intentamos desarrollar interfaces para encontrar nuevas maneras de manejar el sonido&#8221;, explica Ferraz.<\/p>\n<p>Las interfaces son dispositivos programados en la computadora que, o interaccionan con los instrumentos, procesando el sonido emitido por \u00e9stos, o producen ciertos resultados sonoros a partir de comandos digitados en el propio teclado. Tambi\u00e9n pueden disparar m\u00fasicas pregrabadas. Los conciertos utilizan una mezcla de estos tres procedimientos.<\/p>\n<p><strong>Una infinidad de cables<br \/>\n<\/strong>La investigaci\u00f3n -que dur\u00f3 cerca de cuatro a\u00f1os y recibi\u00f3 una beca de aproximadamente 60 mil reales- comenz\u00f3 con el montaje de un &#8220;m\u00f3dulo m\u00f3vil de\u00a0<em>performance<\/em>&#8220;: un conjunto de equipamientos que permit\u00eda la realizaci\u00f3n de conciertos en los cuales las interfaces eran probadas. El m\u00f3dulo est\u00e1 compuesto por dos\u00a0<em>laptops<\/em>, donde se procesa el sonido, cuatro cajas ac\u00fasticas y una infinidad de cables. De acuerdo con Ferraz, el m\u00f3dulo cost\u00f3 cerca de 50 mil reales, pero ese gasto se justifica, puesto que la m\u00fasica electroac\u00fastica brasile\u00f1a a\u00fan enfrenta el problema del alto precio del alquiler de los equipos.<\/p>\n<p>El Laboratorio de Lenguajes Sonoros de la PUC fue utilizado como sede del proyecto. Al comienzo de la investigaci\u00f3n, los compositores trabajaron algunas cuestiones te\u00f3ricas y el resultado de ello fue la producci\u00f3n de 21\u00a0<em>papers<\/em>. Luego construyeron en la computadora, y usando un ambiente de programaci\u00f3n llamado MAX\/MSP, interfaces que permitieran el control y el procesamiento del sonido en presentaciones en vivo. Teor\u00eda y pr\u00e1ctica se unieron en los conciertos. Fueron diez, realizados en festivales de m\u00fasica electroac\u00fastica y en asociaci\u00f3n con artistas de otras \u00e1reas.<\/p>\n<p>&#8220;Los conciertos empezaron siendo &#8216;cerrados&#8217;, con poca interacci\u00f3n&#8221;, cuenta Iazzetta.&#8221; A medida que nuestro dominio de las herramientas avanz\u00f3, pasamos a interactuar en tiempo real, y a usar otros recursos, como la danza y el video&#8221;, completa.<\/p>\n<p><strong>Interacci\u00f3n<br \/>\n<\/strong>&#8220;Lo que pudimos registrar a lo largo de la investigaci\u00f3n fue c\u00f3mo la divisi\u00f3n b\u00e1sica de la m\u00fasica occidental -entre fabricante del instrumento, compositor, instrumentista y oyente- no se aplica a la m\u00fasica electroac\u00fastica&#8221;, explica Ferraz. &#8220;Todos se mezclan en una sola persona&#8221;, completa. De acuerdo con el investigador, este &#8220;nuevo m\u00fasico&#8221; es como un ni\u00f1o, que resuelve agarrar un objeto y llev\u00e1rselo a la boca para intentar extraerle alg\u00fan sonido. Al mismo tiempo en que crea el nuevo instrumento, debe aprender a interactuar con \u00e9ste y componer la m\u00fasica que m\u00e1s se adapte a sus caracter\u00edsticas.<\/p>\n<p>Otro cambio que la investigaci\u00f3n revel\u00f3 fue la concepci\u00f3n de unidad composicional. &#8220;En la escuela de composici\u00f3n, aprendemos a crear una unidad, para que la persona perciba que los sonidos que escuchan forman parte de la misma m\u00fasica&#8221;, dice Ferraz. &#8220;Con la computadora, pude trabajar con sonidos m\u00e1s diversos al mismo tiempo, sin preocuparme con esa unidad&#8221;, agrega. A lo largo del estudio, los investigadores encontraron tambi\u00e9n otras cuestiones vinculadas a la nueva forma de componer y tocar. Iazzetta, por ejemplo, se concentr\u00f3 en la p\u00e9rdida de lo gestual. &#8220;Cuando la m\u00fasica electr\u00f3nica surgi\u00f3, las\u00a0<em>performances<\/em> se resum\u00edan a apretar la tecla\u00a0<em>play<\/em>.&#8221;<\/p>\n<p><strong>Gesto musical<br \/>\n<\/strong>&#8220;A partir de los a\u00f1os 80, cuando los equipamientos pasaron a ser port\u00e1tiles y m\u00e1s r\u00e1pidos, la tecnolog\u00eda fue del estudio al escenario&#8221;, cuenta el investigador. Con las\u00a0<em>performances<\/em> en vivo, el gesto musical tuvo que ser reintroducido. Entretanto, el acto de tocar instrumentos con sonido procesado o en un teclado de computadora no obedece sencillamente a las leyes de la mec\u00e1nica. En un viol\u00edn, por ejemplo, el m\u00fasico sabe que determinada cuerda invariablemente producir\u00e1 ciertos sonidos. Pero en las\u00a0<em>performances<\/em> electroac\u00fasticas, las reglas ya no son tan claras. &#8220;Se crean artificialmente gestos que antes eran naturales, y es necesario crear nuevos gestos para nuevas sonoridades e interfaces&#8221;, subraya Iazzetta.<\/p>\n<p>Otra constataci\u00f3n fue que los programas de composici\u00f3n para computadoras existentes en el mercado utilizan un &#8220;pensamiento composicional&#8221; limitado por las concepciones musicales de las d\u00e9cadas del 50, 60 y 70. Los programas son restrictos por procedimientos tales como la repetici\u00f3n -que se puso de moda a partir del minimalismo de los a\u00f1os 70-, la disposici\u00f3n de sonidos en\u00a0<em>d\u00e9grad\u00e9<\/em> -t\u00e9cnica usada por los compositores de m\u00fasica electr\u00f3nica de la d\u00e9cada del 60-, y la permutaci\u00f3n de frases musicales &#8211; en boga en la d\u00e9cada del 50. &#8220;Adem\u00e1s, los compositores j\u00f3venes est\u00e1n limitados a trabajar con una concepci\u00f3n lineal, en la cual una idea viene despu\u00e9s de la otra, cuando el pensamiento a la hora de componer no fluye de esa manera&#8221;, explica Ferraz.<\/p>\n<p><strong>Mir\u00f3<br \/>\n<\/strong>Para lidiar con ese problema, Ferraz experiment\u00f3 algunos procedimientos que le otorgaran una mayor libertad de actuaci\u00f3n. Una de las ideas fue transponer la t\u00e9cnica del pintor espa\u00f1ol Mir\u00f3 a la composici\u00f3n. Todos los d\u00edas, Ferraz colocaba sonidos aleatoriamente en un secuenciador de sonido, &#8220;de esos que cualquier muchacho tiene en casa&#8221;. &#8220;Como Mir\u00f3, que todos los d\u00edas arrojaba un poco de pintura en la tela, yo creaba un sonido diferente todos los d\u00edas y despu\u00e9s observava ell resultado, como un grafiti&#8221;, dice Ferraz, recordando que solo la computadora -la mismo que puede restringir- permite tales procedimientos.<\/p>\n<p>Los investigadores est\u00e1n ahora iniciando la pr\u00f3xima aventura: estudiar los ambientes ac\u00fasticos. &#8220;Durante esa investigaci\u00f3n, tropezamos con el problema de la difusi\u00f3n de sonido&#8221;, comenta Ferraz. &#8220;Ahora queremos utilizar el espacio para descubrir c\u00f3mo la escrita musical puede cambiar la sensaci\u00f3n de tama\u00f1o de la sala o la localizaci\u00f3n de los instrumentos, por ejemplo&#8221;, completa. La m\u00fasica que enloquece en los clubes nocturnos ha llegado a la Universidad.<\/p>\n<p><strong>El proyecto<br \/>\n<\/strong>Ambiente de Composici\u00f3n y Performance Musical con Soporte Tecnol\u00f3gico\u00a0 (<a href=\"http:\/\/www.bv.fapesp.br\/pt\/auxilios\/3341\/ambiente-de-composicao-e-performance-musical-com-suporte-tecnologico\/\" target=\"_blank\">n\u00ba 96\/05379-0<\/a>);\u00a0<strong>Modalidad\u00a0<\/strong>Apoyo a J\u00f3venes Investigadores; <strong>Coordinador\u00a0<\/strong>Silvio Ferraz &#8211; Pontificia Universidad Cat\u00f3lica de S\u00e3o Paulo; <strong>Inversi\u00f3n\u00a0<\/strong>R$ 44.193,80 y 153.100,00<\/p>\n","protected":false},"excerpt":{"rendered":"C\u00f3mo afecta a la creaci\u00f3n la tecnolog\u00eda de las computadoras","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[187],"tags":[],"coauthors":[93],"class_list":["post-73119","post","type-post","status-publish","format-standard","hentry","category-humanidades-es"],"acf":[],"_links":{"self":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/posts\/73119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/comments?post=73119"}],"version-history":[{"count":0,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/posts\/73119\/revisions"}],"wp:attachment":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/media?parent=73119"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/categories?post=73119"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/tags?post=73119"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/coauthors?post=73119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}