{"id":78519,"date":"2004-08-01T00:00:00","date_gmt":"2004-08-01T00:00:00","guid":{"rendered":"http:\/\/revistapesquisa.fapesp.br\/2004\/08\/01\/si-se-planta-sale-dinero\/"},"modified":"2016-01-28T18:04:27","modified_gmt":"2016-01-28T20:04:27","slug":"si-se-planta-sale-dinero","status":"publish","type":"post","link":"https:\/\/revistapesquisa.fapesp.br\/es\/si-se-planta-sale-dinero\/","title":{"rendered":"Si se planta, sale dinero"},"content":{"rendered":"<p>El historiador franc\u00e9s Fernand Braudel (1902-1985) sol\u00eda contar la historia de la humanidad a trav\u00e9s de los intercambios econ\u00f3micos entre los pueblos. &#8220;Desde siempre ha habido econom\u00edas-mundo, o al menos desde hace mucho tiempo. Como as\u00ed tambi\u00e9n siempre, o al menos desde hace mucho tiempo, ha habido sociedades, civilizaciones, Estados e incluso imperios&#8221;, escribi\u00f3 Braudel en\u00a0<em>El tiempo del mundo<\/em> . Pero, si bien esa econom\u00eda siempre ha regulado los destinos del mundo, hace 500 a\u00f1os se aceler\u00f3. Despu\u00e9s del viaje de Crist\u00f3bal Col\u00f3n a Am\u00e9rica las cosas nunca m\u00e1s fueron iguales. Hombres, enfermedades, animales y plantas superaron la barrera f\u00edsica de la evoluci\u00f3n y saltaron continentes, en barcos comandados por corajosos conquistadores.<\/p>\n<p>Braudel tambi\u00e9n dec\u00eda que despu\u00e9s del descubrimiento de Am\u00e9rica los europeos permanecieron durante un buen tiempo sin saber qu\u00e9 hacer con aquella inmensidad de tierras. Reci\u00e9n en los siglos XVII y XVIII la colonizaci\u00f3n empez\u00f3 a valer. Los intercambios se intensificaron, y se empezaron a formar las ciudades. Y en el esfuerzo por transformar aquellas inh\u00f3spitas tierras en un para\u00edso rentable, equivalente a las Indias, Portugal empez\u00f3 a traer en sus nav\u00edos constantemente \u00e1rboles, semillas, estacas y sabios, conocedores de los secretos de las plantas. La historiadora M\u00e1rcia Mois\u00e9s Ribeiro, ligada al Instituto de Estudios Brasile\u00f1os de la Universidad de S\u00e3o Paulo (IEB\/ USP), estudia ese tiempo de cambios, cuando en la Am\u00e9rica portuguesa se hicieron tentativas de plantar las especias de Oriente: el clavo, el jengibre, la canela y la pimienta.<\/p>\n<p>&#8220;La frecuencia de los contactos entre las colonias portuguesas esparcidas por el mundo, m\u00e1s espec\u00edficamente entre Brasil y Oriente, se intensific\u00f3 a partir de finales del siglo XVII. Como el viaje de Oriente a Portugal era largo, la escala de algunos d\u00edas en Brasil era inevitable. Aun as\u00ed, las autoridades de Lisboa procuraban prohibir la parada, para evitar el contrabando, que acababa produci\u00e9ndose de cualquier manera&#8221;, dice M\u00e1rcia. En 1672, una orden del rey permiti\u00f3 hacer escala en Salvador, Bah\u00eda. Con ello aument\u00f3 la frecuencia de barcos que, provenientes de Oriente, soltaban anclas en Brasil para desembarcar alguna carga, casi siempre ilegalmente, y cargar mercader\u00edas para transportarlas a Europa. &#8220;Este intenso tr\u00e1nsito de embarcaciones permiti\u00f3 la entrada de plantas, especias y g\u00e9neros \u00fatiles en las boticas brasile\u00f1as&#8221;, comenta la investigadora.<\/p>\n<p>Los intercambios entre los continentes comenzaron pocos a\u00f1os despu\u00e9s de que los portugueses desembarcasen en Brasil. &#8220;El cocotero lleg\u00f3 ac\u00e1 m\u00e1s o menos en 1553, a bordo de embarcaciones llegadas desde Cabo Verde, pero procedentes a su vez del Este Asi\u00e1tico. Hoy en d\u00eda este \u00e1rbol es uno de los s\u00edmbolos del pa\u00eds&#8221;, explica la historiadora. En la senda de las palmeras, llegaron a Brasil el mango, la jaca, la canela, el az\u00facar y el algod\u00f3n. Pero, m\u00e1s all\u00e1 del anecdotario de qu\u00e9 plantas vinieron ac\u00e1, la investigaci\u00f3n de M\u00e1rcia se preocupa por analizar el rol del Estado portugu\u00e9s como mediador de las actividades cient\u00edficas inherentes al aprovechamiento de los recursos naturales de las vastas regiones del imperio ultramarino.<\/p>\n<p><strong>Un estudio de la naturaleza<br \/>\n<\/strong>&#8220;Durante el siglo XVIII, el estudio de la naturaleza se justificaba, pues \u00e9sta generaba beneficios para las sociedades. El gobierno metropolitano procuraba conocer todas las especies bot\u00e1nicas, no solamente las de la Am\u00e9rica portuguesa, sino tambi\u00e9n las de otros dominios, a fin de clasificarlas dentro del sistema de Linn\u00e9 y, principalmente, descubrir sus usos medicinales, tecnol\u00f3gicos y alimentarios&#8221;, analiza M\u00e1rcia. Paulatinamente, el gobierno portugu\u00e9s empez\u00f3 a incentivar de manera expl\u00edcita el intercambio de plantas entre los continentes, en una tentativa de diversificar los cultivos y salvar la balanza comercial, que empezaba entonces a preocupar a los gobernantes portugueses.<\/p>\n<p>M\u00e1rcia recupera un estudio pionero de la historiadora Maria Odila da Silva Dias, editado en 1969, que permaneci\u00f3 escondido en la revista del Instituto Hist\u00f3rico y Geogr\u00e1fico Brasile\u00f1o. Intitulado &#8220;Aspectos de la ilustraci\u00f3n en Brasil&#8221;, en dicho trabajo se cuenta que, en 1796, don Rodrigo de Sousa Coutinho, absolutista ilustrado y ministro de Do\u00f1a Maria I, empez\u00f3 una pol\u00edtica de renovaci\u00f3n de la agricultura, con la introducci\u00f3n de nuevas t\u00e9cnicas rurales. Ped\u00eda informes a los gobernadores de las capitan\u00edas sobre los procesos empleados en la preparaci\u00f3n y el cultivo de los g\u00e9neros exportables; ordenaba que se procediese a efectuar relevamientos de plantas aut\u00f3ctonas, que luego ser\u00edan remitidas al reino, y exploraciones mineral\u00f3gicas; promet\u00eda premios a los labradores m\u00e1s industriosos, y trataba de fomentar la introducci\u00f3n del arado y el cultivo de nuevos g\u00e9neros.<\/p>\n<p>Y no solo eso. En el marco de esa pol\u00edtica oficial de promover intercambios de plantas y conocimientos, el gobernador de la capitan\u00eda de S\u00e3o Paulo recib\u00eda &#8220;folletos y memorias sobre los \u00e1rboles azucareros en general, sobre los tipos de az\u00facar fabricados en R\u00edo, sobre el cultivo de la papa, el a\u00f1il, el caf\u00e9, la canela de Goa, el clavo Girofle, la urumbeba; sobre el algodonero, el cultivo del lino y del c\u00e1\u00f1amo; sobre las variedades de quino, al respecto de \u00e1lcalis fijos e iluminados; sobre los m\u00e9todos agr\u00edcolas empleados en Am\u00e9rica del Norte y libros de naturaleza m\u00e1s t\u00e9cnica sobre los procesos de estampado, construcci\u00f3n de edificaciones rurales y preparaci\u00f3n del queso Roquefort; el arte de hacer cola; la preparaci\u00f3n del tabaco; tratados de mineralog\u00eda y sobre el extracto y la preparaci\u00f3n del salitre y estudios de bot\u00e1nica y tratados de medicina&#8221;, escribi\u00f3 Maria Odila.<\/p>\n<p><strong>Peritos orientales<br \/>\n<\/strong>&#8220;Si bien el tema de la naturaleza est\u00e1 recibiendo una mayor atenci\u00f3n por parte de los historiadores brasile\u00f1os y portugueses en las \u00faltimas d\u00e9cadas, nunca estuvo ausente de las preocupaciones de la historiograf\u00eda de cu\u00f1o m\u00e1s tradicional&#8221;, dice la investigadora. Con todo, la mayor parte de los estudios se orienta con mayor intensidad hacia las d\u00e9cadas del 70 y 80 del setecientos, cuando se concret\u00f3 la fundaci\u00f3n de la Academia de Ciencias de Lisboa, con lo que el per\u00edodo que precede a este hecho qued\u00f3 con un d\u00e9ficit de an\u00e1lisis m\u00e1s profundos. Y es precisamente en este per\u00edodo que M\u00e1rcia focaliza su atenci\u00f3n.<\/p>\n<p>De poco servir\u00eda el env\u00edo de plantas a Brasil si con \u00e9l no se importase la tecnolog\u00eda para su cultivo. &#8220;Conciente acerca de la falta de personal habilitado para su manejo en la Am\u00e9rica portuguesa, el gobierno metropolitano se encarg\u00f3 de mandar a Brasil a diversos peritos orientales&#8221;, comenta la investigadora. En uno de estos viajes, en la misma embarcaci\u00f3n que tra\u00eda a don Pedro de Almeida de Portugal, quien acabara de dejar el cargo de virrey de la India, embarc\u00f3 un grupo de goenses con la misi\u00f3n de cumplir las \u00f3rdenes reales de difundir entre los habitantes del Brasil las t\u00e9cnicas de cultivo de plantas orientales.<\/p>\n<p>En otra ocasi\u00f3n, m\u00e1s precisamente, en 1692, una correspondencia an\u00f3nima dirigida al virrey de la India comenta la multiplicaci\u00f3n de los canelos en Bah\u00eda y afirma que no eran de tan buena calidad como los de la India, pues en Brasil faltaban individuos especializados en el cultivo de aquella planta. Otro ejemplo de la importaci\u00f3n de t\u00e9cnicas agr\u00edcolas de la India aparece en la correspondencia intercambiada en 1694 entre el gobierno portugu\u00e9s y el gobernador de Maranh\u00e3o, Francisco de S\u00e1 Menezes. Optimista con respecto a las plantaciones de clavo de la India en Maranh\u00e3o, el rey de Portugal le ordena al gobernador el plant\u00edo de otros cien \u00e1rboles de clavo y determina que siga a rajatabla los consejos de los peritos indios.<\/p>\n<p>M\u00e1rcia descubri\u00f3 incluso cu\u00e1nto ganaban los canarins (nombre asignado en Portugal a los habitantes de Goa venidos al Brasil). &#8220;Ellos recib\u00edan un ordenado de ocho vint\u00e9ns por d\u00eda para realizar diversas tareas, entre ellas ense\u00f1ar el modo correcto de sembrar lino de diversas calidades, transferir las t\u00e9cnicas de beneficiado y encargarse del cultivo de las moreras, que no daban frutos&#8221;, dice la investigadora. Las moreras eran importantes para que los gusanos de seda empezasen a producir.<\/p>\n<p>Preocupado con la baja producci\u00f3n de las moreras, Diogo de Mendon\u00e7a Corte Real, a la saz\u00f3n gobernador de Bah\u00eda, mencion\u00f3 el problema ante el virrey de Brasil, conde de Atouguia, y atribuy\u00f3 aquella situaci\u00f3n tambi\u00e9n a la falta de gente especializada en Brasil, lo que solamente podr\u00eda resolverse con el auxilio de gente que tuviera &#8220;inteligencia en el cultivo de estos \u00e1rboles&#8221;. Aunque el gobierno de Don Jo\u00e3o V (1706-1750) fue signado por la importaci\u00f3n de especies asi\u00e1ticas a la Am\u00e9rica portuguesa, fue Don Jos\u00e9 (1750-1777) quien m\u00e1s incentiv\u00f3 este tipo de pr\u00e1ctica.<\/p>\n<p><strong>Adaptaci\u00f3n<br \/>\n<\/strong>Para que las plantas pudieran adaptarse en Brasil, el gobierno portugu\u00e9s cont\u00f3 con la ayuda de un poderoso aliado: la Iglesia Cat\u00f3lica. Por todo el territorio brasile\u00f1o exist\u00edan estaciones experimentales, donde los jesuitas adaptaban las plantas. Una de \u00e9stas se torn\u00f3 m\u00e1s conocida, tanto por la cantidad de cartas que recib\u00eda de hacendados preocupados con las plagas y hormigas como por la cantidad de jesuitas sabios que all\u00ed viv\u00edan. Era la llamada Quinta do Tanque, y quedaba en el interior de Bah\u00eda.<\/p>\n<p>&#8220;Los jesuitas fueron importantes agentes del proceso de transmisi\u00f3n del saber m\u00e9dico y bot\u00e1nico por los diversos puntos del Imperio portugu\u00e9s. A trav\u00e9s de las cartas, una especie de informe de las actividades desarrolladas por los ignacianos, y de las farmacopeas, la colecci\u00f3n de recetas de remedios, la Compa\u00f1\u00eda de Jes\u00fas funcion\u00f3 como un nexo entre los diversos pueblos del Imperio colonial portugu\u00e9s en lo que se refiere al cultivo y a la pr\u00e1ctica cient\u00edfica&#8221;, explica la investigadora.<\/p>\n<p>Al invertir en Am\u00e9rica, Portugal intentaba compensar econ\u00f3micamente la p\u00e9rdida de las especias de Oriente. Pero el pa\u00eds termin\u00f3 acert\u00e1ndole a un blanco al que no apuntaba. Merced a ese incentivo comercial, el cultivo de drogas de la India en Brasil contribuy\u00f3 a promover la circulaci\u00f3n de una cultura cient\u00edfica entre sus diferentes dominios de ultramar: la aventura de las plantas por el mundo, como suele decir la investigadora.<\/p>\n<p>&#8220;El esp\u00edritu expansionista se asentaba sobre principios contradictorios. Por una parte era \u00e1vido de novedades, ansioso por develar la diversidad del mundo, pero, por otra parte, era dominado por la tradici\u00f3n que lo llevaba a encuadrar lo desconocido en los c\u00e1nones ya familiares&#8221;, explica M\u00e1rcia. El conocimiento de estos saberes nos ayuda a entender la mentalidad cient\u00edfica de la \u00e9poca y a comprender el rol fundamental asumido por los portugueses, como transportadores primarios y secundarios en la difusi\u00f3n global de plantas.<\/p>\n<p><strong>El Proyecto<\/strong><br \/>\nLos Periplos de Ultramar: la Circulaci\u00f3n del Conocimiento Cient\u00edfico en el Imperio Colonial Portugu\u00e9s &#8211; 1650-1800\u00a0(<a href=\"http:\/\/www.bv.fapesp.br\/pt\/bolsas\/90363\/jornadas-no-ultramar-a-circulacao-do-conhecimento-cientifico-no-imperio-colonial-portugues-1650-18\/\" target=\"_blank\">n\u00ba 02\/04400-9<\/a>);\u00a0<strong>Modalidad <\/strong>Programa Joven Investigador\/FAPESP;\u00a0<strong>Becaria\u00a0<\/strong>M\u00e1rcia Mois\u00e9s Ribeiro &#8211; Instituto de Estudios Brasile\u00f1os\/USP<\/p>\n","protected":false},"excerpt":{"rendered":"Luego de perder sus fuentes de Oriente los portugueses recuperaron especias","protected":false},"author":191,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[187],"tags":[],"coauthors":[506],"class_list":["post-78519","post","type-post","status-publish","format-standard","hentry","category-humanidades-es"],"acf":[],"_links":{"self":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/posts\/78519","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/users\/191"}],"replies":[{"embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/comments?post=78519"}],"version-history":[{"count":0,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/posts\/78519\/revisions"}],"wp:attachment":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/media?parent=78519"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/categories?post=78519"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/tags?post=78519"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/coauthors?post=78519"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}