{"id":93358,"date":"2013-01-17T21:38:51","date_gmt":"2013-01-17T23:38:51","guid":{"rendered":"http:\/\/revistapesquisa.fapesp.br\/?p=93358"},"modified":"2015-05-12T18:15:06","modified_gmt":"2015-05-12T21:15:06","slug":"redacci%c3%b3n-cient%c3%adfica","status":"publish","type":"post","link":"https:\/\/revistapesquisa.fapesp.br\/es\/redacci%c3%b3n-cient%c3%adfica\/","title":{"rendered":"Redacci\u00f3n cient\u00edfica"},"content":{"rendered":"<p>Un sitio <em>web<\/em> que otorga acceso a art\u00edculos, pistas y reflexiones para la redacci\u00f3n de art\u00edculos cient\u00edficos fue presentado por el zo\u00f3logo Gilson Volpato, autor\u00a0 de siete libros sobre el tema y docente en el Instituto de Biociencias de Botucat\u00fa, de la Universidad Estadual Paulista (Unesp). La direcci\u00f3n <a href=\"http:\/\/www.gilsonvolpato.com.br\/\">www.gilsonvolpato.com.br<\/a> incluye secciones de Ciencia, Redacci\u00f3n cient\u00edfica, Publicaci\u00f3n cient\u00edfica, \u00c9tica y moral en la ciencia, Sociedad, Administraci\u00f3n y Educaci\u00f3n.<\/p>\n<p>En cada una de ellas hay una lista de libros relacionados con el tema, art\u00edculos, una serie de enlaces a textos externos &#8211; con comentarios del autor &#8211; adem\u00e1s de sugerencias. Tambi\u00e9n se brindar\u00e1 acceso a las clases <em>online<\/em> del curso de Bases Te\u00f3ricas para la Redacci\u00f3n Cient\u00edfica, dictado por Volpato en la Unesp. \u201cPor el momento existen 19 clases disponibles, aunque todo el material ya ha sido grabado. En corto plazo, la totalidad de las 44 clases se hallar\u00e1n disponibles\u201d, expres\u00f3 el profesor a <em>Ag\u00eancia FAPESP.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"Redacci\u00f3n cient\u00edfica","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[184],"tags":[],"coauthors":[93],"class_list":["post-93358","post","type-post","status-publish","format-standard","hentry","category-estrategias-es"],"acf":[],"_links":{"self":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/posts\/93358","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/comments?post=93358"}],"version-history":[{"count":0,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/posts\/93358\/revisions"}],"wp:attachment":[{"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/media?parent=93358"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/categories?post=93358"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/tags?post=93358"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/es\/wp-json\/wp\/v2\/coauthors?post=93358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}