{"id":120159,"date":"2013-06-04T17:50:41","date_gmt":"2013-06-04T20:50:41","guid":{"rendered":"http:\/\/revistapesquisa.fapesp.br\/?p=120159"},"modified":"2013-06-05T17:07:37","modified_gmt":"2013-06-05T20:07:37","slug":"des-avions-plus-silencieux","status":"publish","type":"post","link":"https:\/\/revistapesquisa.fapesp.br\/fr\/des-avions-plus-silencieux\/","title":{"rendered":"Des avions plus silencieux"},"content":{"rendered":"<p><em>Publi\u00e9 en janvier 2009<\/em><\/p>\n<div id=\"attachment_120522\" style=\"max-width: 226px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-120522\" alt=\"Avions au-dessus de S\u00e3o Paulo: moins de bruit dans le futur\" src=\"http:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2013\/06\/Embraer_ceu.jpg\" width=\"216\" height=\"323\" \/><p class=\"wp-caption-text\"><span class=\"media-credits-inline\"> MIGUEL BOYAYAN<\/span>Avions au-dessus de S\u00e3o Paulo: moins de bruit dans le futur<span class=\"media-credits\"> MIGUEL BOYAYAN<\/span><\/p><\/div>\n<p>Le trafic a\u00e9rien mondial a augment\u00e9 de mani\u00e8re continue au cours de ces derni\u00e8res d\u00e9cennies et va poursuivre cette trajectoire. L\u2019Association Internationale de Transport A\u00e9rien (Iata) estime que le nombre de voyageurs atteindra les 2,75 milliards en 2011 (pour 2,13 milliards d\u00e9but 2007). Un des enjeux de l\u2019industrie a\u00e9ronautique, pour \u00e9voluer sans porter pr\u00e9judice \u00e0 la qualit\u00e9 de vie dans les villes, sera de projeter et de mettre au point des avions plus silencieux qui pourront op\u00e9rer dans les a\u00e9roports sans incommoder les personnes vivant aux alentours. Ce besoin est encore plus urgent suite aux nouvelles exigences de la Federal Aviation Administration (FAA), organe r\u00e9gulateur du secteur a\u00e9rien \u00e9tasunien, qui limitent encore plus l\u2019\u00e9mission de bruits a\u00e9riens dans les a\u00e9roports et qui doivent entrer en vigueur \u00e0 partir de 2015.<\/p>\n<p>Embraer, troisi\u00e8me constructeur mondial d\u2019avions, a r\u00e9cemment lanc\u00e9 un vaste projet appel\u00e9 Avion Silencieux pour respecter ces nouvelles exigences et rester comp\u00e9titif sur le march\u00e9 mondial. Il s\u2019agit d\u2019une \u00e9tude a\u00e9roacoustique visant \u00e0 identifier les bruits propag\u00e9s par leurs mod\u00e8les. Ces donn\u00e9es permettront de mettre au point des syst\u00e8mes en ing\u00e9nierie qui rendront les avions plus silencieux. \u00abDans les grandes villes le volume sonore des avions vient juste apr\u00e8s celui des voitures\u00bb, d\u00e9clare l\u2019ing\u00e9nieur Micael Gianini Valle do Carmo, responsable du projet Embraer. \u00abCette \u00e9tude portant sur les bruits externes de nos avions est n\u00e9e il y a quelques ann\u00e9es avec les projets des mod\u00e8les d\u2019avions \u00e0 r\u00e9action Embraer 170\/190, beaucoup plus grands que ceux fabriqu\u00e9s pr\u00e9c\u00e9demment\u00bb. Le programme se focalise sur les bruits a\u00e9rodynamiques cr\u00e9\u00e9s par le flux d\u2019air qui passe autour des ailes et du fuselage de l\u2019avion. Ce projet est cofinanc\u00e9 par la FAPESP, \u00e0 travers le programme Recherche en Partenariat pour l\u2019innovation technologique (Pite), et par Embraer pour un montant de 11 millions de R$ sur 3 ans.<\/p>\n<p>Les progr\u00e8s technologiques de ces derni\u00e8res ann\u00e9es ont rendu les moteurs d\u2019avion plus silencieux, mettant ainsi en \u00e9vidence les bruits a\u00e9rodynamiques. Au cours de l\u2019atterrissage, 75 % \u00e0 80 % des bruits produits par les avions sont d\u2019origine a\u00e9rodynamique et le reste est provoqu\u00e9 par le moteur. Au d\u00e9collage, quand l\u2019avion a besoin de plus de puissance pour prendre son envol, ce rapport s\u2019inverse. \u00abLes principales sources de bruits a\u00e9rodynamiques \u00e0 l\u2019atterrissage et au d\u00e9collage sont le train d\u2019atterrissage et les surfaces hypersustentatrices, nom donn\u00e9 \u00e0 l\u2019ensemble form\u00e9 par l\u2019aile, les volets et les becs (flaps et slats), dispositifs mobiles plac\u00e9s sur les ailes qui permettent d\u2019augmenter la surface portante de l\u2019avion. Le bruit est caus\u00e9 par des tourbillons d\u2019air et par les fluctuations de pressions sur ces points\u00bb, d\u00e9clare l\u2019ing\u00e9nieur Julio Romano Meneghini, professeur \u00e0 l\u2019\u00c9cole Polytechnique de l\u2019Universit\u00e9 de S\u00e3o Paulo (USP) et coordonnateur g\u00e9n\u00e9ral du projet.<\/p>\n<p>Outre l\u2019\u00c9cole Polytechnique, cinq autres centres d\u2019enseignement et de recherche br\u00e9siliens et quatre centres \u00e9trangers travaillent sur ce programme. Il s\u2019agit de l\u2019\u00c9cole d\u2019Ing\u00e9nierie de S\u00e3o Carlos de USP, de l\u2019Universit\u00e9 F\u00e9d\u00e9rale de Santa Catarina (UFSC), de l\u2019Universit\u00e9 de Bras\u00edlia (UnB), de l\u2019Institut Technologique A\u00e9ronautique (ITA), de l\u2019Universit\u00e9 F\u00e9d\u00e9rale d\u2019Uberl\u00e2ndia (UFU), de l\u2019Universit\u00e9 de Twente, en Hollande, de l\u2019Imperial College et l\u2019Universit\u00e9 de Southampton en Angleterre et du Centre A\u00e9rospatial Germanique DLR en Allemagne. Les chercheurs ont l\u2019intention d\u2019aborder le probl\u00e8me sous 3 angles diff\u00e9rents mais compl\u00e9mentaires en termes a\u00e9roacoustiques comme les essais en vol et en soufflerie, les mod\u00e8les analytiques, empiriques et a\u00e9roacoustiques informatis\u00e9s. Cette derni\u00e8re approche sera \u00e9tudi\u00e9e au Centre de Dynamique des Fluides (NDF) de l\u2019\u00c9cole Polytechnique de l\u2019USP, qui recevra un superordinateur compos\u00e9 de plus de 1.200 unit\u00e9s centrales de traitement (CPU) et d\u2019une m\u00e9moire de 2,5 t\u00e9raoctets, le tout financ\u00e9 par le projet. \u00abNous allons modeler et simuler num\u00e9riquement l\u2019\u00e9coulement d\u2019air autour des surfaces hypersustentatrices et du train d\u2019atterrissage. Cette simulation nous permettra de comprendre les structures des tourbillons (sillage) et nous pourrons ainsi \u00e9valuer les bruits g\u00e9n\u00e9r\u00e9s par ces surfaces\u00bb, d\u00e9clare Meneghini. \u00abAvec l\u2019aide du superordinateur, l\u2019un des plus performants du pays, nous allons concr\u00e8tement comprendre le ph\u00e9nom\u00e8ne complexe associ\u00e9 au bruit a\u00e9rodynamique et proposer ensuite des modifications \u00e0 Embraer en mati\u00e8re de g\u00e9om\u00e9trie des ailes, des volets, des becs et du train d\u2019atterrissage, etc.\u00bb, dit-il.<\/p>\n<p>La partie exp\u00e9rimentale du programme se d\u00e9roulera sur la piste de l\u2019unit\u00e9 d\u2019Embraer situ\u00e9e dans la commune de Gavi\u00e3o Peixoto, dans l\u2019\u00e9tat de S\u00e3o Paulo. Son objectif sera d\u2019identifier les sources de bruit a\u00e9rodynamique pour les quantifier. Pour obtenir ces informations, 256 microphones seront plac\u00e9s sur une zone de 50 m\u00e8tres sur 50 \u00e0 l\u2019une des extr\u00e9mit\u00e9s de la piste afin de capter le bruit produit par les avions qui se poseront et d\u00e9colleront de nombreuses fois. Ce nombre de microphones est n\u00e9cessaire car le bruit propag\u00e9 par les avions est tr\u00e8s complexe. \u00abGr\u00e2ce au traitement des donn\u00e9es acoustiques, nous pourrons respectivement connaitre le pourcentage sonore attribu\u00e9 aux volets, au train d\u2019atterrissage, aux becs, etc.\u00bb, souligne Meneghini. Selon le chercheur, les r\u00e9sultats de ces essais permettront, entre autres, de mettre au point des kits de r\u00e9duction de bruit a\u00e9rodynamique qui seront plac\u00e9s \u00e0 des endroits sp\u00e9cifiques de l\u2019avion. Cette partie du travail d\u00e9pendra de l\u2019UFSC et de l\u2019\u00c9cole d\u2019Ing\u00e9nierie de S\u00e3o Carlos. \u00abNous serons responsables du d\u00e9veloppement d\u2019outils exp\u00e9rimentaux et du diagnostic des sources de bruit des avions\u00bb, d\u00e9clare le professeur C\u00e9sar Jos\u00e9 Deschamps, du D\u00e9partement d\u2019Ing\u00e9nierie M\u00e9canique de l\u2019UFSC. \u00abNous allons \u00e9galement r\u00e9aliser des \u00e9tudes pour comprendre le bruit a\u00e9ronautique d\u2019un point de vue plus th\u00e9orique et ainsi utiliser les meilleures m\u00e9thodologies pour le pr\u00e9voir. Nous pourrons ainsi proposer des modifications pour les futurs avions d\u2019Embraer\u00bb, d\u00e9clare Deschamps.<\/p>\n<p>L\u2019Universit\u00e9 de Bras\u00edlia (UnB) est charg\u00e9e d\u2019un autre aspect du projet concernant l\u2019\u00e9tude des bruits cr\u00e9\u00e9s par la turbine. La turbine est un type d\u2019h\u00e9lice muni de nombreuses pales, c\u2019est la seconde source de bruit des syst\u00e8mes propulsifs des avions, la premi\u00e8re \u00e9tant le jet d\u2019air chaud expuls\u00e9 par la turbine. Bien qu\u2019Embraer ne fabrique pas les moteurs de ses avions (ils sont fournis par l\u2019entreprise am\u00e9ricaine General Electric), elle s\u2019int\u00e9resse \u00e0 ce type de bruit car elle fabrique la nacelle, structure m\u00e9tallique qui re\u00e7oit le moteur turbofan. \u00abLa nacelle est la premi\u00e8re ligne de front contre les bruits du moteur\u00bb, annonce le professeur Roberto Bobenrieth Miserda, de l\u2019Institut de Technologie de l\u2019UnB.<\/p>\n<p>Selon Julio Meneghini, les institutions \u00e9trang\u00e8res impliqu\u00e9es dans le programme jouent un r\u00f4le important. L\u2019Universit\u00e9 de Twente, en Hollande, fournira une soufflerie pour les essais a\u00e9roacoustiques. L\u2019Universit\u00e9 de Southampton et l\u2019Imperial College, en Angleterre, mettront leurs comp\u00e9tences au service de la mise au point de mod\u00e8les analytiques simplifi\u00e9s et de simulateurs \u00abIls poss\u00e8dent une longue exp\u00e9rience dans ce domaine et utiliseront ces mod\u00e8les empiriques pour calculer les estimations en termes de bruit\u00bb, d\u00e9clare Meneghini. Des \u00e9changes entre des \u00e9tudiants br\u00e9siliens, hollandais et anglais sont \u00e9galement pr\u00e9vus.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-120523\" alt=\"Les r\u00e9gions des ailes et du train d\u00b4atterrissage sont les principales sources de bruit des avions\" src=\"http:\/\/revistapesquisa.fapesp.br\/wp-content\/uploads\/2013\/06\/art3751img11.jpg\" width=\"299\" height=\"199\" \/><span class=\"media-credits-inline\">EMBRAER <\/span>Le projet Avion Silencieux qui favorisera l\u2019avanc\u00e9e th\u00e9orique de m\u00e9thodologies et la cr\u00e9ation d\u2019outils pour comprendre les ph\u00e9nom\u00e8nes a\u00e9roacoustiques, contribuera \u00e9galement \u00e0 la formation de ressources humaines sp\u00e9cialis\u00e9es dans ce domaine, car il y a peu de professionnels br\u00e9siliens sp\u00e9cialis\u00e9s en a\u00e9roacoustique. Une partie des fonds du programme sera donc destin\u00e9e au financement de bourses d\u2019initiation scientifique, de ma\u00eetrise, de doctorat et de post-doctorat pour des \u00e9l\u00e8ves impliqu\u00e9s dans des recherches li\u00e9es au programme. \u00abNous voulons cr\u00e9er un centre de comp\u00e9tences dans le domaine acoustique et former des sp\u00e9cialistes hautement qualifi\u00e9s au profit de l\u2019industrie a\u00e9ronautique\u00bb, souligne l\u2019ing\u00e9nieur Deschamps, de l\u2019UFSC. Actuellement, une partie des \u00e9tudes et de l\u2019\u00e9valuation des niveaux sonores externes des avions d\u2019Embraer est r\u00e9alis\u00e9e par des consultants internationaux, avec certaines difficult\u00e9s, comme une r\u00e9ponse tardive aux situations critiques. On estime qu\u2019environ 40 \u00e9tudiants participeront au projet, outre les 25 chercheurs d\u2019Embraer et des universit\u00e9s.<\/p>\n<p>Des programmes identiques \u00e0 ceux financ\u00e9s par la FAPESP et Embraer sont en train d\u2019\u00eatre d\u00e9velopp\u00e9s par des entreprises et des institutions de recherches a\u00e9rospatiales aux \u00c9tats-Unis et en Europe. La NASA (agence spatiale nord-am\u00e9ricaine) par exemple, d\u00e9veloppe le projet Quiet Aircraft Technology (QAT), dont l\u2019objectif est de r\u00e9duire les bruits des avions de moiti\u00e9 d\u2019ici 10 ans et de 75 % d\u2019ici 25 ans. On estime que les premiers avions qui utiliseront certaines des avanc\u00e9es du QAT seront fabriqu\u00e9s \u00e0 partir de 2010. Un autre programme am\u00e9ricain appel\u00e9 Advanced Subsonic Technology (une collaboration entre la NASA, le gouvernement f\u00e9d\u00e9ral et le secteur priv\u00e9) vise \u00e0 mettre au point des dispositifs de r\u00e9duction de bruit de 20 d\u00e9cibels d\u2019ici 2020, par rapport aux technologies utilis\u00e9es en 1997. C\u2019est un objectif os\u00e9 qui, s\u2019il se concr\u00e9tise, repr\u00e9sentera une r\u00e9duction d\u2019environ 20 % des bruits g\u00e9n\u00e9r\u00e9s par un Boeing 777 au cours de l\u2019atterrissage, sur les 100 d\u00e9cibels qu\u2019il produit actuellement. La Communaut\u00e9 Europ\u00e9enne sponsorise \u00e9galement le projet th\u00e9matique Silence(R) avec la collaboration de 51 entreprises et de 14 pays pour un budget de plus de 110 millions d\u2019euros. Son objectif est de valider des technologies visant \u00e0 atteindre une r\u00e9duction de six d\u00e9cibels pour des avions plus silencieux.<\/p>\n<p><!--[if gte mso 9]><xml>\n<w:WordDocument>\n<w:View>Normal<\/w:View>\n<w:Zoom>0<\/w:Zoom>\n<w:TrackMoves\/>\n<w:TrackFormatting\/>\n<w:HyphenationZone>21<\/w:HyphenationZone>\n<w:PunctuationKerning\/>\n<w:ValidateAgainstSchemas\/>\n<w:SaveIfXMLInvalid>false<\/w:SaveIfXMLInvalid>\n<w:IgnoreMixedContent>false<\/w:IgnoreMixedContent>\n<w:AlwaysShowPlaceholderText>false<\/w:AlwaysShowPlaceholderText>\n<w:DoNotPromoteQF\/>\n<w:LidThemeOther>PT-BR<\/w:LidThemeOther>\n<w:LidThemeAsian>X-NONE<\/w:LidThemeAsian>\n<w:LidThemeComplexScript>X-NONE<\/w:LidThemeComplexScript>\n<w:Compatibility>\n<w:BreakWrappedTables\/>\n<w:SnapToGridInCell\/>\n<w:WrapTextWithPunct\/>\n<w:UseAsianBreakRules\/>\n<w:DontGrowAutofit\/>\n<w:SplitPgBreakAndParaMark\/>\n<w:DontVertAlignCellWithSp\/>\n<w:DontBreakConstrainedForcedTables\/>\n<w:DontVertAlignInTxbx\/>\n<w:Word11KerningPairs\/>\n<w:CachedColBalance\/>\n<\/w:Compatibility>\n<w:BrowserLevel>MicrosoftInternetExplorer4<\/w:BrowserLevel>\n<m:mathPr>\n<m:mathFont m:val=\"Cambria Math\"\/>\n<m:brkBin m:val=\"before\"\/>\n<m:brkBinSub m:val=\"&#45;-\"\/>\n<m:smallFrac m:val=\"off\"\/>\n<m:dispDef\/>\n<m:lMargin m:val=\"0\"\/>\n<m:rMargin m:val=\"0\"\/>\n<m:defJc m:val=\"centerGroup\"\/>\n<m:wrapIndent m:val=\"1440\"\/>\n<m:intLim m:val=\"subSup\"\/>\n<m:naryLim m:val=\"undOvr\"\/>\n<\/m:mathPr><\/w:WordDocument>\n<\/xml><![endif]--><\/p>\n<p><!--[if gte mso 9]><xml>\n<w:LatentStyles DefLockedState=\"false\" DefUnhideWhenUsed=\"true\"\nDefSemiHidden=\"true\" DefQFormat=\"false\" DefPriority=\"99\"\nLatentStyleCount=\"267\">\n<w:LsdException Locked=\"false\" Priority=\"0\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" QFormat=\"true\" Name=\"Normal\"\/>\n<w:LsdException Locked=\"false\" Priority=\"9\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" QFormat=\"true\" Name=\"heading 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"9\" QFormat=\"true\" Name=\"heading 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"9\" QFormat=\"true\" Name=\"heading 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"9\" QFormat=\"true\" Name=\"heading 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"9\" QFormat=\"true\" Name=\"heading 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"9\" QFormat=\"true\" Name=\"heading 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"9\" QFormat=\"true\" Name=\"heading 7\"\/>\n<w:LsdException Locked=\"false\" Priority=\"9\" QFormat=\"true\" Name=\"heading 8\"\/>\n<w:LsdException Locked=\"false\" Priority=\"9\" QFormat=\"true\" Name=\"heading 9\"\/>\n<w:LsdException Locked=\"false\" Priority=\"39\" Name=\"toc 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"39\" Name=\"toc 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"39\" Name=\"toc 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"39\" Name=\"toc 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"39\" Name=\"toc 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"39\" Name=\"toc 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"39\" Name=\"toc 7\"\/>\n<w:LsdException Locked=\"false\" Priority=\"39\" Name=\"toc 8\"\/>\n<w:LsdException Locked=\"false\" Priority=\"39\" Name=\"toc 9\"\/>\n<w:LsdException Locked=\"false\" Priority=\"35\" QFormat=\"true\" Name=\"caption\"\/>\n<w:LsdException Locked=\"false\" Priority=\"10\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" QFormat=\"true\" Name=\"Title\"\/>\n<w:LsdException Locked=\"false\" Priority=\"1\" Name=\"Default Paragraph Font\"\/>\n<w:LsdException Locked=\"false\" Priority=\"11\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" QFormat=\"true\" Name=\"Subtitle\"\/>\n<w:LsdException Locked=\"false\" Priority=\"22\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" QFormat=\"true\" Name=\"Strong\"\/>\n<w:LsdException Locked=\"false\" Priority=\"20\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" QFormat=\"true\" Name=\"Emphasis\"\/>\n<w:LsdException Locked=\"false\" Priority=\"59\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Table Grid\"\/>\n<w:LsdException Locked=\"false\" UnhideWhenUsed=\"false\" Name=\"Placeholder Text\"\/>\n<w:LsdException Locked=\"false\" Priority=\"1\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" QFormat=\"true\" Name=\"No Spacing\"\/>\n<w:LsdException Locked=\"false\" Priority=\"60\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light Shading\"\/>\n<w:LsdException Locked=\"false\" Priority=\"61\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light List\"\/>\n<w:LsdException Locked=\"false\" Priority=\"62\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light Grid\"\/>\n<w:LsdException Locked=\"false\" Priority=\"63\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Shading 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"64\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Shading 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"65\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium List 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"66\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium List 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"67\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"68\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"69\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"70\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Dark List\"\/>\n<w:LsdException Locked=\"false\" Priority=\"71\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful Shading\"\/>\n<w:LsdException Locked=\"false\" Priority=\"72\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful List\"\/>\n<w:LsdException Locked=\"false\" Priority=\"73\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful Grid\"\/>\n<w:LsdException Locked=\"false\" Priority=\"60\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light Shading Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"61\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light List Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"62\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light Grid Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"63\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Shading 1 Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"64\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Shading 2 Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"65\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium List 1 Accent 1\"\/>\n<w:LsdException Locked=\"false\" UnhideWhenUsed=\"false\" Name=\"Revision\"\/>\n<w:LsdException Locked=\"false\" Priority=\"34\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" QFormat=\"true\" Name=\"List Paragraph\"\/>\n<w:LsdException Locked=\"false\" Priority=\"29\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" QFormat=\"true\" Name=\"Quote\"\/>\n<w:LsdException Locked=\"false\" Priority=\"30\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" QFormat=\"true\" Name=\"Intense Quote\"\/>\n<w:LsdException Locked=\"false\" Priority=\"66\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium List 2 Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"67\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 1 Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"68\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 2 Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"69\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 3 Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"70\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Dark List Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"71\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful Shading Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"72\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful List Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"73\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful Grid Accent 1\"\/>\n<w:LsdException Locked=\"false\" Priority=\"60\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light Shading Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"61\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light List Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"62\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light Grid Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"63\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Shading 1 Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"64\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Shading 2 Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"65\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium List 1 Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"66\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium List 2 Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"67\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 1 Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"68\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 2 Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"69\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 3 Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"70\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Dark List Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"71\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful Shading Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"72\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful List Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"73\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful Grid Accent 2\"\/>\n<w:LsdException Locked=\"false\" Priority=\"60\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light Shading Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"61\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light List Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"62\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light Grid Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"63\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Shading 1 Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"64\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Shading 2 Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"65\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium List 1 Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"66\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium List 2 Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"67\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 1 Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"68\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 2 Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"69\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 3 Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"70\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Dark List Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"71\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful Shading Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"72\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful List Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"73\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful Grid Accent 3\"\/>\n<w:LsdException Locked=\"false\" Priority=\"60\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light Shading Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"61\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light List Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"62\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light Grid Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"63\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Shading 1 Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"64\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Shading 2 Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"65\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium List 1 Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"66\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium List 2 Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"67\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 1 Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"68\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 2 Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"69\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 3 Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"70\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Dark List Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"71\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful Shading Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"72\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful List Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"73\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful Grid Accent 4\"\/>\n<w:LsdException Locked=\"false\" Priority=\"60\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light Shading Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"61\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light List Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"62\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light Grid Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"63\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Shading 1 Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"64\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Shading 2 Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"65\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium List 1 Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"66\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium List 2 Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"67\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 1 Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"68\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 2 Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"69\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 3 Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"70\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Dark List Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"71\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful Shading Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"72\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful List Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"73\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful Grid Accent 5\"\/>\n<w:LsdException Locked=\"false\" Priority=\"60\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light Shading Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"61\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light List Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"62\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Light Grid Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"63\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Shading 1 Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"64\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Shading 2 Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"65\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium List 1 Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"66\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium List 2 Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"67\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 1 Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"68\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 2 Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"69\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Medium Grid 3 Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"70\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Dark List Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"71\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful Shading Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"72\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful List Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"73\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" Name=\"Colorful Grid Accent 6\"\/>\n<w:LsdException Locked=\"false\" Priority=\"19\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" QFormat=\"true\" Name=\"Subtle Emphasis\"\/>\n<w:LsdException Locked=\"false\" Priority=\"21\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" QFormat=\"true\" Name=\"Intense Emphasis\"\/>\n<w:LsdException Locked=\"false\" Priority=\"31\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" QFormat=\"true\" Name=\"Subtle Reference\"\/>\n<w:LsdException Locked=\"false\" Priority=\"32\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" QFormat=\"true\" Name=\"Intense Reference\"\/>\n<w:LsdException Locked=\"false\" Priority=\"33\" SemiHidden=\"false\"\nUnhideWhenUsed=\"false\" QFormat=\"true\" Name=\"Book Title\"\/>\n<w:LsdException Locked=\"false\" Priority=\"37\" Name=\"Bibliography\"\/>\n<w:LsdException Locked=\"false\" Priority=\"39\" QFormat=\"true\" Name=\"TOC Heading\"\/>\n<\/w:LatentStyles>\n<\/xml><![endif]--><!--[if gte mso 10]>\n\n\n\n<style>\n \/* Style Definitions *\/\n table.MsoNormalTable\n\t{mso-style-name:\"Tabela normal\";\n\tmso-tstyle-rowband-size:0;\n\tmso-tstyle-colband-size:0;\n\tmso-style-noshow:yes;\n\tmso-style-priority:99;\n\tmso-style-qformat:yes;\n\tmso-style-parent:\"\";\n\tmso-padding-alt:0cm 5.4pt 0cm 5.4pt;\n\tmso-para-margin:0cm;\n\tmso-para-margin-bottom:.0001pt;\n\tmso-pagination:widow-orphan;\n\tfont-size:11.0pt;\n\tfont-family:\"Calibri\",\"sans-serif\";\n\tmso-ascii-font-family:Calibri;\n\tmso-ascii-theme-font:minor-latin;\n\tmso-fareast-font-family:\"Times New Roman\";\n\tmso-fareast-theme-font:minor-fareast;\n\tmso-hansi-font-family:Calibri;\n\tmso-hansi-theme-font:minor-latin;\n\tmso-bidi-font-family:\"Times New Roman\";\n\tmso-bidi-theme-font:minor-bidi;}\n<\/style>\n\n<![endif]--><em><strong><span lang=\"FR\">Retraite forc\u00e9e<\/span><span lang=\"FR\"><br \/>\n<\/span><\/strong><span lang=\"FR\">Un jet anglais a \u00e9t\u00e9 retir\u00e9 de la circulation \u00e0 cause du bruit de ses moteurs<\/span><\/em><\/p>\n<p><span lang=\"FR\">Un des meilleurs avions britanniques, le BAC 1-11 (One Eleven), a \u00e9t\u00e9 retir\u00e9 de la circulation \u00e0 cause du bruit de ses moteurs. Cet avion, mis au point par Hunting Aircraft et fabriqu\u00e9 pour British Aircraft Corporation (BAC), a \u00e9t\u00e9 lanc\u00e9 au d\u00e9but des ann\u00e9es 60 et a vol\u00e9 environ 30 ans, jusqu\u2019\u00e0 sa retraite forc\u00e9e pour des raisons de restrictions sonores. D\u2019autres avions comme le Boeing 737-200, le Douglas DC-8 et le Tupolev Tu-154, auraient connu le m\u00eame sort sans l\u2019invention d\u2019un \u00e9quipement antibruit appel\u00e9 hush kit, cr\u00e9\u00e9 pour r\u00e9duire le bruit des anciens moteurs turbofan de type low-bypass. Les mod\u00e8les actuels (high-bypass) sont beaucoup plus silencieux. Le hush kit est un type d\u2019exhausteur plac\u00e9 \u00e0 la sortie de la turbine et qui sert \u00e0 \u00e9touffer le bruit des turbines des anciens avions. Cette technologie a \u00e9galement permis de r\u00e9duire les \u00e9missions de gaz polluants du moteur.<\/span><\/p>\n<p><span lang=\"FR\"><strong>LE PROJET<\/strong>\u00a0 Avion Silencieux: Une recherche a\u00e9roacoustique <strong>MODALIT\u00c9<\/strong> Recherche en Partenariat pour l\u2019Innovation Technologique (Pite) <strong>COORDONNATEUR<\/strong> JULIO ROMANO MENEGHINI \u2013 USP <strong>INVESTISSEMENT<\/strong> 707.506,58 r\u00e9aux et 1.709.305,41 dollars (FAPESP) 6.000.000,00 r\u00e9aux (Embraer)<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"Des avions plus silencieux","protected":false},"author":23,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[1194],"tags":[],"coauthors":[116],"class_list":["post-120159","post","type-post","status-publish","format-standard","hentry","category-technologie"],"acf":[],"_links":{"self":[{"href":"https:\/\/revistapesquisa.fapesp.br\/fr\/wp-json\/wp\/v2\/posts\/120159","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/revistapesquisa.fapesp.br\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistapesquisa.fapesp.br\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/fr\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/fr\/wp-json\/wp\/v2\/comments?post=120159"}],"version-history":[{"count":0,"href":"https:\/\/revistapesquisa.fapesp.br\/fr\/wp-json\/wp\/v2\/posts\/120159\/revisions"}],"wp:attachment":[{"href":"https:\/\/revistapesquisa.fapesp.br\/fr\/wp-json\/wp\/v2\/media?parent=120159"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/fr\/wp-json\/wp\/v2\/categories?post=120159"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/fr\/wp-json\/wp\/v2\/tags?post=120159"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/revistapesquisa.fapesp.br\/fr\/wp-json\/wp\/v2\/coauthors?post=120159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}